{"id":103214,"date":"2019-11-26T10:30:42","date_gmt":"2019-11-26T10:30:42","guid":{"rendered":"https:\/\/dievolkswirtschaft.ch\/2019\/11\/rinawi-08-09-2019fr\/"},"modified":"2023-08-23T22:55:43","modified_gmt":"2023-08-23T20:55:43","slug":"rinawi-08-09-2019","status":"publish","type":"post","link":"https:\/\/dievolkswirtschaft.ch\/de\/2019\/11\/rinawi-08-09-2019\/","title":{"rendered":"Leistungsbilanz\u00fcbersch\u00fcsse: Auch eine Folge der \u00dcberalterung"},"content":{"rendered":"<p>Die Welt befindet sich im demografischen Wandel. Viele L\u00e4nder erleben eine im historischen Vergleich einmalige Ver\u00e4nderung der Altersstruktur, obschon sich diese sehr langsam vollzieht. Dabei lassen sich sowohl globale als auch l\u00e4nderspezifische Entwicklungstrends beobachten. Der wichtigste globale Trend ist die gesellschaftliche Alterung. Weltweit steigt die Lebenserwartung an, w\u00e4hrend die Geburtenrate sinkt. Die Folge ist eine dramatisch ver\u00e4nderte Altersstruktur: Der Anteil junger Menschen nimmt stetig ab, der Anteil \u00e4lterer Menschen steigt rapide an.&#13;<br \/>\n&#13;<br \/>\nSo weit der globale Trend. Doch bei der konkreten Auspr\u00e4gung gibt es je nach Land Unterschiede. In vielen Industrienationen etwa ist die Lebenserwartung besonders hoch und die Geburtenrate tief. Dadurch ist die Alterung hier bereits sehr weit fortgeschritten. Die Bev\u00f6lkerungsstatistik der Vereinten Nationen zeigt, dass das Medianalter vieler wichtiger Industrienationen bereits bei etwa 45 Jahren liegt. In vielen Schwellenl\u00e4ndern hingegen ist der Alterungsprozess weniger dramatisch. Denn die Lebenserwartung liegt dort tiefer, und die Geburtenrate \u2013 wenn auch abnehmend \u2013 ist weiterhin auf hohem Niveau. Mit einigen Ausnahmen liegt das Medianalter dieser L\u00e4ndergruppe bei etwa 30 Jahren. Beispielsweise in Russland und China liegt es aber h\u00f6her. Die Unterschiede zwischen Industrie- und Schwellenl\u00e4ndern zeigen: Der Alterungsprozess betrifft zwar die gesamte Welt, verl\u00e4uft aber nicht im Gleichschritt.&#13;<\/p>\n<h2>Viele Sparer beg\u00fcnstigen \u00dcberschuss<\/h2>\n<p>&#13;<br \/>\nDer demografische Wandel hat enorme gesamtwirtschaftliche Auswirkungen. In der aktuellen Diskussion steht dabei meist der Arbeitsmarkt im Fokus, etwa bez\u00fcglich der Erh\u00f6hung des Rentenalters. Seltener wird analysiert, was dieser Wandel f\u00fcr die Entwicklung der Leistungsbilanzsalden bedeutet. Leistungsbilanzsalden zeigen die gesamtwirtschaftliche Differenz zwischen Ersparnis und Investitionen. Folglich kann der demografische Wandel auch \u00fcber diese zwei Kan\u00e4le auf die Leistungsbilanz wirken. Insbesondere das Sparverhalten ist dabei stark altersabh\u00e4ngig, aber auch zwischen Investitionsverhalten und der Altersstruktur eines Landes haben empirische Studien wiederholt einen signifikanten Zusammenhang festgestellt. Insgesamt kann allerdings festgehalten werden, dass der Einfluss der demografischen Struktur auf die Ersparnis \u00fcberwiegt. Der demografische Wandel wirkt deshalb vor allem \u00fcber den Kanal der Ersparnis auf die Leistungsbilanz.&#13;<br \/>\n&#13;<br \/>\nUm den Einfluss der Altersstruktur auf die gesamtwirtschaftliche Ersparnis zu analysieren, bildet das sogenannte Lebenszyklusmodell die theoretische Basis. Dieses Modell besagt, dass Individuen ihren Konsum \u00fcber ihr gesamtes Leben hinweg gl\u00e4tten \u2013 das heisst konstant halten \u2013 m\u00f6chten, obwohl ihr Einkommen teilweise erheblich schwankt. Um ein konstantes Konsumniveau zu halten, sparen oder entsparen sie w\u00e4hrend verschiedener Lebensphasen: In jungen Jahren ist das Einkommen tendenziell relativ gering, sodass Junge ihren Konsum durch Kreditaufnahme ausgleichen. Sp\u00e4ter, im mittleren Alter, erm\u00f6glichen Einkommenssteigerungen den Aufbau von Verm\u00f6gen, das schliesslich im Rentenalter wieder aufgebraucht wird.&#13;<br \/>\n&#13;<br \/>\nDie derzeitige Altersstruktur in vielen Industrienationen, mit einem grossen Anteil an Personen mittleren Alters, tr\u00e4gt somit zu einer hohen gesamtwirtschaftlichen Ersparnis bei. Verschiebt sich die Altersstruktur in Zukunft hin zu einem grossen Anteil an Rentnern, die ihr Verm\u00f6gen abbauen, m\u00fcsste dies folglich zu einem R\u00fcckgang der gesamtwirtschaftlichen Ersparnis f\u00fchren. In einer geschlossenen Volkswirtschaft w\u00fcrde dieser R\u00fcckgang der Ersparnisse mit abnehmenden Investitionen einhergehen. In einer offenen Volkswirtschaft entkoppelt sich der Zusammenhang zwischen Ersparnis und Investitionen. Sind inl\u00e4ndische Ersparnisse h\u00f6her als inl\u00e4ndische Investitionen, wird ein Teil der Ersparnisse im Ausland angelegt \u2013 daraus resultiert ein Leistungsbilanz\u00fcberschuss. Umgekehrt k\u00f6nnen inl\u00e4ndische Investitionen auch mit Ersparnissen aus dem Ausland finanziert werden, falls die inl\u00e4ndischen Ersparnisse zu gering sind. Dies \u00e4ussert sich sodann in einem Leistungsbilanzdefizit.&#13;<\/p>\n<h2>Industrienationen bauen Verm\u00f6gen auf<\/h2>\n<p>&#13;<br \/>\nEine Reihe von Studien hat den Zusammenhang zwischen Demografie und Leistungsbilanz empirisch untersucht. Die Mehrzahl dieser Studien nutzt als Indikator den Abh\u00e4ngigenquotienten. Dieser zeigt das Verh\u00e4ltnis der wirtschaftlich inaktiven Bev\u00f6lkerung (j\u00fcnger als 15 und \u00e4lter als 64 Jahre) zur aktiven Bev\u00f6lkerung (von 15 bis und mit 64 Jahren). Allerdings verdichtet dieser Indikator die Informationen sehr stark und ber\u00fccksichtigt den Zusammenhang zwischen der Altersstruktur und dem Spar- und Investitionsverhalten nur unzureichend. Dies vor allem deshalb, weil das Spar- und Investitionsverhalten \u00fcber den Lebenszyklus stark schwankt.&#13;<br \/>\n&#13;<br \/>\nUm den Zusammenhang zwischen Demografie und Leistungsbilanz besser abzubilden, ist eine detaillierte Messung der demografischen Struktur notwendig. Eine M\u00f6glichkeit ist es, die Altersstruktur einer Bev\u00f6lkerung in Form eines Polynoms verschiedener Altersgruppen darzustellen.<a href=\"#footnote_1\" id=\"footnote-anchor_1\" class=\"inline-footnote__anchor\">[1]<\/a> Das Polynom erlaubt es, den demografischen Einfluss auf die Leistungsbilanz entlang der gesamten Altersverteilung zu sch\u00e4tzen. Konkret wird ein Regressionsmodell gesch\u00e4tzt, bei dem der Saldo der Leistungsbilanz auf eine Reihe von erkl\u00e4renden Variablen regressiert wird, die neben verschiedenen Einflussfaktoren auch das Polynom der Altersstruktur enthalten.&#13;<br \/>\n&#13;<br \/>\nDie Ergebnisse einer solchen Sch\u00e4tzung f\u00fcr 49 L\u00e4nder \u00fcber die Jahre von 1970 bis 2016 deuten darauf hin, dass die demografische Struktur eines Landes ein wichtiger Einflussfaktor der Leistungsbilanz ist. Konkret zeigt sich, dass ein relativ gr\u00f6sserer Anteil an der Bev\u00f6lkerung von Personen im Alter von 45 bis und mit 64 Jahren zu einem Leistungsbilanz\u00fcberschuss beitr\u00e4gt. (siehe <em>Abbildung 1<\/em>). L\u00e4nder mit einer Bev\u00f6lkerungsstruktur, die von vergleichsweise vielen Personen in dieser mittleren Altersstufe und wenigen jungen und alten Personen gekennzeichnet ist, weisen also eher einen Leistungsbilanz\u00fcberschuss auf. Bei der Interpretation der Koeffizienten ist zu beachten, dass es sich um den partiellen Einfluss der einzelnen Kohorten auf die Leistungsbilanz handelt. Um den gesamten Einfluss einer Altersstruktur auf die Leistungsbilanz zu erhalten, muss man die gewichtete Summe der Koeffizienten betrachten. Als Gewicht wird dabei der Anteil einer Alterskohorte an der Gesamtbev\u00f6lkerung verwendet.&#13;<br \/>\n&#13;<br \/>\nDie Sch\u00e4tzung zeigt also auf, wie sich die gegenw\u00e4rtige demografische Struktur auf die Leistungsbilanz auswirkt. Fazit: Die gegenw\u00e4rtige Altersstruktur in vielen Industrienationen, wo das Medianalter bei etwa 45 Jahren liegt, tr\u00e4gt zu Leistungsbilanz\u00fcbersch\u00fcssen bei. Mit anderen Worten: Ein Grossteil der Bev\u00f6lkerung in Industrienationen befindet sich zurzeit in der Phase der Verm\u00f6gensbildung.&#13;<\/p>\n<h3 class=\"text__graphic-title\">Abb. 1: Gesch\u00e4tzter Einfluss einzelner Altersgruppen auf die Leistungsbilanz<\/h3>\n<p>&#13;<br \/>\n<div class='chart chart--normal' id='Rinawi_1_de'>\n\n<\/div>\n\n<script>\n$(function () {\n    $('#Rinawi_1_de').highcharts({\n    chart: {\n    },\n    title: {\n        text: ''\n    },\n    \n    xAxis: [{\n        categories: ['0-4', '5-9', '10-14', '15-19', '20-24', '25-29', '30-34', '35-39', '40-44', '45-49', '50-54', '55-59', '60-64', '65-69', '70-74', '75-79', '80+'],\n       title: {\n            text: 'Altersgruppen der Bev\u00f6lkerung'\n        },\n    }],\n    yAxis: { \/\/ Primary yAxis\n        labels: {\n            format: '{value}'\n         \n        },       \n          \n        title: {\n            text: 'Koeffizienten der Altersgruppen'\n        },\n\n    plotLines: [{\n                color: '#23318a',\n                dashStyle: 'spline', \/\/ Spline = Linie, Dot = gepunktete Linie\n                width: 1,\n                value: 0, \/\/ Wert, wo vertikale Linie eingeblendet werden soll\n                label: {\n                    rotation: 0,\n                    y: 15,\n                    style: {\n                        fontStyle: 'italic'\n                    },\n                    text: ' '\n                },\n                zIndex: 3\n            }]\n\n\n        \n    },    \n        plotOptions: {\n            line: {\n                marker: {\n                    enabled: false\n               }\n            }\n        },\n    series: [ {\n        name: 'Einfluss auf Leistungsbilanz',\n        type: 'line',\n        color: '#88c0d3',\n        data: [0.421984166,0.159437239,-0.008407648,-0.096619725,-0.120268203,-0.094422288,-0.034151204,0.045475841,0.129389629,0.202520937,0.249800578,0.256159306,0.206527919,0.085837208,-0.120982051,-0.428999066,-0.853283048],\n        tooltip: {\n            valueSuffix: ''\n        },\n    },{\n        name: 'Ober- und Untergrenze 90%-Konfidenzintervall',\n        type: 'line',\n        color: '#0074be',\n        data: [0.816357672,0.383751988,0.140467137,0.04455981,0.023397246,0.040889427,0.089063309,0.169210672,0.272646695,0.372103035,0.436287433,0.438489854,0.362034231,0.230061471,0.12334922,0.032989912,-0.075158373,],\n        tooltip: {\n            valueSuffix: ''\n        },\n  dashStyle: 'shortdot',\n\n    },\n    {\n        name: '90% Konfidenzbereich',\n        type: 'line',\n                color: '#0074be',\n        data: [0.02761063,-0.06487751,-0.157282442,-0.237799257,-0.263933659,-0.229734004,-0.15736571,-0.078258999,-0.013867446,0.032938831,0.063313715,0.073828764,0.051021609,-0.05838706,-0.365313321,-0.890988052,-1.631407738],\n        tooltip: {\n            valueSuffix: ''\n        },\n                showInLegend:false,\n  dashStyle: 'shortdot'\n\n    },     ]\n});\n});\n\n\n\n<\/script>\n&#13;<br \/>\n&#13;<br \/>\n<span class=\"text__legend\">Anmerkung: Die Grafik zeigt die durchschnittlichen Effekte einzelner Altersgruppen auf die Leistungsbilanz (gemessen am Bruttoinlandprodukt) f\u00fcr eine Stichprobe von 49 L\u00e4ndern \u00fcber die Jahre 1970 bis 2016.\u00a0Ein Koeffizient von 0,26 f\u00fcr die Kohorte der 55- bis 59-J\u00e4hrigen ist wie folgt zu interpretieren: W\u00e4chst diese Alterskohorte gemessen an der Gesamtbev\u00f6lkerung um 1 Prozentpunkt, so steigt die Leistungsbilanz (gemessen am BIP) um 0,26 Prozentpunkte. <\/span><span class=\"text__quelle--ground\">&#13;<br \/>\n<\/span>&#13;<br \/>\n&#13;<br \/>\n<span class=\"text__quelle--ground\">Quelle: Gerigk, Rinawi und Wicht (2018) \/ Die Volkswirtschaft<\/span>&#13;<\/p>\n<h2>Aus \u00dcbersch\u00fcssen werden Defizite<\/h2>\n<p>&#13;<br \/>\nEine alternde Bev\u00f6lkerung d\u00fcrfte auch die zuk\u00fcnftige Entwicklung der Leistungsbilanz beeinflussen. Theoretisch bedeutet dies f\u00fcr die meisten Industrienationen, dass sich k\u00fcnftig ein grosser Anteil der Bev\u00f6lkerung in der Phase des Entsparens befinden wird. Denn aus den Sparern von heute werden die Entsparer von morgen. Anders ist es in vielen Schwellenl\u00e4ndern: In Zukunft werden dort demografiebedingt verh\u00e4ltnism\u00e4ssig mehr Individuen sparen.&#13;<br \/>\n&#13;<br \/>\nDas Altern der Bev\u00f6lkerung hat Konsequenzen, wie empirische Projektionen zum k\u00fcnftigen Zusammenhang zwischen Demografie und Leistungsbilanz zeigen: So wird die Demografie in den Industrienationen mit einer verh\u00e4ltnism\u00e4ssig alten Bev\u00f6lkerung nur noch bis etwa Mitte der 2030er-Jahre positive Effekte auf die Leistungsbilanz haben. Im Durchschnitt der f\u00fcnf L\u00e4nder mit der \u00e4ltesten Bev\u00f6lkerung im Datensatz tr\u00e4gt die demografische Struktur aktuell mit etwa 1,6 Prozentpunkten zum Leistungsbilanz\u00fcberschuss (im Verh\u00e4ltnis zum Bruttoinlandprodukt) bei. Konkret: Die Schweiz hatte 2018 einen \u00dcberschuss von etwa 70 Milliarden Franken, was etwa 10 Prozent des BIP entspricht. Nimmt man die 1,6 Prozentpunkte als Vergleichswert, kann also gut ein Sechstel des \u00dcberschusses mit der demografischen Struktur erkl\u00e4rt werden.&#13;<br \/>\n&#13;<br \/>\nWenn Mitte der 2030er-Jahre der Anteil der \u00c4lteren stark ansteigt, wird auch der Anteil der Bev\u00f6lkerung, der die Ersparnisse aufbraucht, zunehmen. Das f\u00fchrt tendenziell zu einer Verringerung des Leistungsbilanzsaldos. Unter der Bedingung, dass alle anderen Einflussfaktoren gleich bleiben, muss man f\u00fcr die kommenden Jahrzehnte also mit einem deutlichen R\u00fcckgang der Ersparnisse rechnen.&#13;<br \/>\n&#13;<br \/>\nUmgekehrt ist es in den Schwellenl\u00e4ndern mit einer relativ jungen Bev\u00f6lkerung. Dort ist der Effekt der Demografie auf die Leistungsbilanz gegenw\u00e4rtig negativ und tr\u00e4gt im Durchschnitt der f\u00fcnf L\u00e4nder mit der j\u00fcngsten Bev\u00f6lkerung mit etwa 0,7 Prozentpunkten zum Leistungsbilanzdefizit (gemessen am Bruttoinlandprodukt) bei. F\u00fcr diese Schwellenl\u00e4nder heisst das: Momentan muss zur Finanzierung von Investitionen Kapital aus dem Ausland aufgenommen werden. Dieser negative Effekt wird sich zunehmend verkleinern und ab Mitte der 2020er-Jahre sogar umkehren (siehe <em>Abbildung 2<\/em>).&#13;<\/p>\n<h3 class=\"text__graphic-title\">Abb. 2: Bisheriger und zuk\u00fcnftiger Einfluss der Demografie auf die Leistungsbilanz nach L\u00e4ndern mit junger und alter Bev\u00f6lkerung (1970\u20132060)<\/h3>\n<p>&#13;<br \/>\n<div class='chart chart--normal' id='Rinawi_2_de'>\n\n<\/div>\n\n<script>\n$(function () {\n    $('#Rinawi_2_de').highcharts({\n        chart: {\n        zoomType: 'xy'\n    },\n    title: {\n        text: ''\n    },\n    \n    xAxis: [{\n        categories: ['1970', '1971', '1972', '1973', '1974', '1975', '1976', '1977', '1978', '1979', '1980', '1981', '1982', '1983', '1984', '1985', '1986', '1987', '1988', '1989', '1990', '1991', '1992', '1993', '1994', '1995', '1996', '1997', '1998', '1999', '2000', '2001', '2002', '2003', '2004', '2005', '2006', '2007', '2008', '2009', '2010', '2011', '2012', '2013', '2014', '2015', '2016', '2017', '2018', '2019', '2020', '2021', '2022', '2023', '2024', '2025', '2026', '2027', '2028', '2029', '2030', '2031', '2032', '2033', '2034', '2035', '2036', '2037', '2038', '2039', '2040', '2041', '2042', '2043', '2044', '2045', '2046', '2047', '2048', '2049', '2050', '2051', '2052', '2053', '2054', '2055', '2056', '2057', '2058', '2059', '2060'],\n       title: {\n            text: ''\n        },\n          plotBands: [{ \/\/ Farbhinterlegung Mittelwert\n                color: 'rgba(137,193,211,0.3)',\n                                showInLegend: true,\n\n                from: 46.9,\n                to: 91,\n label: {\n                text: 'zuk\u00fcnftiger Einfluss <br\/>gem\u00e4ss Bev\u00f6lkerungsprognosen der UNO',\n                align: 'left',\n                x:+10,\n               \n            }\n\n\n            }],\n    }],\n    yAxis: [{ \/\/ Primary yAxis\n        labels: {\n            format: '{value}'\n         \n        },\n        \n          \n        title: {\n            text: 'Beitrag der Demografie zur Leistungsbilanz in % des BIP'\n        },\n\n\n    plotLines: [{\n                color: '#23318a',\n                dashStyle: 'spline', \/\/ Spline = Linie, Dot = gepunktete Linie\n                width: 1,\n                value: 0, \/\/ Wert, wo vertikale Linie eingeblendet werden soll\n                label: {\n                    rotation: 0,\n                    y: 15,\n                    style: {\n                        fontStyle: 'italic'\n                    },\n                    text: ' '\n                },\n                zIndex: 3\n            }]\n\n\n        \n    }, ],\n   \n        plotOptions: {\n            line: {\n                marker: {\n                    enabled: false\n                }\n            }\n        },\n       \n    series: [ {\n        name: 'L\u00e4nder mit alter Bev\u00f6lkerung (Deutschland, Italien, Japan, Schweiz, Spanien)',\n        type: 'line',\n        color: '#a5c4d2',\n        data: [0.016731244,\t0.012508864,\t0.017984334,\t0.034260936,\t0.063236937,\t0.105618685,\t0.114713132,\t0.137863278,\t0.175394446,\t0.225800633,\t0.287102133,\t0.314328611,\t0.354196757,\t0.407016069,\t0.473458856,\t0.552816153,\t0.592410326,\t0.646433651,\t0.713027239,\t0.790006638,\t0.875456989,\t0.921094656,\t0.97692585,\t1.04188168,\t1.115981579,\t1.198482871,\t1.259216547,\t1.327686191,\t1.399931312,\t1.47112751,\t1.537921786,\t1.560996532,\t1.588623643,\t1.620685101,\t1.657168865,\t1.696808934,\t1.702993155,\t1.713859677,\t1.727879167,\t1.743939877,\t1.760228872,\t1.747156978,\t1.739505768,\t1.732606888,\t1.722728491,\t1.708333373,\t1.6818223,\t1.654194117,\t1.626023889,\t1.597791553,\t1.567339182,\t1.516520619,\t1.469410896,\t1.421298742,\t1.367176414,\t1.303746104,\t1.222237706,\t1.139249921,\t1.053153992,\t0.963414729,\t0.868404627,\t0.761972666,\t0.65813309,\t0.55265373,\t0.440883189,\t0.319037557,\t0.189057097,\t0.059552941,\t-0.073183663,\t-0.211920798,\t-0.358685046,\t-0.507124066,\t-0.652141869,\t-0.79471004,\t-0.936574578,\t-1.08137238,\t-1.213552952,\t-1.33571279,\t-1.453085065,\t-1.568971157,\t-1.68530035,\t-1.778011322,\t-1.859393835,\t-1.933454752,\t-2.003832817,\t-2.074351072,\t-2.121251106,\t-2.155380964,\t-2.181874752,\t-2.207273722,\t-2.238717794,],\n        tooltip: {\n            valueSuffix: ''\n        },\n    },{\n        name: 'L\u00e4nder mit junger Bev\u00f6lkerung (Indien, Indonesien, Mexiko, S\u00fcdafrika, T\u00fcrkei)',\n        type: 'line',\n        color: '#c74d70',\n        data: [-3.760622263,\t-3.788421392,\t-3.808859825,\t-3.821530581,\t-3.825232506,\t-3.819347382,\t-3.840326786,\t-3.849357367,\t-3.848055363,\t-3.838337898,\t-3.820613623,\t-3.812238455,\t-3.795378447,\t-3.768805027,\t-3.730724096,\t-3.680778265,\t-3.651411772,\t-3.609831095,\t-3.557084322,\t-3.494688034,\t-3.423219204,\t-3.359871626,\t-3.286973238,\t-3.204456091,\t-3.112162828,\t-3.010676861,\t-2.929723263,\t-2.841202974,\t-2.745444059,\t-2.642925501,\t-2.534355879,\t-2.449900866,\t-2.359240055,\t-2.26366663,\t-2.164378166,\t-2.061774015,\t-1.970554352,\t-1.87410295,\t-1.772775412,\t-1.666975021,\t-1.557316184,\t-1.453577161,\t-1.347039104,\t-1.237147212,\t-1.122982383,\t-1.004490137,\t-0.907179654,\t-0.802878618,\t-0.693445623,\t-0.581534028,\t-0.468651652,\t-0.374965012,\t-0.280673146,\t-0.185474202,\t-0.088584311,\t0.009692492,\t0.083967589,\t0.160990551,\t0.239806741,\t0.318790495,\t0.396791607,\t0.451576978,\t0.507907391,\t0.565556705,\t0.624411821,\t0.683969736,\t0.721608877,\t0.761984825,\t0.804408312,\t0.847947896,\t0.89155221,\t0.911753476,\t0.934503496,\t0.958936393,\t0.984258056,\t1.009574175,\t1.010085225,\t1.013878226,\t1.020151138,\t1.027723312,\t1.035164595,\t1.017767429,\t1.004282832,\t0.993865371,\t0.985828698,\t0.979137003,\t0.949853837,\t0.926237702,\t0.90681535,\t0.889978409,\t0.874063134],\n        tooltip: {\n            valueSuffix: ''\n        },\n\n    },\n   \n    \n\n    ]\n});\n});\n\n\n\n<\/script>\n&#13;<br \/>\n&#13;<br \/>\n<span class=\"text__legend\">Lesebeispiel: Die Abbildung zeigt, dass die demografische Struktur in den L\u00e4ndern mit einer alten Bev\u00f6lkerung im Jahr 2020 durchschnittlich noch mit knapp 1,6 Prozentpunkten zum Leistungsbilanz\u00fcberschuss (gemessen am BIP) beitragen wird. Im Jahr 2060 hingegen wird die Altersstruktur in diesen L\u00e4ndern 2,2 Prozentpunkte des Leistungsbilanzdefizits erkl\u00e4ren k\u00f6nnen.<\/span>&#13;<br \/>\n&#13;<br \/>\n<span class=\"text__quelle--ground\">Quelle: Gerigk, Rinawi und Wicht (2018) \/ Die Volkswirtschaft<\/span>&#13;<\/p>\n<h2>\u00dcbersch\u00fcsse in naher Zukunft ben\u00f6tigt<\/h2>\n<p>&#13;<br \/>\nDie Alterung der Bev\u00f6lkerung gestaltet sich insbesondere f\u00fcr viele Industrienationen als eine grosse Herausforderung. So wird sie etwa zu einem R\u00fcckgang der Anzahl Erwerbspersonen f\u00fchren, was die Sozialsysteme stark belasten und das Wirtschaftswachstum verlangsamen k\u00f6nnte. Diesem R\u00fcckgang k\u00f6nnte tempor\u00e4r entgegengewirkt werden, indem die Erwerbst\u00e4tigkeit von Frauen erh\u00f6ht wird. Auch die Einwanderung von Arbeitskr\u00e4ften k\u00f6nnte eine Entlastung bewirken. Die zugewanderte Bev\u00f6lkerung altert allerdings auch, sodass der potenzielle Verj\u00fcngungseffekt nur vor\u00fcbergehend ist. Eine l\u00e4ngerfristige L\u00f6sung w\u00e4re die Erh\u00f6hung des Renteneintrittsalters, was jedoch politisch auf starken Widerstand st\u00f6sst.&#13;<br \/>\n&#13;<br \/>\nEs k\u00f6nnen aber auch freie Kapitalstr\u00f6me helfen, den demografischen \u00dcbergang zu bew\u00e4ltigen. Denn obwohl die gesamte Welt altert, sind die Alterungsprozesse stark asynchron, also zeitlich verschoben. Deswegen k\u00f6nnen heute junge, wachsende Volkswirtschaften durch Leistungsbilanzdefizite ihr Wachstum finanzieren. Gleichzeitig k\u00f6nnen heute alte, eher stagnierende Volkswirtschaften durch Leistungsbilanz\u00fcbersch\u00fcsse Ersparnisse aufbauen, die sie in naher Zukunft ben\u00f6tigen werden. Somit zeigt sich in der Analyse zum Zusammenhang zwischen Demografie und Leistungsbilanz, dass ein bedeutender Anteil der globalen Leistungsbilanzungleichgewichte demografiebedingt ist.<\/p>\n<ol class=\"footnote\"><li id=\"footnote_1\" class=\"footnote--item\">Siehe Fair und Dominguez (1991).&nbsp;<a href=\"#footnote-anchor_1\" class=\"inline-footnote__anchor hidden-print\">[<span class=\"icon-arrow-up\"><\/span>]<\/a><\/li><\/ol>","protected":false},"excerpt":{"rendered":"<p>Die Welt befindet sich im demografischen Wandel. Viele L\u00e4nder erleben eine im historischen Vergleich einmalige Ver\u00e4nderung der Altersstruktur, obschon sich diese sehr langsam vollzieht. Dabei lassen sich sowohl globale als auch l\u00e4nderspezifische Entwicklungstrends beobachten. Der wichtigste globale Trend ist die gesellschaftliche Alterung. Weltweit steigt die Lebenserwartung an, w\u00e4hrend die Geburtenrate sinkt. Die Folge ist eine [&hellip;]<\/p>","protected":false},"author":4891,"featured_media":18272,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"ep_exclude_from_search":false,"footnotes":""},"post__type":[69,66],"post_opinion":[],"post_serie":[],"post_content_category":[97],"post_content_subject":[],"acf":{"seco_author":4891,"seco_co_author":null,"author_override":"","seco_author_post_ocupation_year":"","seco_author_post_occupation_de":"Dr. oec., Internationale wirtschaftspolitische Analysen, Schweizerische Nationalbank (SNB), Z\u00fcrich","seco_author_post_occupation_fr":"Analyses de politique \u00e9conomique internationale, Banque nationale suisse (BNS), Zurich","seco_co_authors_post_ocupation":null,"short_title":"Leistungsbilanz\u00fcbersch\u00fcsse wegen \u00dcberalterung","post_lead":"L\u00e4nder mit hohen Leistungsbilanz\u00fcbersch\u00fcssen stehen bisweilen in der Kritik. Dass die \u00dcbersch\u00fcsse auch mit der \u00dcberalterung dieser L\u00e4nder zusammenh\u00e4ngen, wird hingegen kaum thematisiert.","post_hero_image_description":"Die junge Bev\u00f6lkerung Mexikos produziert heute noch ein Handelsbilanzdefizit, doch das k\u00f6nnte sich bald \u00e4ndern. Kunstwerk an der amerikanisch-mexikanischen Grenze.","post_hero_image_description_copyright_de":"Keystone","post_hero_image_description_copyright_fr":"Keystone","post_references_literature":"<ul>&#13;\n \t<li>Fair, R. C. und Dominguez, K. M. (1991). Effects of the Changing U.S. Age Distribution on Macroeconomic Equations. In: \u00a0American Economic Review, 81, 1276-1294.<\/li>&#13;\n \t<li>Gerigk, J., Rinawi, M. und Wicht, A. (2018). <a href=\"https:\/\/ideas.repec.org\/a\/usg\/auswrt\/2018690145-76.html\">Demographics and the Current Account.<\/a> In: Aussenwirtschaft, 69 (1), 45\u201376.<\/li>&#13;\n<\/ul>","post_kasten":null,"post_notes_for_print":"","first_teaser_header_de":"","first_teaser_header_fr":"","first_teaser_text_de":"","first_teaser_text_fr":"","second_teaser_header_de":"","second_teaser_header_fr":"","second_teaser_text_de":"","second_teaser_text_fr":"","kseason_de":"","kseason_fr":"","post_in_pdf":103217,"main_focus":[156058,156847],"serie_email":null,"frontpage_slider_bild":103221,"artikel_bild-slider":null,"legacy_id":"87536","post_abstract":"Mit Beginn der Finanzkrise sind Leistungsbilanzungleichgewichte wieder in das politische Blickfeld ger\u00fcckt, und auch weiterhin werden sie kontrovers diskutiert. Dabei wird L\u00e4ndern mit einem Leistungsbilanz\u00fcberschuss h\u00e4ufig vorgeworfen, dass sie diesen auf Kosten der Defizitl\u00e4nder erwirtschaften. Auch wird gefordert, dass sie mehr konsumieren und weniger exportieren, damit sich die Ungleichgewichte verringern. In dieser Diskussion sollte ber\u00fccksichtigt werden, dass die demografische Struktur eines Landes einen grossen Einfluss auf die Leistungsbilanz hat. Der demografische Wandel wird langfristig dazu beitragen, dass viele heutige \u00dcberschussl\u00e4nder in der Zukunft demografiebedingt Defizite erwirtschaften werden.","magazine_issue":"20191201","seco_author_reccomended_post":null,"redaktoren":[3988,0],"korrektor":4139,"planned_publication_date":"20191126","original_files":null,"external_release_for_author":"20190831","external_release_for_author_time":"00:00:00","link_for_external_authors":"https:\/\/dievolkswirtschaft.ch\/exedit\/5cee274f34fe7"},"_links":{"self":[{"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/posts\/103214"}],"collection":[{"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/users\/4891"}],"replies":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/comments?post=103214"}],"version-history":[{"count":1,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/posts\/103214\/revisions"}],"predecessor-version":[{"id":125886,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/posts\/103214\/revisions\/125886"}],"acf:user":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/users\/4139"},{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/users\/0"},{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/users\/3988"},{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/users\/4891"}],"acf:post":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/main_focus_post\/156847"},{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/main_focus_post\/156058"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/media\/18272"}],"wp:attachment":[{"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/media?parent=103214"}],"wp:term":[{"taxonomy":"post__type","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/post__type?post=103214"},{"taxonomy":"post_opinion","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/post_opinion?post=103214"},{"taxonomy":"post_serie","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/post_serie?post=103214"},{"taxonomy":"post_content_category","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/post_content_category?post=103214"},{"taxonomy":"post_content_subject","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/post_content_subject?post=103214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}