{"id":104472,"date":"2019-05-22T11:00:49","date_gmt":"2019-05-22T11:00:49","guid":{"rendered":"https:\/\/dievolkswirtschaft.ch\/2019\/05\/bonvin-06-2019fr\/"},"modified":"2025-06-16T13:11:41","modified_gmt":"2025-06-16T11:11:41","slug":"bonvin-06-2019","status":"publish","type":"post","link":"https:\/\/dievolkswirtschaft.ch\/de\/2019\/05\/bonvin-06-2019\/","title":{"rendered":"Wasser: Grundlage f\u00fcr nachhaltige Entwicklung und Frieden"},"content":{"rendered":"<p>Stellen Sie sich folgendes Szenario im Jahr 2051 vor: Schnee ist Mangelware, und Niederschl\u00e4ge werden immer unregelm\u00e4ssiger. Sie sitzen im Gemeinderat einer Schweizer Berggemeinde und m\u00fcssen \u00fcber folgende Frage entscheiden: Wie soll das Wasser im Stausee auf dem Gemeindegebiet verwendet werden, um den gr\u00f6sstm\u00f6glichen Nutzen daraus zu ziehen? Wem soll es zugutekommen?<\/p>\n<ol>\n<li style=\"list-style-type: none;\">\n<ol>\n<li>Neuen Hotels, die Arbeitspl\u00e4tze schaffen;<\/li>\n<\/ol>\n<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<ol>\n<li style=\"list-style-type: none;\">\n<ol>\n<li>der Erzeugung von erneuerbarer Elektrizit\u00e4t im Winter;<\/li>\n<\/ol>\n<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<ol>\n<li style=\"list-style-type: none;\">\n<ol>\n<li>der Bew\u00e4sserung der Weinberge und dem Tr\u00e4nken des Viehs im Sommer;<\/li>\n<\/ol>\n<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<ol>\n<li style=\"list-style-type: none;\">\n<ol>\n<li>einer Wasserreserve zur Brandbek\u00e4mpfung.<\/li>\n<\/ol>\n<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<ol>\n<li style=\"list-style-type: none;\">\n<ol>\n<li>Der Stausee soll die beiden flussabw\u00e4rts liegenden St\u00e4dte vor \u00dcberschwemmungen sch\u00fctzen.<\/li>\n<\/ol>\n<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<ol>\n<li style=\"list-style-type: none;\">\n<ol>\n<li>Die nat\u00fcrliche Sch\u00f6nheit des Flusses unterhalb der Staumauer f\u00fcr Touristen steht im Vordergrund.<\/li>\n<\/ol>\n<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p>Das Szenario stammt aus der Ausstellung \u00abWasser unser\u00bb, welche vor zwei Jahren im Alpinen Museum der Schweiz in Bern zu sehen war. Es veranschaulicht Interessenkonflikte um die Ressource Wasser und zeigt, dass es notwendig ist, eine gemeinsame Vision f\u00fcr eine nachhaltige wirtschaftliche Entwicklung zu finden, gegens\u00e4tzliche Positionen anzugleichen und Kompromisse auszuhandeln. Die Herausforderungen enden nicht an der Gemeindegrenze, sondern umfassen das Einzugsgebiet eines Wasserlaufs und betreffen alle Anrainer. Zusammenarbeit wird folglich zu einem Schl\u00fcsselwort, um Kosten und Nutzen zu teilen.<\/p>\n<h2><strong>Fl\u00fcsse enden nicht an der Landesgrenze<\/strong><\/h2>\n<p>In der Schweiz und in Europa besteht bereits ein rechtlicher Rahmen, um ausgewogene L\u00f6sungen auszuhandeln \u2013 dazu geh\u00f6ren beispielsweise die \u00dcbereinkommen zum Schutz des Rheins und der Donau. Doch f\u00fcr die Mehrheit der 3 Milliarden Menschen, die weltweit von grenz\u00fcberschreitenden S\u00fcsswasserressourcen abh\u00e4ngen, sind solche Vereinbarungen alles andere als selbstverst\u00e4ndlich. Weltweit teilen sich 153 Staaten 60\u00a0Prozent der Fl\u00fcsse, Seen und Grundwasserleiter, die nicht nur zur Erzeugung von Trinkwasser, Energie, Lebensmitteln und Industrieg\u00fctern dienen, sondern auch f\u00fcr das \u00d6kosystem unabdingbar sind und in einigen F\u00e4llen als lebenswichtige kommerzielle Wasserstrassen genutzt werden.<\/p>\n<p>Eine grenz\u00fcberschreitende integrierte Wasserbewirtschaftung in den Einzugsgebieten ist der Schl\u00fcssel zum Erfolg, um Wohlstand und Stabilit\u00e4t zu gew\u00e4hrleisten. Dieses Ziel ist in der Agenda 2030 der Vereinten Nationen f\u00fcr eine nachhaltige Entwicklung festgehalten: Gem\u00e4ss Punkt 6.5 soll auf allen Ebenen eine integrierte Bewirtschaftung der Wasserressourcen umgesetzt werden \u2013 gegebenenfalls auch mittels grenz\u00fcberschreitender Zusammenarbeit. Allerdings sind bisher nur begrenzte Fortschritte erzielt worden, wie ein Bericht aus dem Jahr 2018 zeigt.<a href=\"#footnote_1\" id=\"footnote-anchor_1\" class=\"inline-footnote__anchor\">[1]<\/a> Hinzu kommt: Der Wettbewerb um die Wasserressourcen wird sich in den n\u00e4chsten 15 bis 30 Jahren verst\u00e4rken.<\/p>\n<p>Ein mangelnder Fortschritt bei der grenz\u00fcberschreitenden Zusammenarbeit wirkt sich auf andere, ebenfalls wichtige Ziele f\u00fcr nachhaltige Entwicklung (<span lang=\"en-Latn\">Sustainable Development Goals<\/span>) negativ aus. Dazu z\u00e4hlen die Erh\u00f6hung des Anteils der erneuerbaren Energie am globalen Energiemix, die St\u00e4rkung der Widerstandskraft und der Anpassungsf\u00e4higkeit gegen\u00fcber Naturkatastrophen, die Entwicklung der nachhaltigen Landwirtschaft sowie der Zugang zu Trinkwasser.<a href=\"#footnote_2\" id=\"footnote-anchor_2\" class=\"inline-footnote__anchor\">[2]<\/a> Im Rahmen der internationalen Zusammenarbeit setzt sich die Schweiz daf\u00fcr ein, dass die grenz\u00fcberschreitenden Herausforderungen bei der Wasserbewirtschaftung angegangen werden.<\/p>\n<h2><strong>Aralsee ausgetrocknet<\/strong><\/h2>\n<p>Um den Ansatz der Schweiz zu veranschaulichen, ist Zentralasien ein gutes Beispiel: In Kirgisistan, Tadschikistan und Usbekistan steht Wasser seit \u00fcber 25 Jahren im Zentrum der Schweizer Entwicklungszusammenarbeit des Staatssekretariats f\u00fcr Wirtschaft (Seco), der Direktion f\u00fcr Entwicklung und Zusammenarbeit (Deza) und der Humanit\u00e4ren Hilfe. Diese semiaride Region ist auf Wasserressourcen, die aus zwei grossen Flussl\u00e4ufen stammen, angewiesen (siehe <em>Abbildung<\/em>). Der 2580 Kilometer lange Fluss Amudarja fliesst durch Afghanistan, Tadschikistan, Kirgisistan, Usbekistan und Turkmenistan. Der Fluss Syrdarja weist eine L\u00e4nge von 2200 Kilometern auf und durchquert Kirgisistan, Usbekistan und Kasachstan. Beide Fl\u00fcsse m\u00fcnden in den Aralsee. Die \u00dcbernutzung von Wasser f\u00fcr landwirtschaftliche Zwecke hat zur Austrocknung dieses Binnengew\u00e4ssers zwischen Usbekistan und Kasachstan gef\u00fchrt.<\/p>\n<h3 class=\"text__graphic-title\">Wassereinzugsgebiet um den Aralsee<\/h3>\n<p><a href=\"https:\/\/dievolkswirtschaft.ch\/content\/uploads\/2019\/05\/BONVIN_ABB_DE.png\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-87242\" src=\"https:\/\/dievolkswirtschaft.ch\/content\/uploads\/2019\/05\/BONVIN_ABB_DE.png\" alt=\"\" width=\"2552\" height=\"1486\" \/><\/a><\/p>\n<p><span class=\"text__legend\">Anmerkung: Die Fl\u00fcsse sind schematisch dargestellt. Die Liniendicke entspricht nicht der Durchflussmenge. In der N\u00e4he des Aralsees enthalten die Fl\u00fcsse kein Wasser mehr.<\/span><\/p>\n<p>F\u00fcr die wirtschaftliche Entwicklung und die Stabilit\u00e4t der zentralasiatischen Staaten ist der Zugang zu Wasser angesichts des Bev\u00f6lkerungsdrucks und des Klimawandels heute mehr denn je entscheidend. Eine \u00f6konomische Studie hat aufgezeigt, dass fehlende Massnahmen und eine mangelnde Zusammenarbeit zwischen den Anrainerstaaten in der Region direkt oder indirekt Kosten von mindestens 4,5\u00a0Milliarden Dollar pro Jahr verursachen.<a href=\"#footnote_3\" id=\"footnote-anchor_3\" class=\"inline-footnote__anchor\">[3]<\/a><\/p>\n<h2><strong>\u00abBlue Peace\u00bb-Initiative<\/strong><\/h2>\n<p>Im Hinblick auf eine nachhaltige wirtschaftliche Entwicklung hat sich die Schweizer Entwicklungszusammenarbeit daher auf regionale Massnahmen ausgerichtet, um die Anrainerstaaten in den Einzugsgebieten bei ihrer gemeinsamen Wasserbewirtschaftung zu unterst\u00fctzen. Die Initiative Blue Peace Central Asia (BPCA) b\u00fcndelt diese Anstrengungen. Einerseits st\u00e4rkt sie die Diplomatie, indem sie auf die traditionellen Vermittlungskompetenzen baut. Andererseits stellt sie Fachwissen zur Verf\u00fcgung, das in der Schweiz bei der grenz\u00fcberschreitenden Wasserbewirtschaftung und beim gemeinsamen Betrieb von Anlagen an Wasserl\u00e4ufen vorhanden ist. Wichtig sind auch Erfahrungen aus bestehenden Projekten in Zentralasien.<\/p>\n<p>Das gemeinsame Verst\u00e4ndnis, auf welches BPCA in Zentralasien hinarbeitet, l\u00e4sst sich zusammenfassen mit dem Leitsatz: Wasser ist ein wesentlicher Faktor f\u00fcr eine nachhaltige wirtschaftliche Entwicklung der Region. Dazu sollen aber nicht einfach die Kosten, welche durch die Unt\u00e4tigkeit verursacht werden, aufgelistet werden, sondern es gilt Massnahmen zu ergreifen, die allen zugutekommen. BPCA umfasst drei Komponenten:<\/p>\n<ol>\n<li style=\"list-style-type: none;\">\n<ol>\n<li>Eine diplomatische und politische Komponente: Die Anrainerstaaten werden unterst\u00fctzt, um im Dialog L\u00f6sungen f\u00fcr eine integrierte Bewirtschaftung der Einzugsgebiete grosser Wasserl\u00e4ufe zu suchen.<\/li>\n<\/ol>\n<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<ol>\n<li style=\"list-style-type: none;\">\n<ol>\n<li>Eine operative Komponente: Es gilt, verl\u00e4ssliche Daten zur verf\u00fcgbaren Wasserqualit\u00e4t und -quantit\u00e4t zu erheben. Die Fakten bilden die Vertrauensbasis zwischen den Anrainern. Dar\u00fcber hinaus unterst\u00fctzt BPCA den Aufbau von Infrastrukturen mit einem grenz\u00fcberschreitenden Mehrwert.<\/li>\n<\/ol>\n<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<ol>\n<li style=\"list-style-type: none;\">\n<ol>\n<li>Eine Jugendkomponente: Junge Menschen werden f\u00fcr die verschiedenen \u00f6kologischen und sozio\u00f6konomischen Herausforderungen sensibilisiert, die im Zusammenhang mit der Wasserbewirtschaftung entlang von Wasserl\u00e4ufen zu bew\u00e4ltigen sind.<\/li>\n<\/ol>\n<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p>BPCA bietet einen politischen Rahmen f\u00fcr alle regionalen Massnahmen im Bereich Wasser, welche die Schweizer Entwicklungszusammenarbeit in Zentralasien realisiert. Die Initiative st\u00fctzt sich \u2013 insbesondere bei der operativen Komponente \u2013 auf bestehende bilaterale Programme in Kirgisistan, Tadschikistan und Usbekistan. Beispielsweise unterst\u00fctzt das Seco zusammen mit der Europ\u00e4ischen Union (EU) das von der Weltbank realisierte Entwicklungsprogramm f\u00fcr Energie und Wasser in Zentralasien (CAEWDEP) (siehe <em>Kasten<\/em>). Die Deza wiederum finanziert Programme, die dem Ausbau der nationalen Bewirtschaftung von Wasserressourcen (NWRM) dienen.<\/p>\n<p>Im Bereich der Infrastrukturinvestitionen sind die politischen Strategien der multilateralen Institutionen eng mit den Handlungskonzepten ihrer Partnerstaaten verkn\u00fcpft. Derzeit besteht allerdings kaum ein Interesse, ein komplexes Projekt mit grenz\u00fcberschreitenden Auswirkungen zu integrieren. M\u00f6glicherweise sind hier Unterst\u00fctzungsbeitr\u00e4ge als Finanzierungsquelle n\u00fctzlich, um den ersten Schritt zu tun und die Zur\u00fcckhaltung bei den Investitionen in der Region abzubauen. Die Unterst\u00fctzungsbeitr\u00e4ge bieten wahrscheinlich eine Nische f\u00fcr bilaterale Akteure.<\/p>\n<p>Die Absicht, die Widerstandskraft der zentralasiatischen L\u00e4nder zu st\u00e4rken und in dieser Region eine nachhaltige wirtschaftliche Entwicklung zu gew\u00e4hrleisten, ist zwar edel, und diesbez\u00fcglich bestehen ehrgeizige Ziele. Doch gleichzeitig m\u00fcssen die Akteure bescheiden bleiben. Denn die Fortschritte h\u00e4ngen im Wesentlichen vom Vertrauen zwischen den Anrainerstaaten ab, das sich nicht einfach verordnen l\u00e4sst. Massgebend sind auch \u00e4ussere Einfl\u00fcsse auf diese Region an der Schnittstelle zwischen Orient und Okzident, ein wesentliches Glied der alten und der neuen Seidenstrasse. Die Rolle der Schweiz in dieser Region wird daher sicherlich weit \u00fcber die physischen Grenzen Zentralasiens hinaus wahrgenommen.<\/p>\n<ol class=\"footnote\"><li id=\"footnote_1\" class=\"footnote--item\">UNO (2018): <a href=\"http:\/\/www.unwater.org\/publications\/executive-summary-sdg-6-synthesis-report-2018-on-water-and-sanitation\/\">Sustainable Development Goal\u00a06 \u2013\u00a0Synthesis Report on Water and Sanitation 2018<\/a>, Kapitel II\/E (S. 75\u201386), New York.&nbsp;<a href=\"#footnote-anchor_1\" class=\"inline-footnote__anchor hidden-print\">[<span class=\"icon-arrow-up\"><\/span>]<\/a><\/li><li id=\"footnote_2\" class=\"footnote--item\"><a href=\"https:\/\/www.eda.admin.ch\/agenda2030\/de\/home\/agenda-2030\/die-17-ziele-fuer-eine-nachhaltige-entwicklung.html\">SDG<\/a> 7.2, 13.1, 2.4 und 6.1.&nbsp;<a href=\"#footnote-anchor_2\" class=\"inline-footnote__anchor hidden-print\">[<span class=\"icon-arrow-up\"><\/span>]<\/a><\/li><li id=\"footnote_3\" class=\"footnote--item\">Adelphi und Carec (2017): <a href=\"https:\/\/www.adelphi.de\/en\/project\/rethinking-water-central-asia-costs-inaction-and-benefits-water-cooperation\">Rethinking Water in Central Asia \u2013\u00a0the Costs of Inaction and Benefits of Water Cooperation<\/a>, Almaty.&nbsp;<a href=\"#footnote-anchor_3\" class=\"inline-footnote__anchor hidden-print\">[<span class=\"icon-arrow-up\"><\/span>]<\/a><\/li><\/ol>","protected":false},"excerpt":{"rendered":"<p>Stellen Sie sich folgendes Szenario im Jahr 2051 vor: Schnee ist Mangelware, und Niederschl\u00e4ge werden immer unregelm\u00e4ssiger. Sie sitzen im Gemeinderat einer Schweizer Berggemeinde und m\u00fcssen \u00fcber folgende Frage entscheiden: Wie soll das Wasser im Stausee auf dem Gemeindegebiet verwendet werden, um den gr\u00f6sstm\u00f6glichen Nutzen daraus zu ziehen? Wem soll es zugutekommen? Neuen Hotels, die [&hellip;]<\/p>","protected":false},"author":3468,"featured_media":211257,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"ep_exclude_from_search":false,"footnotes":""},"post__type":[69,66],"post_opinion":[],"post_serie":[],"post_content_category":[97],"post_content_subject":[230],"acf":{"seco_author":3468,"seco_co_author":"","author_override":"","seco_author_post_ocupation_year":"","seco_author_post_occupation_de":"Sonderbeauftragter f\u00fcr Wasser in Zentralasien, Abteilung Globalprogramm Wasser und Eurasien, Direktion f\u00fcr Entwicklung und Zusammenarbeit (Deza), Eidgen\u00f6ssisches Departement f\u00fcr ausw\u00e4rtige Angelegenheiten (EDA), Bern","seco_author_post_occupation_fr":"Envoy\u00e9 sp\u00e9cial pour l\u2019eau en Asie centrale, divisions Programme global Eau et Eurasie, Direction du d\u00e9veloppement et de la coop\u00e9ration (DDC), D\u00e9partement f\u00e9d\u00e9ral des affaires \u00e9trang\u00e8res (DFAE), Berne","seco_co_authors_post_ocupation":null,"short_title":"Wasser als Grundlage f\u00fcr nachhaltige Entwicklung","post_lead":"Um bei grenz\u00fcberschreitenden Gew\u00e4ssern die Wasserversorgung sicherzustellen, ist die Zusammenarbeit der Anrainerstaaten wichtig. In Zentralasien setzt sich die Schweiz f\u00fcr ausgewogene L\u00f6sungen mit maximalem Nutzen ein.&#13;","post_hero_image_description":"Wirtschaftspolitik ist die Gesamtheit der Massnahmen, mit denen der Staat auf die Wirtschaft einwirkt.","post_hero_image_description_copyright_de":"KI-generiert \/ Die Volkswirtschaft","post_hero_image_description_copyright_fr":"Alamy","post_references_literature":"","post_kasten":[{"kasten_title":"Das Central Asia Energy and Water Development Program","kasten_box":"Die Wasser- und Energiesysteme Zentralasiens sind untrennbar miteinander verbunden, jedoch unzureichend koordiniert. Vor diesem Hintergrund st\u00e4rkt ein Entwicklungsprogramm der Weltbank, das <em>Central Asia Energy and Water Development Program (CAEWDP)<\/em>, die Rahmenbedingungen in Afghanistan, Kasachstan, Kirgisistan, Tadschikistan, Turkmenistan und Usbekistan. Das vom Staatssekretariat f\u00fcr Wirtschaft (Seco) unterst\u00fctzte Programm hilft den Regierungen, wirksame Institutionen aufzubauen. Beispielsweise vermittelt das CAEWDP Fachwissen, erstellt Machbarkeitsanalysen und pr\u00fcft geplante Projekte auf ihre Umwelt- und Sozialvertr\u00e4glichkeit. Weiter f\u00f6rdert es anhand von Plattformen den regionalen, auf Fakten basierenden Dialog. \u00dcber Ideenwettbewerbe belebt es den Austausch zwischen jungen Wasserexperten. Die Aktivit\u00e4ten des CAEWDP sind mit dem Programm Blue Peace Central Asia sowie mit anderen Entwicklungspartnern koordiniert."}],"post_notes_for_print":"Die Bew\u00e4sserung von Feldern stromaufw\u00e4rts f\u00fchrte zum Austrocknen des Aralsees. Ehemaliger Hafen in Mo'ynoq, Usbekistan.","first_teaser_header_de":"","first_teaser_header_fr":"","first_teaser_text_de":"","first_teaser_text_fr":"","second_teaser_header_de":"","second_teaser_header_fr":"","second_teaser_text_de":"","second_teaser_text_fr":"","kseason_de":"","kseason_fr":"","post_in_pdf":104475,"main_focus":[156114,156887],"serie_email":"","frontpage_slider_bild":211257,"artikel_bild-slider":null,"legacy_id":"86306","post_abstract":"F\u00fcr eine nachhaltige wirtschaftliche Entwicklung und die Stabilit\u00e4t der L\u00e4nder ist der Zugang zu Wasser angesichts des Bev\u00f6lkerungsdrucks und des Klimawandels von entscheidender Bedeutung. Das \u00abblaue Gold\u00bb vereint die Anrainerstaaten von Wasserl\u00e4ufen. In einem solchen Umfeld ist eine grenz\u00fcberschreitende integrierte Wasserbewirtschaftung in den Einzugsgebieten unerl\u00e4sslich. Die Schweiz engagiert sich daher in der internationalen Zusammenarbeit f\u00fcr den Zugang zu Wasser, insbesondere in Zentralasien, wo sich sechs L\u00e4nder zwei Wasserl\u00e4ufe teilen. Im Hinblick auf eine nachhaltige wirtschaftliche Entwicklung hat sich die Schweizer Entwicklungszusammenarbeit auf regionale Massnahmen ausgerichtet, um die betroffenen L\u00e4nder bei ihrer gemeinsamen Wasserbewirtschaftung zu unterst\u00fctzen. Daraus ist die Initiative \u00abBlue Peace Central Asia\u00bb entstanden, die sowohl diplomatischen als auch operativen Zwecken dient. Die Fortschritte h\u00e4ngen jedoch vom Vertrauen zwischen den Anrainern und von \u00e4usseren Einfl\u00fcssen ab.","magazine_issue":"20190601","seco_author_reccomended_post":"","redaktoren":"","korrektor":"","planned_publication_date":"2019-05-22 09:00:49","original_files":null,"external_release_for_author":"20190505","external_release_for_author_time":"23:30:00","link_for_external_authors":"https:\/\/dievolkswirtschaft.ch\/exedit\/5cac4cbe2d8f4"},"_links":{"self":[{"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/posts\/104472"}],"collection":[{"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/users\/3468"}],"replies":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/comments?post=104472"}],"version-history":[{"count":3,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/posts\/104472\/revisions"}],"predecessor-version":[{"id":211456,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/posts\/104472\/revisions\/211456"}],"acf:post":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/main_focus_post\/156887"},{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/main_focus_post\/156114"}],"acf:user":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/users\/3468"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/media\/211257"}],"wp:attachment":[{"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/media?parent=104472"}],"wp:term":[{"taxonomy":"post__type","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/post__type?post=104472"},{"taxonomy":"post_opinion","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/post_opinion?post=104472"},{"taxonomy":"post_serie","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/post_serie?post=104472"},{"taxonomy":"post_content_category","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/post_content_category?post=104472"},{"taxonomy":"post_content_subject","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/post_content_subject?post=104472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}