{"id":107168,"date":"2018-04-24T10:20:59","date_gmt":"2018-04-24T10:20:59","guid":{"rendered":"https:\/\/dievolkswirtschaft.ch\/2018\/04\/le-marche-numerique-intensifie-la-concurrence-des-contenusa\/"},"modified":"2023-08-23T23:03:10","modified_gmt":"2023-08-23T21:03:10","slug":"voigt-05-2018","status":"publish","type":"post","link":"https:\/\/dievolkswirtschaft.ch\/de\/2018\/04\/voigt-05-2018\/","title":{"rendered":"Ein digitaler Marktplatz f\u00fcr mehr inhaltlichen Wettbewerb"},"content":{"rendered":"<p>Die Geschichte wiederholt sich. Die breite Verf\u00fcgbarkeit des Wissens nach der Erfindung des Buchdrucks beendete die d\u00fcstere Epoche des Glaubens und l\u00e4utete die Neuzeit, die Aufkl\u00e4rung und den auf Angebot und Nachfrage fussenden Kapitalismus ein. Es gibt Gr\u00fcnde zur Annahme, dass die zweite Informationsrevolution, die wir derzeit durch die Digitalisierung erleben, \u00e4hnlich epochale Auswirkungen zeitigen wird.&#13;<br \/>\n&#13;<br \/>\nWie sehr scheinbar ewige Regeln bereits ausser Kraft sind, merken wir alle in unserem Alltag. Die Zeiten, in denen Wissen Macht bedeutete und ein Informationsvorsprung ein klarer Gesch\u00e4ftsvorteil war, gehen dem Ende zu. Eine Preissuchmaschine findet heute f\u00fcr alle das gleiche billigste Angebot, und f\u00fcr die Mehrheit der Bev\u00f6lkerung gilt inzwischen der scherzhafte Sch\u00fclerspruch: \u00abWissen ist das Gleiche wie Googeln, einfach in krass!\u00bb&#13;<br \/>\n&#13;<br \/>\nVor Gutenberg kostete ein Buch so viel wie ein grosses Stadthaus. Heute kostet eine Zeitung so viel wie ein Kaffee, und selbst das ist den meisten Leuten zu teuer. \u00abInformationen sind heute eine Ware, die man nicht mehr besitzen kann, weil sie sich sofort verfl\u00fcchtigen\u00bb, bringt es der amerikanische Journalist Jeff Jarvis auf den Punkt.&#13;<\/p>\n<h2>Eigene Relevanz-Definitionen<\/h2>\n<p>&#13;<br \/>\nWenn ich etwas wissen will, finde ich heute die Information. Oder noch besser: Die Information findet mich und mein Interesse gleich selbst. Aber welche Inhalte lasse ich zu mir kommen? Welche sind glaubw\u00fcrdig? Was ist wichtig?&#13;<br \/>\n&#13;<br \/>\nDas ist das Dilemma, in dem unsere Mediengesellschaft aktuell steckt. Der regelrechte Inhaltsbeschuss sorgt f\u00fcr Un\u00fcbersichtlichkeit und f\u00fchrt zum Autorit\u00e4tsverlust. Klassischen Medienmarken wird zunehmend der direkte kommunikative Nahkampf in den sozialen Medien entgegengesetzt.&#13;<br \/>\n&#13;<br \/>\nNiemand liest das Internet von vorne bis hinten durch. Angesichts der Informationsschwemme hat jeder damit angefangen, die Relevanz der Inhalte selber zu definieren. Dabei entscheiden etwa der Wohnort oder die eigenen Interessen dar\u00fcber, ob eine Information individuell relevant ist oder nicht. Es gibt aber auch eine Datenrelevanz: Sind die Informationen vom Urheber, oder ist es lediglich die dritte Zusammenfassung oder \u00dcbersetzung? Zudem ist entscheidend, ob eine Information glaubw\u00fcrdig ist. Hier spielen etwa die Marke und die Transparenz eines Medienprodukts eine Rolle. Und schliesslich sind die Themen, \u00fcber welche die eigenen Freunde diskutieren, f\u00fcr viele wichtiger als der n\u00e4chste Hurrikan in Florida, \u00fcber den der \u00abTagesschau\u00bb-Sprecher gerade berichtet.&#13;<br \/>\n&#13;<br \/>\nDie f\u00fcr mich relevanten Inhalte kommen via Linkempfehlungen von Freunden zu mir, aber auch durch Algorithmen und zunehmend smarter werdende Helferlein wie Alexa von Amazon und Google Home. Diese digitalen Assistenten m\u00fcssen einem nicht sympathisch sein, aber sie machen deutlich, wie absurd uns der Gedanke, f\u00fcr Informationen zu bezahlen, bald vorkommen wird.&#13;<br \/>\n&#13;<br \/>\n\u00abAlexa, wenn du mir noch einmal einen langweiligen Artikel empfiehlst, f\u00fcr den ich extra zahlen soll, werfe ich dich aus dem Fenster\u00bb \u2013 diesen Satz k\u00f6nnten wir uns vermutlich bald selber sagen h\u00f6ren. Informationen gibt es in H\u00fclle und F\u00fclle. Das kostbare Gut ist meine Aufmerksamkeit. Die Informationen werden zunehmend auf mein Profil geschneidert. Das macht sie f\u00fcr mich relevanter und \u00e4usserst wertvoll, wenn ich diese Daten verkn\u00fcpfen kann. Das zeigt sich nicht nur in den Medien, sondern auch in anderen Bereichen: Amazon, der Betreiber von Alexa, ist gerade daran, in den Versicherungsmarkt einzusteigen. Denn Alexa weiss genau, wie oft ich wirklich jogge und wie oft nicht.&#13;<\/p>\n<h2>Facebook als Informationsplattform ungeeignet<\/h2>\n<p>&#13;<br \/>\nDiese allumfassende Datenverkn\u00fcpfung birgt enormen Konfliktstoff. Der Widerstand der Politik regt sich entsprechend in verschiedenen L\u00e4ndern. Versuche, wie etwa das Netzwerkdurchsetzungsgesetz<a href=\"#footnote_1\" id=\"footnote-anchor_1\" class=\"inline-footnote__anchor\">[1]<\/a> in Deutschland, sind plump und wenig tauglich. Es zeigt aber, dass erkannt worden ist, dass sich Facebook und Co. auf keine Art und Weise als neutrale Informationsinfrastruktur eignen. Endlich.&#13;<br \/>\n&#13;<br \/>\nFacebook ordnet die Landesbewohner nach den Zielgruppenbed\u00fcrfnissen ihrer Werbekunden. Aus gesellschaftlicher Sicht sind die Folgen umfassend: Facebook behandelt die Vielschichtigkeit der Gesellschaft etwa so wie der K\u00fcnstler Ursus Wehrli die zu ordnenden Objekte in seinem Buch \u00abKunst aufr\u00e4umen\u00bb. Wehrlis Resultate sind h\u00f6chst absurd und am\u00fcsant. Ob auch die nach Zielgruppen aufger\u00e4umte Gesellschaft lustig wird, wird sich zeigen. Wir erleben es derzeit in dem grossen Social-Media-Experiment, an dem wir teilnehmen. Der Ausgang ist ungewiss.&#13;<br \/>\n&#13;<br \/>\nDie Plattformen sind als Infrastruktur inzwischen so wichtig, dass der deutsche \u00d6konom Nick Srnicek in seinem Buch \u00abPlatform Capitalism\u00bb bereits anregt, \u00fcber Verstaatlichung nachzudenken. Nur ist das angesichts der globalen Verbreitung nicht mehr so einfach wie damals, als private Eisenbahnen oder Elektrizit\u00e4tswerke so essenziell f\u00fcr eine Gesellschaft wurden, dass sie von den Nationalstaaten in den Besitz der Allgemeinheit \u00fcbergef\u00fchrt wurden. Aber immerhin: Bez\u00fcglich der derzeit alles beherrschenden Plattformen mit ihrer The-Winner-Takes-It-All-\u00d6konomie gibt es \u00f6konomische Hoffnung. Und diese Hoffnung ist dezentral.&#13;<\/p>\n<h2>Dezentrales Mediensystem<\/h2>\n<p>&#13;<br \/>\nBlockchain und neue dezentrale Verteilsysteme wie etwa Ethereum werden vor der Medienwirtschaft nicht mehr lange haltmachen. Diese neuen Technologien werden eine dezentral geregelte Teilhabe an der Wertsch\u00f6pfung und wesentlich feiner austarierte Erwerbsmodelle zulassen. Was das heisst, sieht man zurzeit etwa an dem Medien-Start-up Refind, das der Basler Unternehmer Dominik Grollimund hochzieht.&#13;<br \/>\n&#13;<br \/>\nAuf der Medienplattform Refind wird letztlich auch der Nutzer f\u00fcr seine Zeit belohnt. Die Inhalte aus aller Welt gibt es gratis, aber wer Freunde einl\u00e4dt oder Artikel teilt, bekommt 20 bis 30 virtuelle Coins. Diese haben bisher allerdings noch nichts mit einer Kryptow\u00e4hrung zu tun. Es handelt sich lediglich um sogenannte Tokens, von denen es gleich eine Milliarde gibt. Das Beispiel von Refind zeigt, wie ein dezentrales, viel ausdifferenzierteres Wertsch\u00f6pfungssystem funktionieren k\u00f6nnte: Wer einen Artikel geschrieben hat, bekommt Geld. Aber nicht nur er, sondern auch die Kuratoren, die den Inhalt geteilt und so vertrieben haben.&#13;<br \/>\n&#13;<br \/>\nWir haben l\u00e4ngst gelernt: \u00abZentral\u00bb hat keine Chance gegen \u00abdezentral\u00bb. Das war schon beim Grossen Brockhaus gegen Wikipedia so, und auch die jetzt scheinbar allm\u00e4chtigen Plattformen haben auf lange Sicht den dezentralen Wirtschaftsmechanismen wenig entgegenzusetzen. Artikel und Interesse finden dank k\u00fcnstlicher Intelligenz und lernenden Systemen immer \u00f6fter auch ohne Zwischenh\u00e4ndler zueinander. Facebooks Firmenpolitik, die keine Links nach aussen zul\u00e4sst, wird bald so innovativ wirken wie die Paywalls der Verlagsh\u00e4user. Aber wer soll die Inhalte erstellen, wenn sich Journalismus nicht mehr lohnt?&#13;<\/p>\n<h2>Wettbewerb der Inhalte neu organisieren<\/h2>\n<p>&#13;<br \/>\nAn das klassische Zeitungsgesch\u00e4ft mit den Informationen glaubt niemand mehr wirklich. Aber den Journalismus brauchen wir trotzdem. Derzeit sehen wir, wie sich die Informationserstellung in einen Spendenmarkt verwandelt. Milliard\u00e4r Christoph Blocher stattet die \u00abWeltwoche\u00bb und die \u00abBasler Zeitung\u00bb mit Geld aus, und die Verleger des neuen Schweizer Onlinemagazins \u00abRepublik\u00bb stehen im Kollektiv f\u00fcr ihre Einzelspende Schlange. Das Motiv ist letztlich in beiden F\u00e4llen das Gleiche: die \u00dcberzeugung und die Identifikation mit dem Produkt.&#13;<br \/>\n&#13;<br \/>\nAber nur auf Spenden baut man keine vern\u00fcnftige Medienlandschaft. Um zu verstehen, wie Journalismus in der Schweiz unabh\u00e4ngig und im Wettbewerb betrieben werden kann, lohnt sich ein Vergleich mit der Transportbranche. Kein Schweizer Transportunternehmer w\u00fcrde Geld verdienen, wenn nur eine einzige private Autobahn zur Verf\u00fcgung st\u00fcnde und deren Besitzer \u2013 \u00e4hnlich wie Facebook heute \u2013 laufend und ohne Ank\u00fcndigung Preise, Spurbreite und Verkehrsregeln \u00e4nderte.&#13;<br \/>\n&#13;<br \/>\nF\u00fcr die Kernaufgabe, den Transport, brauchte es eine gemeinsame Infrastruktur und ein paar Regeln, an die man sich h\u00e4lt. Trotz dieser gemeinsamen Basis w\u00fcrde niemand behaupten, im Transportgewerbe herrsche kein oder zu wenig Wettbewerb. Allerdings w\u00fcrde es auch keinem Lastwagenfahrer in den Sinn kommen, selber eine Strasse zu bauen, damit er die anderen beherrschen kann. Die Kosten f\u00fcr die gemeinsame Infrastruktur tragen alle gemeinsam. Daf\u00fcr k\u00f6nnen sie dem Kern ihres Unternehmens nachgehen: dem Erbringen von Transportleistungen zum Nutzen aller, unabh\u00e4ngig und in scharfem Wettbewerb untereinander.&#13;<br \/>\n&#13;<br \/>\nDer Journalismus nach dem Ende der Verleger-\u00c4ra steht aktuell genau vor diesem Schritt. Es braucht eines oder besser mehrere technische und inhaltliche Infrastruktur-Angebote. Nur so k\u00f6nnen neue, unabh\u00e4ngige Medienmarken und eine vielf\u00e4ltige Medienlandschaft entstehen. Auf einer solchen digitalen Allmende werden die allgemeinen Kosten jedes Einzelnen drastisch gesenkt. Dadurch st\u00fcnden \u2013 etwa f\u00fcr den Vertrieb bzw. den Weg der Inhalte zum Interesse \u2013 endlich ad\u00e4quate Mittel zur Verf\u00fcgung. Aber auch bereits erstellte und finanzierte SRG-Inhalte sollten, ebenso wie das Grundrauschen einer vermutlich bald \u00f6ffentlich subventionierten Nachrichtenagentur, allen zur Verf\u00fcgung stehen.&#13;<br \/>\n&#13;<br \/>\nAuf dieser kosteng\u00fcnstigen Basis wird es beispielsweise wieder m\u00f6glich sein, lokale oder regionale Medienmarken aufzubauen. Auch die im neuen Mediengesetz sich abzeichnende direkte Medienf\u00f6rderung f\u00fcr Onlinejournalismus wird wesentlich effizienter. Denn dadurch fliesst das Geld direkt in den Inhalt und das Markenprofil und nicht mehr in den Aufbau eines Kanals.&#13;<br \/>\n&#13;<br \/>\nDie Forderung nach einer gemeinsamen Infrastruktur ist bereits in den Vorschlag der Eidgen\u00f6ssischen Medienkommission geflossen. Die Verleger und ihre Lobbyisten wollen alles M\u00f6gliche, aber sicher keine zus\u00e4tzlichen Wettbewerber. Aber dem logischen Gedanken einer gemeinsamen Infrastruktur haben sie so wenig entgegenzusetzen wie Facebook und andere Plattformen der dezentralen Blockchain-\u00d6konomie.<\/p>\n<ol class=\"footnote\"><li id=\"footnote_1\" class=\"footnote--item\">Gem\u00e4ss dem Netzwerkdurchsetzungsgesetz m\u00fcssen rechtswidrige Inhalte von den Betreibern sozialer Netzwerke innerhalb von 24 Stunden gel\u00f6scht werden.&nbsp;<a href=\"#footnote-anchor_1\" class=\"inline-footnote__anchor hidden-print\">[<span class=\"icon-arrow-up\"><\/span>]<\/a><\/li><\/ol>","protected":false},"excerpt":{"rendered":"<p>Die Geschichte wiederholt sich. Die breite Verf\u00fcgbarkeit des Wissens nach der Erfindung des Buchdrucks beendete die d\u00fcstere Epoche des Glaubens und l\u00e4utete die Neuzeit, die Aufkl\u00e4rung und den auf Angebot und Nachfrage fussenden Kapitalismus ein. Es gibt Gr\u00fcnde zur Annahme, dass die zweite Informationsrevolution, die wir derzeit durch die Digitalisierung erleben, \u00e4hnlich epochale Auswirkungen zeitigen [&hellip;]<\/p>","protected":false},"author":4656,"featured_media":22868,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"ep_exclude_from_search":false,"footnotes":""},"post__type":[66],"post_opinion":[],"post_serie":[],"post_content_category":[154],"post_content_subject":[],"acf":{"seco_author":4656,"seco_co_author":null,"author_override":"","seco_author_post_ocupation_year":"","seco_author_post_occupation_de":"Gr\u00fcnder der Open-Source-Plattform Wepublish, Partner beim Beratungsunternehmen DasNetz.ch und ehemaliger Chefredaktor des Newsportals Watson, Z\u00fcrich","seco_author_post_occupation_fr":"Fondateur de la plateforme source ouverte \u00ab Wepublish \u00bb, partenaire de la soci\u00e9t\u00e9 de conseil DasNetz.ch et ancien r\u00e9dacteur en chef du site d\u2019information \u00ab Watson \u00bb, Zurich","seco_co_authors_post_ocupation":null,"short_title":"Mediale Infrastruktur soll Vielfalt f\u00f6rdern","post_lead":"Das Internet lehrt uns: \u00abDezentral\u00bb schl\u00e4gt \u00abzentral\u00bb. Das war bei Wikipedia gegen den Grossen Brockhaus so, das wird auch beim Rest der Welt gegen Facebook so sein. Gerade in dem Moment, als die alten Medienh\u00e4user die Plattform\u00f6konomie begriffen haben, l\u00e4uten die Blockchain-Leute ihr letztes St\u00fcndlein ein. Zum Gl\u00fcck!","post_hero_image_description":"Die anf\u00e4ngliche Euphorie ist verflogen. Ist Facebook als Informationsinfrastruktur nicht geeignet?","post_hero_image_description_copyright_de":"Keystone","post_hero_image_description_copyright_fr":"","post_references_literature":"","post_kasten":null,"post_notes_for_print":"","first_teaser_header_de":"","first_teaser_header_fr":"","first_teaser_text_de":"","first_teaser_text_fr":"","second_teaser_header_de":"","second_teaser_header_fr":"","second_teaser_text_de":"","second_teaser_text_fr":"","kseason_de":"","kseason_fr":"","post_in_pdf":107171,"main_focus":[156261,156992],"serie_email":null,"frontpage_slider_bild":107175,"artikel_bild-slider":null,"legacy_id":"76953","post_abstract":"Mit der Digitalisierung werden Informationen immer einfacher zug\u00e4nglich und immer billiger. Journalismus ist zunehmend kein Gesch\u00e4ft mehr, und die alte Medienordnung l\u00f6st sich vor unseren Augen auf. Statt sich auf untaugliche Plattformen wie Facebook zu verlassen, sollte die Medienwirtschaft der Zukunft in vielen Bereichen auf Kooperation und auf die dezentrale Funktionsweise der Blockchain-\u00d6konomie setzen. Die Medienf\u00f6rderung k\u00f6nnte hier sehr wirksame Hebel ansetzen und einen unabh\u00e4ngigen Wettbewerb der journalistischen Inhalte um unsere Aufmerksamkeit stimulieren. Doch die Verleger str\u00e4uben sich dagegen.","magazine_issue":"20180501","seco_author_reccomended_post":null,"redaktoren":[3988,0],"korrektor":4139,"planned_publication_date":"20180425","original_files":null,"external_release_for_author":"20180329","external_release_for_author_time":"00:00:00","link_for_external_authors":"https:\/\/dievolkswirtschaft.ch\/exedit\/5a9505754601c"},"_links":{"self":[{"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/posts\/107168"}],"collection":[{"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/users\/4656"}],"replies":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/comments?post=107168"}],"version-history":[{"count":1,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/posts\/107168\/revisions"}],"predecessor-version":[{"id":126234,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/posts\/107168\/revisions\/126234"}],"acf:user":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/users\/4139"},{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/users\/0"},{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/users\/3988"},{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/users\/4656"}],"acf:post":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/main_focus_post\/156992"},{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/main_focus_post\/156261"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/media\/22868"}],"wp:attachment":[{"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/media?parent=107168"}],"wp:term":[{"taxonomy":"post__type","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/post__type?post=107168"},{"taxonomy":"post_opinion","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/post_opinion?post=107168"},{"taxonomy":"post_serie","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/post_serie?post=107168"},{"taxonomy":"post_content_category","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/post_content_category?post=107168"},{"taxonomy":"post_content_subject","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/post_content_subject?post=107168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}