{"id":117776,"date":"2014-06-04T14:11:40","date_gmt":"2014-06-04T14:11:40","guid":{"rendered":"https:\/\/dievolkswirtschaft.ch\/2014\/06\/frauen-und-arbeitsmarkt-verschwendung-vermeiden\/"},"modified":"2023-08-23T23:17:48","modified_gmt":"2023-08-23T21:17:48","slug":"frauen-und-arbeitsmarkt-verschwendung-vermeiden","status":"publish","type":"post","link":"https:\/\/dievolkswirtschaft.ch\/de\/2014\/06\/frauen-und-arbeitsmarkt-verschwendung-vermeiden\/","title":{"rendered":"Frauen und Arbeitsmarkt: Verschwendung vermeiden!"},"content":{"rendered":"<p>In der Schweizer Wirtschaft w\u00e4chst der\u00a0Bedarf an Fachkr\u00e4ften. Die demografische\u00a0Alterung hat den Mangel an qualifiziertem\u00a0Personal bereits verst\u00e4rkt, und dieser Trend\u00a0wird sich in den kommenden Jahren weiter intensivieren. Im vergangenen Jahrzehnt\u00a0begegneten die Unternehmen dieser Herausforderung,\u00a0indem sie in gr\u00f6sserer Zahl\u00a0ausl\u00e4ndische Fachkr\u00e4fte rekrutierten, vor\u00a0allem aus der Europ\u00e4ischen Union. Doch\u00a0am 9. Februar hat das Schweizervolk entschieden,\u00a0die Zuwanderung zu bremsen.<\/p>\n<p>&#13;<\/p>\n<p>&nbsp;<\/p>\n<p>&#13;<\/p>\n<p>Nun m\u00fcssen sich die Wirtschaftsakteure\u00a0\u00fcberlegen, wie sie das Arbeitskr\u00e4ftereservoir\u00a0in der Schweiz optimal nutzen k\u00f6nnen.\u00a0Bereits 2011 betonten Bund, Kantone und\u00a0Sozialpartner anl\u00e4sslich der Lancierung\u00a0der Fachkr\u00e4fteinitiative, dass es wichtig sei,\u00a0das einheimische Arbeitskr\u00e4ftepotenzial \u2013\u00a0insbesondere dasjenige der Frauen \u2013 besser\u00a0auszusch\u00f6pfen und entsprechende Massnahmen\u00a0zu ergreifen.<\/p>\n<p>&#13;<\/p>\n<h3>Frauen sind heute ebenso gut\u00a0ausgebildet\u00a0wie M\u00e4nner<\/h3>\n<p>&#13;<\/p>\n<p>In der Schweiz ist das Bildungsniveau\u00a0der Frauen in den vergangenen Jahren betr\u00e4chtlich\u00a0gestiegen. Insgesamt haben sie\u00a0die M\u00e4nner eingeholt. Bei den Abschl\u00fcssen\u00a0an universit\u00e4ren Hochschulen und Fachhochschulen\u00a0haben sie die M\u00e4nner sogar\u00a0\u00fcberholt. Nun ist es an der Zeit, die Rendite\u00a0dieser weitgehend staatlich finanzierten Investitionen\u00a0zu optimieren. \u00a0Innerhalb der Paare ver\u00e4ndert sich das\u00a0Verh\u00e4ltnis zwischen dem Bildungsniveau der beiden Partner stetig, was sich auch auf\u00a0ihr berufliches Engagement auswirkt: Bei\u00a0den Paaren, f\u00fcr die sich aufgrund des Alters\u00a0der Frau (25 bis 44 Jahre) die Frage einer\u00a0Familiengr\u00fcndung stellt, war 2012 in 74% der F\u00e4lle die Frau mindestens gleich gut\u00a0ausgebildet wie der Mann. 1990 hatte dieser\u00a0Anteil noch bei 65% gelegen.<a href=\"#footnote_1\" id=\"footnote-anchor_1\" class=\"inline-footnote__anchor\">[1]<\/a><\/p>\n<p>&#13;<\/p>\n<h3>Mehrheit der Frauen arbeitet mit\u00a0hohen\u00a0Teilzeitpensen oder Vollzeit<\/h3>\n<p>&#13;<\/p>\n<p>Die Frauen sind auf dem Arbeitsmarkt\u00a0immer pr\u00e4senter. Diese Realit\u00e4t widerlegt\u00a0den Mythos, dass der Beruf der Hausfrau\u00a0seit Kurzem ein Revival erlebe. Wenn man\u00a0das letzte Jahrzehnt mit den 1990er-Jahren\u00a0vergleicht, stellt man fest, dass die Erwerbsquote\u00a0in beiden Jahrzehnten gleich\u00a0stark gestiegen ist (+15%). Bei den berufst\u00e4tigen Frauen geht der Trend gleichzeitig\u00a0in Richtung h\u00f6herer Pensen. So arbeiten\u00a0deutlich mehr Frauen Vollzeit (+9% im\u00a0letzten Jahrzehnt, gegen\u00fcber +2% in den\u00a01990er-Jahren). Zwar sind Teilzeitstellen\u00a0nach wie vor die Regel. Es gibt aber eine\u00a0deutliche Entwicklung hin zu h\u00f6heren\u00a0Pensen: Die Zahl der Frauen mit einem Besch\u00e4ftigungsgrad zwischen 50% und\u00a089% hat in diesem Zeitraum um 37%\u00a0zugenommen, die Zahl derjenigen, die\u00a0h\u00f6chstens 50% arbeiten, hingegen lediglich\u00a0um 3%.<a href=\"#footnote_2\" id=\"footnote-anchor_2\" class=\"inline-footnote__anchor\">[2]<\/a><\/p>\n<p>&#13;<\/p>\n<h3>Wirtschaftliches Potenzial der Frauen<\/h3>\n<p>&#13;<\/p>\n<p>Das Humankapital der Frauen l\u00e4sst sich\u00a0auf zwei Ebenen besser nutzen:<\/p>\n<p>&#13;<\/p>\n<ul>&#13;<\/p>\n<li>durch eine verst\u00e4rkte Beteiligung am Arbeitsmarkt und h\u00f6here Pensen. Dazu\u00a0sind Rahmenbedingungen notwendig,\u00a0die es den Frauen erm\u00f6glichen, sich auf\u00a0Wunsch beruflich st\u00e4rker zu engagieren;<\/li>\n<p>&#13;<\/p>\n<li>durch eine h\u00f6here Produktivit\u00e4t. Heute\u00a0bestehen hier angesichts\u00a0der Ausbildung\u00a0der Frauen h\u00e4ufig Defizite. Beheben\u00a0liessen sich diese durch eine angemessene Ber\u00fccksichtigung f\u00fcr verantwortungsvolle\u00a0Aufgaben, Weiterbildungen\u00a0und Bef\u00f6rderungen.<\/li>\n<p>&#13;\n<\/ul>\n<p>&#13;<\/p>\n<h3>Zu wenige Frauen in F\u00fchrungsetagen<\/h3>\n<p>&#13;<\/p>\n<p>In der Schweiz sind die Frauen wie in den\u00a0meisten Industriel\u00e4ndern auf F\u00fchrungsebene\u00a0stark untervertreten. Daran hat sich\u00a0auch in den letzten zehn Jahren kaum etwas\u00a0ge\u00e4ndert. 2013 hatten die Frauen in den Verwaltungsr\u00e4ten der 120 gr\u00f6ssten Schweizer\u00a0Unternehmen lediglich 12% der Sitze <a href=\"#footnote_3\" id=\"footnote-anchor_3\" class=\"inline-footnote__anchor\">[3]<\/a> und 1% der Vorsitze inne. Auf Gesch\u00e4ftsleitungsebene\u00a0ist die Situation noch extremer:\u00a0Lediglich 6% der Mitglieder und 3% der\u00a0CEOs sind Frauen.<a href=\"#footnote_4\" id=\"footnote-anchor_4\" class=\"inline-footnote__anchor\">[4]<\/a><\/p>\n<p>&#13;<\/p>\n<p>Diese schwache Vertretung der Frauen\u00a0\u00fcberrascht insbesondere im Fall der Verwaltungsr\u00e4te\u00a0der grossen Unternehmen,\u00a0denn Nachwuchs scheint durchaus vorhanden.\u00a0So geh\u00f6ren mehr als 6000 Frauen in\u00a0der Schweiz zu den h\u00f6heren Kadern, welche\u00a0mehr als 100 Personen f\u00fchren. Die H\u00e4lfte\u00a0von ihnen ist in traditionell m\u00e4nnlich dominierten\u00a0Branchen t\u00e4tig (siehe Grafik 1).<\/p>\n<p>&#13;<\/p>\n<p>Ein st\u00e4rkeres berufliches Engagement\u00a0von Frauen, die dies wollen, l\u00e4sst sich im\u00a0Wesentlichen auf zwei Wegen herbeif\u00fchren.<\/p>\n<p>&#13;<\/p>\n<h3>Vereinbarkeit von Beruf und Familie\u00a0verbessern<\/h3>\n<p>&#13;<\/p>\n<p>Die erste M\u00f6glichkeit besteht darin, daf\u00fcr\u00a0zu sorgen, dass Beruf und Familie besser\u00a0miteinander vereinbar sind. In dieser Hinsicht\u00a0hat die Schweiz einen betr\u00e4chtlichen\u00a0R\u00fcckstand aufzuholen. In den letzten Jahren\u00a0hat sich die Situation zwar verbessert;\u00a0in zwei Schl\u00fcsselbereichen sind aber weitere\u00a0Fortschritte notwendig: bei der Kinderbetreuung\u00a0und bei den Arbeitsbedingungen.<\/p>\n<p>&#13;<\/p>\n<h3>Familienerg\u00e4nzende Kinderbetreuung\u00a0weiter ausbauen<\/h3>\n<p>&#13;<\/p>\n<p>Die Frage der Kinderbetreuung spielt bei\u00a0beruflichen Entscheidungen von Frauen und\u00a0zunehmend auch von M\u00e4nnern eine zentrale\u00a0Rolle. Das Angebot an Betreuungspl\u00e4tzen\u00a0hinkt dem Bedarf insgesamt weiter hinterher,<br \/>&#13;<br \/>\nsowohl f\u00fcr Vorschul- als auch f\u00fcr Schulkinder.\u00a0Im internationalen Vergleich ist die\u00a0Schweiz nach wie vor im R\u00fcckstand. Die Gemeinden\u00a0m\u00fcssen als Hauptverantwortliche\u00a0solche Einrichtungen st\u00e4rker finanziell unterst\u00fctzen. Aktuell subventioniert der Bund\u00a0die Schaffung von Betreuungspl\u00e4tzen.<\/p>\n<p>&#13;<\/p>\n<h3>Flexiblere Arbeitsbedingungen anbieten<\/h3>\n<p>&#13;<\/p>\n<p>Damit sich mehr Eltern \u2013 Frauen, aber\u00a0auch M\u00e4nner \u2013 und mehr Arbeitnehmende\u00a0mit pflegebed\u00fcrftigen etagten Angeh\u00f6rigen\u00a0beruflich engagieren k\u00f6nnen, brauchen\u00a0sie flexiblere Arbeitsbedingungen. Dies\u00a0w\u00fcrde es ihnen erm\u00f6glichen, die Schnittstelle\u00a0zwischen Berufst\u00e4tigkeit und Familienleben\u00a0besser zu bew\u00e4ltigen. Vielversprechende L\u00f6sungen sind mehr Flexibilit\u00e4t bei\u00a0den Arbeitszeiten (wie Teilzeitstellen und\u00a0Jobsharing) und beim Arbeitsort (Telearbeit).\u00a0Entgegen der vorherrschenden Meinung\u00a0ist die Gr\u00f6sse eines Unternehmens kein Hindernis f\u00fcr eine Personalpolitik,\u00a0welche die Vereinbarkeit von Beruf und\u00a0Familie f\u00f6rdert. KMU verf\u00fcgen zwar nicht\u00a0\u00fcber die Ressourcen von Grossunternehmen\u00a0und sind deshalb meistens nicht in der\u00a0Lage, umfassende Programme umzusetzen.\u00a0Sie k\u00f6nnen aber andere, nicht weniger wertvolle\u00a0St\u00e4rken ausspielen: Formalit\u00e4ten und hierarchische Barrieren sind in KMU weniger\u00a0ausgepr\u00e4gt. Dies gibt zus\u00e4tzlichen Spielraum und macht es einfacher, die gegenseitigen\u00a0Bed\u00fcrfnisse abzukl\u00e4ren und rasch\u00a0individuelle L\u00f6sungen zu finden.\u00a0Eine solche Flexibilit\u00e4t erfordert jedoch\u00a0einen Paradigmenwechsel: Die Arbeitsorganisation\u00a0muss die Bed\u00fcrfnisse des Unternehmens\u00a0ber\u00fccksichtigen, sollte aber\u00a0weniger auf Pr\u00e4senzzeit und st\u00e4rker auf\u00a0Ergebnisse ausgerichtet sein. Dazu m\u00fcssen\u00a0psychologische Barrieren nicht nur bei den\u00a0Personalverantwortlichen, sondern auch\u00a0bei F\u00fchrungskr\u00e4ften aller Stufen abgebaut\u00a0werden.<\/p>\n<p>&#13;<\/p>\n<h3>Gl\u00e4serne Decke durchschlagen: Neue\u00a0Denkmuster und Unternehmenskulturen<\/h3>\n<p>&#13;<\/p>\n<p>H\u00e4ufig ist die ungen\u00fcgende Vereinbarkeit\u00a0von Beruf und Familie nicht das einzige\u00a0Hindernis f\u00fcr einen beruflichen Aufstieg\u00a0von Frauen. Denn rund jede dritte Frau\u00a0mit Terti\u00e4rabschluss hat in ihrem Leben\u00a0keine Kinder.5 Alle Menschen haben bewusst\u00a0oder unbewusst Denkmuster, die\u00a0stark von den aktuellen soziokulturellen Vorstellungen und Rollenmodellen gepr\u00e4gt\u00a0sind. Diverse aktuelle Studien aus dem Bereich\u00a0der Verhaltens\u00f6konomie zeigen, dass\u00a0h\u00e4ufig automatisch geschlechtsbezogene\u00a0Verzerrungseffekte (Gender Bias) aktiviert\u00a0werden, wenn Entscheidungstr\u00e4ger das Geschlecht\u00a0einer Person erfahren, die sich bewirbt.\u00a06 Diese Effekte beeinflussen die Vorstellungen\u00a0\u00fcber das berufliche Potenzial\u00a0von Frauen, die Bewertung ihrer Leistung und somit auch alle Entscheidungen von der\u00a0Anstellung \u00fcber die Weiterbildung bis zur\u00a0Bef\u00f6rderung. Die folgenden Beispiele veranschaulichen\u00a0solche Verzerrungen bei der Leistungsbewertung\u00a0und die damit verbundenen\u00a0Folgen: In einer Studie stieg die Chance\u00a0von Frauen, f\u00fcr ein Orchester rekrutiert zu\u00a0werden, um 50%, wenn die Bewerberinnen\u00a0und Bewerber f\u00fcr die Verantwortlichen\u00a0nicht sichtbar waren, sondern hinter einem\u00a0Vorhang spielten.7 Eine andere Studie\u00a0ergab, dass Frauen bei Erstfinanzierungen\u00a0f\u00fcr Jungunternehmen benachteiligt sind.\u00a0Bei entsprechenden Tests bevorzugten die\u00a0Investoren M\u00e4nner gegen\u00fcber Frauen selbst \u00a0bei inhaltlich identischen Pr\u00e4sentationen.8\u00a0Die Organisations- und Entscheidungsprozesse\u00a0im Personalbereich sind deshalb zu\u00a0\u00fcberdenken. Neue Konzepte sind gefragt.\u00a0Folgende Massnahmen k\u00f6nnen zur Verbesserung\u00a0der Situation beitragen:<\/p>\n<p>&#13;<\/p>\n<ul>&#13;<\/p>\n<li>Informationen und Sensibilisierung der F\u00fchrungskr\u00e4fte aller Stufen;\u00a0\u2013Bewerbungsgespr\u00e4che vor Vertretern\u00a0beider Geschlechter;<\/li>\n<p>&#13;<\/p>\n<li>Bewertung des Potenzials von Bewerberinnen\u00a0und Bewerbern sowie der Leistung\u00a0von Angestellten und Kadern mit\u00a0gemeinsamen Evaluationen (gleichzeitig\u00a0und vergleichend) statt mit getrennten\u00a0(nacheinander und einzeln);<\/li>\n<p>&#13;<\/p>\n<li>systematische Erweiterung des Rekrutierungspools\u00a0f\u00fcr F\u00fchrungskr\u00e4fte, insbesondere\u00a0\u00fcber pers\u00f6nliche m\u00e4nnliche\u00a0Netzwerke hinaus;<\/li>\n<p>&#13;<\/p>\n<li>Festlegung von Selektionskriterien, die\u00a0das Kompetenzprofil des gesamten (F\u00fchrungs-)\u00a0Teams und nicht nur der einzelnen\u00a0Personen ber\u00fccksichtigen.<\/li>\n<p>&#13;\n<\/ul>\n<p>&#13;<\/p>\n<ol class=\"footnote\"><li id=\"footnote_1\" class=\"footnote--item\">BFS, Volksz\u00e4hlung und Strukturerhebung, 2014.&nbsp;<a href=\"#footnote-anchor_1\" class=\"inline-footnote__anchor hidden-print\">[<span class=\"icon-arrow-up\"><\/span>]<\/a><\/li><li id=\"footnote_2\" class=\"footnote--item\">BFS, Medienmitteilung vom 25. April 2014 zurSchweizerischen Arbeitskr\u00e4fteerhebung (Sake) 2013.&nbsp;<a href=\"#footnote-anchor_2\" class=\"inline-footnote__anchor hidden-print\">[<span class=\"icon-arrow-up\"><\/span>]<\/a><\/li><li id=\"footnote_3\" class=\"footnote--item\">Bei den b\u00f6rsenkotierten Unternehmen insgesamtbetr\u00e4gt der Anteil 16% (siehe zCapital und SchweizerischerArbeitgeberverband: Gemischte Teamserbringenbessere Leistungen. Umfrage \u00fcber Frauenin Verwaltungsr\u00e4ten von Schweizer Publikumsgesellschaften,Z\u00fcrich, 31. Oktober 2013).&nbsp;<a href=\"#footnote-anchor_3\" class=\"inline-footnote__anchor hidden-print\">[<span class=\"icon-arrow-up\"><\/span>]<\/a><\/li><li id=\"footnote_4\" class=\"footnote--item\">Guido Schilling AG: Schillingreport 2014 \u2013 Transparenz an der Spitze: Die Gesch\u00e4ftsleitungen und Verwaltungsr\u00e4te der hundert gr\u00f6ssten Schweizer Unternehmen im Vergleich, Z\u00fcrich.&nbsp;<a href=\"#footnote-anchor_4\" class=\"inline-footnote__anchor hidden-print\">[<span class=\"icon-arrow-up\"><\/span>]<\/a><\/li><\/ol>","protected":false},"excerpt":{"rendered":"<p>In der Schweizer Wirtschaft w\u00e4chst der\u00a0Bedarf an Fachkr\u00e4ften. Die demografische\u00a0Alterung hat den Mangel an qualifiziertem\u00a0Personal bereits verst\u00e4rkt, und dieser Trend\u00a0wird sich in den kommenden Jahren weiter intensivieren. Im vergangenen Jahrzehnt\u00a0begegneten die Unternehmen dieser Herausforderung,\u00a0indem sie in gr\u00f6sserer Zahl\u00a0ausl\u00e4ndische Fachkr\u00e4fte rekrutierten, vor\u00a0allem aus der Europ\u00e4ischen Union. Doch\u00a0am 9. Februar hat das Schweizervolk entschieden,\u00a0die Zuwanderung zu bremsen. [&hellip;]<\/p>","protected":false},"author":3420,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"ep_exclude_from_search":false,"footnotes":""},"post__type":[66],"post_opinion":[],"post_serie":[],"post_content_category":[76,154],"post_content_subject":[],"acf":{"seco_author":3420,"seco_co_author":[2782,0],"author_override":"","seco_author_post_ocupation_year":"","seco_author_post_occupation_de":"Stv. Leiterin Ressort Arbeitsmarktanalyse und Sozialpolitik, Staatssekretariat f\u00fcr Wirtschaft SECO, Bern","seco_author_post_occupation_fr":"Cheffe suppl\u00e9ante, secteur Analyse du march\u00e9 du travail et politique sociale, Secr\u00e9tariat d\u2019\u00c9tat \u00e0 l\u2019\u00e9conomie SECO, Berne","seco_co_authors_post_ocupation":[{"seco_co_author":2782,"seco_co_author_post_occupation_year":"","seco_co_author_post_occupation_de":"Arbeitsmarktanalyse und Sozialpolitik, Direktion f\u00fcr Wirtschaftspolitik,Staatssekretariat f\u00fcr Wirtschaft (seco), Bern","seco_co_author_post_occupation_fr":"Chef du secteur Analyse du march\u00e9 du travail et politique sociale, direction de la Politique \u00e9conomique, Secr\u00e9tariat d'\u00c9tat \u00e0 l'\u00e9conomie (seco), Berne"}],"short_title":"","post_lead":"Die Schweizer Wirtschaft leidet unter einem Fachkr\u00e4ftemangel, der sich angesichts politischer Massnahmen zur Eind\u00e4mmung der Einwanderung noch versch\u00e4rfen d\u00fcrfte. Gleichzeitig sind Frauen heute ebenso gut qualifiziert wie M\u00e4nner und auch zunehmend auf dem Arbeitsmarkt pr\u00e4sent. Viele Frauen w\u00fcrden sich beruflich gerne noch st\u00e4rker engagieren. Ihre Kompetenzen nicht voll zu nutzen, ist eine wirtschaftliche Verschwendung. Um dies zu \u00e4ndern, gibt es im Wesentlichen zwei Wege: eine bessere Vereinbarkeit von Beruf und Familie sowie ein \u00dcberdenken von Stereotypen und Unternehmenskulturen.","post_hero_image_description":"","post_hero_image_description_copyright_de":"","post_hero_image_description_copyright_fr":"","post_references_literature":"","post_kasten":[{"kasten_title":"Kasten 1","kasten_box":"<h6>Informations- und Sensibilisierungsinstrumente\u00a0des Seco<\/h6>&#13;\n<p>Publikationen:<\/p>&#13;\n<ul>&#13;\n<li>KMU-Handbuch \u00abBeruf und Familie\u00bb<\/li>&#13;\n<li>Frauen in F\u00fchrungspositionen: so\u00a0gelingt\u2019s!<\/li>&#13;\n<li>Frauen in Verwaltungsr\u00e4ten:<br \/>&#13;\nSituation in Schweizer Unternehmen\u00a0und L\u00f6sungsans\u00e4tze in Europa\u00a0Informationsplattform:<\/li>&#13;\n<li>\u00abVereinbarkeit Beruf und Familie:\u00a0Massnahmen der Kantone und\u00a0Gemeinden\u00bb, www.berufundfamilie.<br \/>&#13;\nadmin.ch.<\/li>&#13;\n<\/ul>&#13;"}],"post_notes_for_print":"","first_teaser_header_de":"","first_teaser_header_fr":"","first_teaser_text_de":"","first_teaser_text_fr":"","second_teaser_header_de":"","second_teaser_header_fr":"","second_teaser_text_de":"","second_teaser_text_fr":"","kseason_de":"","kseason_fr":"","post_in_pdf":117779,"main_focus":[156669,157278],"serie_email":null,"frontpage_slider_bild":"","artikel_bild-slider":null,"legacy_id":"23776","post_abstract":"","magazine_issue":"20140601","seco_author_reccomended_post":null,"redaktoren":null,"korrektor":null,"planned_publication_date":null,"original_files":null,"external_release_for_author":"19700101","external_release_for_author_time":"00:00:00","link_for_external_authors":"https:\/\/dievolkswirtschaft.ch\/exedit\/5570407ca4476"},"_links":{"self":[{"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/posts\/117776"}],"collection":[{"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/users\/3420"}],"replies":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/comments?post=117776"}],"version-history":[{"count":1,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/posts\/117776\/revisions"}],"predecessor-version":[{"id":127051,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/posts\/117776\/revisions\/127051"}],"acf:post":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/main_focus_post\/157278"},{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/main_focus_post\/156669"}],"acf:user":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/users\/0"},{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/users\/2782"},{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/users\/3420"}],"wp:attachment":[{"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/media?parent=117776"}],"wp:term":[{"taxonomy":"post__type","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/post__type?post=117776"},{"taxonomy":"post_opinion","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/post_opinion?post=117776"},{"taxonomy":"post_serie","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/post_serie?post=117776"},{"taxonomy":"post_content_category","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/post_content_category?post=117776"},{"taxonomy":"post_content_subject","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/de\/wp-json\/wp\/v2\/post_content_subject?post=117776"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}