{"id":130992,"date":"2020-12-23T13:50:46","date_gmt":"2020-12-23T13:50:46","guid":{"rendered":"https:\/\/dievolkswirtschaft.ch\/2020\/12\/plateformes-quelles-nouveautes-sous-langle-economique\/"},"modified":"2023-08-23T23:56:07","modified_gmt":"2023-08-23T21:56:07","slug":"plateformes-quelles-nouveautes-sous-langle-economique","status":"publish","type":"post","link":"https:\/\/dievolkswirtschaft.ch\/fr\/2020\/12\/plateformes-quelles-nouveautes-sous-langle-economique\/","title":{"rendered":"Plateformes&nbsp;: quelles nouveaut\u00e9s sous l\u2019angle \u00e9conomique&nbsp;?"},"content":{"rendered":"<p>La litt\u00e9rature \u00e9conomique s\u2019int\u00e9resse de pr\u00e8s aux plateformes depuis une vingtaine d\u2019ann\u00e9es. Elle a forg\u00e9 le terme de \u00ab\u00a0march\u00e9 biface\u00a0\u00bb pour d\u00e9crire le ph\u00e9nom\u00e8ne, sans pour autant en donner une d\u00e9finition claire. Une plateforme d\u00e9signe habituellement un interm\u00e9diaire dans un march\u00e9 biface. Un tel march\u00e9 comprend au moins deux parties entre lesquelles il y a des effets de r\u00e9seau indirects, comme le chauffeur et le client sur Uber ou le logeur et l\u2019h\u00f4te sur Airbnb<a href=\"#footnote_1\" id=\"footnote-anchor_1\" class=\"inline-footnote__anchor\">[1]<\/a>. Autrement dit, l\u2019utilit\u00e9 de participer \u00e0 l\u2019une des faces du march\u00e9 d\u00e9pend du nombre d\u2019acteurs pr\u00e9sents sur l\u2019autre versant. Cette caract\u00e9ristique se retrouve bien entendu dans de nombreux march\u00e9s. Ainsi, le caract\u00e8re biface d\u2019un march\u00e9 est davantage de nature graduelle que binaire.&#13;<br \/>\n&#13;<br \/>\nLes plateformes tiennent compte des effets de r\u00e9seau notamment dans la fixation des prix. Il est essentiel pour une strat\u00e9gie biface de toujours impliquer toutes les faces du march\u00e9 afin de g\u00e9n\u00e9rer des effets de r\u00e9seau importants. Au lieu d\u2019exploiter au maximum une disposition \u00e9lev\u00e9e \u00e0 payer d\u2019une seule face du march\u00e9, la plateforme choisit une structure de prix qui internalise autant que possible les externalit\u00e9s positives li\u00e9es \u00e0 la participation. Ce ph\u00e9nom\u00e8ne est visible dans les structures de prix selon lesquelles l\u2019une des faces du march\u00e9 ne paie rien du tout. Outre l\u2019explication voulant que les utilisateurs paient dans ces cas-l\u00e0 avec leurs donn\u00e9es plut\u00f4t qu\u2019avec de l\u2019argent, la th\u00e9orie des march\u00e9s bifaces rel\u00e8ve \u00e9galement que des prix nuls d\u2019un c\u00f4t\u00e9 du march\u00e9 peuvent maximiser le profit d\u2019une plateforme en augmentant la participation de cette face du march\u00e9, accroissant ainsi l\u2019utilit\u00e9 et la disposition \u00e0 payer sur l\u2019autre versant. Cette internalisation d\u2019effets de r\u00e9seau indirects est souhaitable dans une optique de prosp\u00e9rit\u00e9, puisqu\u2019elle permet de maximiser \u00ab\u00a0le g\u00e2teau\u00a0\u00bb.&#13;<\/p>\n<h2>De nouveaux d\u00e9fis<\/h2>\n<p>&#13;<br \/>\nQuel est l\u2019apport de ces connaissances th\u00e9oriques dans la pratique\u00a0? D\u2019importants effets de r\u00e9seau peuvent tout d\u2019abord faire basculer les march\u00e9s, qui subissent ensuite l\u2019influence d\u2019un seul prestataire dominant. Une telle configuration peut correspondre \u00e0 un \u00e9quilibre \u00ab\u00a0naturel\u00a0\u00bb du march\u00e9, et une strat\u00e9gie biface peut consister \u00e0 cr\u00e9er un \u00e9quilibre de ce type, la plateforme \u00ab\u00a0subventionnant\u00a0\u00bb alors l\u2019une des faces du march\u00e9.&#13;<br \/>\n&#13;<br \/>\nComment les autorit\u00e9s responsables de la concurrence doivent-elles r\u00e9agir lorsqu\u2019une plateforme domine un march\u00e9\u00a0? Du point de vue de la politique de la concurrence, il n\u2019est pas forc\u00e9ment n\u00e9cessaire d\u2019intervenir dans une telle situation. En Suisse et dans l\u2019Union europ\u00e9enne (UE), le droit cartellaire n\u2019interdit pas le monopole. En outre, une plateforme dominante maximise les effets de r\u00e9seau pour toutes les parties, ce qui peut l\u2019emporter sur la baisse de prosp\u00e9rit\u00e9 engendr\u00e9e par le pouvoir de march\u00e9 qui accompagne un monopole. En ce qui concerne les march\u00e9s bifaces, l\u2019ouverture, la concurrence pour le march\u00e9 et le contr\u00f4le des abus rev\u00eatent donc une importance particuli\u00e8re.&#13;<br \/>\n&#13;<br \/>\nConcernant la concurrence pour le march\u00e9, les entr\u00e9es sur le march\u00e9 sont particuli\u00e8rement significatives. Les effets de r\u00e9seau mentionn\u00e9s pr\u00e9c\u00e9demment peuvent en effet compliquer l\u2019arriv\u00e9e de nouvelles plateformes. Souvent, les utilisateurs d\u2019une plateforme n\u2019ont a priori pas de raison d\u2019en changer\u00a0: d\u2019une part, les effets de r\u00e9seau d\u2019une nouvelle plateforme sont encore faibles\u00a0; d\u2019autre part, au moins une face du march\u00e9 de la plateforme existante est trait\u00e9e de mani\u00e8re avantageuse \u2013\u00a0souvent aux d\u00e9pens de l\u2019autre versant. Il est donc difficile de pousser toutes les faces du march\u00e9 \u00e0 recourir \u00e0 une nouvelle plateforme, m\u00eame lorsque cette derni\u00e8re pr\u00e9sente des avantages par rapport \u00e0 une plateforme existante. L\u2019entr\u00e9e sur le march\u00e9 peut \u00e9galement \u00eatre compliqu\u00e9e par le fait que les donn\u00e9es dont disposent certaines plateformes repr\u00e9sentent un avantage concurrentiel important. Dans ce cas, par exemple pour les moteurs de recherche et les prestataires de services de traduction, les fournisseurs \u00e9tablis ont une longueur d\u2019avance en mati\u00e8re de connaissances. Ils am\u00e9liorent constamment leur offre gr\u00e2ce \u00e0 l\u2019augmentation du volume de donn\u00e9es, ce qui attire encore plus d\u2019utilisateurs.&#13;<br \/>\n&#13;<br \/>\nContr\u00f4ler les abus peut se r\u00e9v\u00e9ler difficile. Comme expliqu\u00e9 pr\u00e9c\u00e9demment, les plateformes incluent g\u00e9n\u00e9ralement les diff\u00e9rentes faces du march\u00e9 dans leur strat\u00e9gie. Prendre en compte un seul versant pour le contr\u00f4le des abus risque de conduire \u00e0 des conclusions erron\u00e9es. Des prix \u00e9lev\u00e9s peuvent ainsi sembler abusifs alors qu\u2019ils s\u2019inscrivent dans une structure de prix asym\u00e9trique. Par ailleurs, les plateformes n\u2019occupent souvent une position dominante que sur l\u2019une des faces du march\u00e9. Dans ce cas, les march\u00e9s peuvent \u00e9galement \u00eatre consid\u00e9r\u00e9s de mani\u00e8re isol\u00e9e.&#13;<\/p>\n<h2>Des probl\u00e8mes connus<\/h2>\n<p>&#13;<br \/>\nLa politique de la concurrence est en outre confront\u00e9e \u00e0 d\u2019autres d\u00e9fis. Contrairement \u00e0 ceux mentionn\u00e9s jusqu\u2019ici et qui sont propres aux plateformes, ces d\u00e9fis-l\u00e0 sont connus de longue date. Les grands prestataires peuvent ainsi tenter d\u2019\u00e9tendre \u00e0 d\u2019autres march\u00e9s leur domination sur un march\u00e9. <a href=\"https:\/\/ec.europa.eu\/commission\/presscorner\/detail\/fr\/IP_17_1784\">Google<\/a> a par exemple \u00e9t\u00e9 amend\u00e9 par l\u2019UE pour avoir utilis\u00e9 la position dominante de son moteur de recherche dans le dessein de renforcer la position de son service de vente.&#13;<br \/>\n&#13;<br \/>\nLes plateformes en ligne peuvent aussi b\u00e9n\u00e9ficier dans certains domaines d\u2019une position si forte et si difficile \u00e0 attaquer qu\u2019elles fonctionnent comme les gardiennes de certains march\u00e9s. Les utilisateurs sont donc, dans une certaine mesure, d\u00e9pendants de la plateforme dominante. Une enqu\u00eate est d\u2019ailleurs en cours dans l\u2019UE pour \u00e9tablir si <a href=\"https:\/\/ec.europa.eu\/commission\/presscorner\/detail\/fr\/ip_20_1073\">Apple<\/a> contrevient au droit de la concurrence avec son App Store. Enfin, les prestataires dominants peuvent acheter de jeunes entreprises innovantes qui commencent \u00e0 se d\u00e9velopper afin de se prot\u00e9ger d\u2019une \u00e9ventuelle future \u00ab\u00a0menace\u00a0\u00bb. Face \u00e0 ces ph\u00e9nom\u00e8nes connus depuis longtemps, les autorit\u00e9s de la concurrence peuvent s\u2019appuyer sur leur longue exp\u00e9rience.&#13;<br \/>\n&#13;<br \/>\nCes derni\u00e8res doivent int\u00e9grer \u00e0 leurs analyses les particularit\u00e9s des march\u00e9s bifaces pr\u00e9c\u00e9demment mentionn\u00e9es (en sus des probl\u00e8mes connus de longue date), faute de quoi elles risquent de prendre des d\u00e9cisions erron\u00e9es. La Commission suisse de la concurrence (Comco) s\u2019est r\u00e9cemment occup\u00e9e de certains cas relatifs \u00e0 des plateformes en ligne, en tenant compte dans ses analyses des particularit\u00e9s des march\u00e9s bifaces. Dans le domaine des solutions de paiement en ligne, elle a notamment examin\u00e9 si <a href=\"https:\/\/www.weko.admin.ch\/weko\/fr\/home\/actualites\/communiques-de-presse\/nsb-news.msg-id-73448.html\">Apple<\/a> avait fait obstacle \u00e0 l\u2019utilisation sur ses appareils de l\u2019application suisse de paiement Twint au profit d\u2019Apple Pay. Elle a \u00e9galement interdit certaines clauses contractuelles anticoncurrentielles aux <a href=\"https:\/\/www.weko.admin.ch\/weko\/fr\/home\/actualites\/communiques-de-presse\/nsb-news.msg-id-59358.html\">plateformes de r\u00e9servation d\u2019h\u00f4tels<\/a>. Enfin, les autorit\u00e9s de la concurrence ont tenu compte des particularit\u00e9s des plateformes dans leur examen approfondi de la concentration des portails d\u2019emploi <a href=\"https:\/\/www.weko.admin.ch\/weko\/fr\/home\/actualites\/communiques-de-presse\/nsb-news.msg-id-58426.html\">JobCloud et JobScout\u00a024<\/a>.&#13;<\/p>\n<h2>Et maintenant\u00a0?<\/h2>\n<p>&#13;<br \/>\nCes cas montrent que la loi suisse sur les cartels, formul\u00e9e de mani\u00e8re relativement ouverte, fonctionne globalement bien \u00e0 l\u2019\u00e8re des plateformes num\u00e9riques. La question d\u2019une adaptation de la l\u00e9gislation se pose cependant dans de nombreux pays face \u00e0 la domination croissante de certaines grandes plateformes en ligne<a href=\"#footnote_2\" id=\"footnote-anchor_2\" class=\"inline-footnote__anchor\">[2]<\/a>. Un large \u00e9ventail de mesures est en discussion \u00e0 l\u2019\u00e9chelle internationale, dont certaines sont d\u00e9j\u00e0 entr\u00e9es en vigueur. Les propositions vont de seuils de notification suppl\u00e9mentaires dans le contr\u00f4le des fusions au renversement du fardeau de la preuve pour certaines op\u00e9rations de concentration, en passant par la baisse g\u00e9n\u00e9rale du seuil d\u2019intervention pr\u00e9vu par le droit de la concurrence dans le contr\u00f4le des abus et la scission de grandes plateformes en ligne. Des r\u00e8gles sont \u00e9galement au centre des d\u00e9bats en dehors du droit de la concurrence, comme les r\u00e9glementations sectorielles ou le droit \u00e0 la portabilit\u00e9 des donn\u00e9es dans la l\u00e9gislation sur la protection des donn\u00e9es.&#13;<br \/>\n&#13;<br \/>\nLa r\u00e9ponse aux d\u00e9fis pos\u00e9s par les plateformes num\u00e9riques en mati\u00e8re de concurrence fera-t-elle un jour l\u2019objet d\u2019un consensus\u00a0? Les autorit\u00e9s suisses participent en tout cas activement aux discussions internationales en cours<a href=\"#footnote_3\" id=\"footnote-anchor_3\" class=\"inline-footnote__anchor\">[3]<\/a>. \u00c0 l\u2019heure actuelle, il n\u2019est pas n\u00e9cessaire d\u2019intervenir au niveau l\u00e9gislatif en Suisse. D\u2019une part, la loi sur les cartels est formul\u00e9e de mani\u00e8re relativement ouverte, de sorte qu\u2019elle permet de couvrir de nombreuses nouveaut\u00e9s sans avoir \u00e0 \u00eatre modifi\u00e9e. D\u2019autre part, une grande partie des d\u00e9fis ne sont pas fondamentalement nouveaux ni sp\u00e9cifiques aux plateformes. Les avantages li\u00e9s \u00e0 la taille existent par exemple sur de nombreux march\u00e9s, notamment traditionnels. Enfin, il convient de noter que le droit de la concurrence n\u2019est pas pertinent pour l\u2019ensemble des d\u00e9fis pos\u00e9s par les plateformes num\u00e9riques, notamment lorsqu\u2019il est question de la protection des donn\u00e9es ou de la formation de l\u2019opinion.<\/p>\n<ol class=\"footnote\"><li id=\"footnote_1\" class=\"footnote--item\">Voir Rochet et Tirole (2003) ainsi que Rysman (2009).&nbsp;<a href=\"#footnote-anchor_1\" class=\"inline-footnote__anchor hidden-print\">[<span class=\"icon-arrow-up\"><\/span>]<\/a><\/li><li id=\"footnote_2\" class=\"footnote--item\">Voir notamment Conseil f\u00e9d\u00e9ral (2017), Schweitzer et al. (2018), Digital competition expert panel (2019), Cr\u00e9mer et al. (2019), Stigler Committee on digital platforms (2019), Subcommittee on antitrust (2020) et OCDE (2018).&nbsp;<a href=\"#footnote-anchor_2\" class=\"inline-footnote__anchor hidden-print\">[<span class=\"icon-arrow-up\"><\/span>]<\/a><\/li><li id=\"footnote_3\" class=\"footnote--item\">Wallimann et Beuret (2020).&nbsp;<a href=\"#footnote-anchor_3\" class=\"inline-footnote__anchor hidden-print\">[<span class=\"icon-arrow-up\"><\/span>]<\/a><\/li><\/ol>","protected":false},"excerpt":{"rendered":"<p>La litt\u00e9rature \u00e9conomique s\u2019int\u00e9resse de pr\u00e8s aux plateformes depuis une vingtaine d\u2019ann\u00e9es. Elle a forg\u00e9 le terme de \u00ab\u00a0march\u00e9 biface\u00a0\u00bb pour d\u00e9crire le ph\u00e9nom\u00e8ne, sans pour autant en donner une d\u00e9finition claire. Une plateforme d\u00e9signe habituellement un interm\u00e9diaire dans un march\u00e9 biface. Un tel march\u00e9 comprend au moins deux parties entre lesquelles il y a [&hellip;]<\/p>","protected":false},"author":4053,"featured_media":100216,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"ep_exclude_from_search":false,"footnotes":""},"post__type":[81,83],"post_opinion":[],"post_serie":[],"post_content_category":[105],"post_content_subject":[],"acf":{"seco_author":4053,"seco_co_author":[5135,0],"author_override":"","seco_author_post_ocupation_year":"","seco_author_post_occupation_de":"Wissenschaftlicher Mitarbeiter, Ressort Wachstum und Wettbewerbspolitik, Staatssekretariat f\u00fcr Wirtschaft (Seco), Bern","seco_author_post_occupation_fr":"Collaborateur scientifique, secteur Croissance et politique de la concurrence, Secr\u00e9tariat d\u2019\u00c9tat \u00e0 l\u2019\u00e9conomie (Seco), Berne","seco_co_authors_post_ocupation":[{"seco_co_author":5135,"seco_co_author_post_occupation_year":"","seco_co_author_post_occupation_de":"PhD in Economics, wissenschaftlicher Mitarbeiter, Ressort Wachstum und Wettbewerbspolitik, Staatssekretariat f\u00fcr Wirtschaft (Seco), Bern","seco_co_author_post_occupation_fr":"Collaborateur scientifique, secteur Croissance et politique de la concurrence, Secr\u00e9tariat d\u2019\u00c9tat \u00e0 l\u2019\u00e9conomie (Seco), Berne"}],"short_title":"Plateformes : quelles nouveaut\u00e9s sous l\u2019angle \u00e9conomique ?","post_lead":"Les plateformes Internet sont omnipr\u00e9sentes. Alors que des voix r\u00e9clament une adaptation du droit de la concurrence, un ajustement s\u2019av\u00e8re tout sauf \u00e9vident du point de vue \u00e9conomique.","post_hero_image_description":"Ein Uber-Eats-Fahrer liefert in Genf Essen aus.","post_hero_image_description_copyright_de":"Keystone","post_hero_image_description_copyright_fr":"Keystone","post_references_literature":"<ul>&#13;\n \t<li>Conseil f\u00e9d\u00e9ral (2017). <a href=\"https:\/\/www.seco.admin.ch\/seco\/fr\/home\/wirtschaftslage---wirtschaftspolitik\/wirschaftspolitik\/digitalisierung.html\"><em>Rapport sur les principales conditions-cadre pour l'\u00e9conomie num\u00e9rique<\/em><\/a>. Chapitre\u00a07, Politique de la concurrence.<\/li>&#13;\n \t<li>Cr\u00e9mer J., de Montjoye Y.-A. et Schweitzer H. (2019). <a href=\"https:\/\/ec.europa.eu\/competition\/publications\/reports\/kd0419345enn.pdf\"><em>Competition policy for the digital era<\/em><\/a>. \u00c9tude command\u00e9e par la Direction g\u00e9n\u00e9rale de la concurrence de la Commission europ\u00e9enne.<\/li>&#13;\n \t<li>Digital competition expert panel (2019). <a href=\"https:\/\/assets.publishing.service.gov.uk\/government\/uploads\/system\/uploads\/attachment_data\/file\/785547\/unlocking_digital_competition_furman_review_web.pdf\"><em>Unlocking digital competition<\/em><\/a>. Rapport d\u2019une commission d\u2019experts mandat\u00e9e par le Minist\u00e8re britannique des finances et de l\u2019\u00e9conomie.<\/li>&#13;\n \t<li>OCDE \u2013\u00a0Organisation de coop\u00e9ration et de d\u00e9veloppement \u00e9conomiques (2018). <a href=\"https:\/\/www.oecd.org\/fr\/concurrence\/rethinking-antitrust-tools-for-multi-sided-platforms.htm\"><em>Rethinking antitrust tools for multi-sided platforms<\/em><\/a>.<\/li>&#13;\n \t<li>Rochet J.\u2010C. et Tirole J. (2003). \u00ab\u00a0<a href=\"https:\/\/academic.oup.com\/jeea\/article\/1\/4\/990\/2280902\">Platform competition in two\u2010sided markets<\/a> \u00bb. <em>Journal of the European Economic Association<\/em>, 1\u00a0: 990\u20131029.<\/li>&#13;\n \t<li>Rysman M. (2009). \u00ab\u00a0<a href=\"https:\/\/www.aeaweb.org\/articles?id=10.1257\/jep.23.3.125\">The economics of two-sided markets<\/a> \u00bb. <em>Journal of Economic Perspectives<\/em>, 23, 3\u00a0: 125\u2013143.<\/li>&#13;\n \t<li>Schweitzer H., Haucap J., Kerber W. et Welker R. (2018). <a href=\"https:\/\/www.bmwi.de\/Redaktion\/DE\/Publikationen\/Wirtschaft\/modernisierung-der-missbrauchsaufsicht-fuer-marktmaechtige-unternehmen.pdf?__blob=publicationFile&amp;v=15\"><em>Modernisierung der Missbrauchsaufsicht f\u00fcr marktm\u00e4chtige Unternehmen<\/em><\/a>. \u00c9tude command\u00e9e par le Minist\u00e8re f\u00e9d\u00e9ral allemand de l'\u00e9conomie et de l\u2019\u00e9nergie.<\/li>&#13;\n \t<li>Stigler Committee on digital platforms (2019). <a href=\"https:\/\/www.chicagobooth.edu\/-\/media\/research\/stigler\/pdfs\/digital-platforms---committee-report---stigler-center.pdf\"><em>Final report<\/em><\/a>. University of Chicago Booth School of Business.<\/li>&#13;\n \t<li>Subcommittee on Antitrust, commercial and administrative law of the Committee on the judiciary, U.S.\u00a0House of Representatives (2020). <a href=\"https:\/\/judiciary.house.gov\/uploadedfiles\/competition_in_digital_markets.pdf\"><em>Investigation of competition in digital markets<\/em><\/a>. Rapport de la majorit\u00e9 et recommandations.<\/li>&#13;\n \t<li>Wallimann N. et Beuret C. (2020). \u00ab\u00a0<a href=\"https:\/\/dievolkswirtschaft.ch\/fr\/2020\/06\/wallimann-beuret-07-2020fr\/\">Qui supervise la concurrence \u00e0 l\u2019\u00e9chelle mondiale\u00a0?<\/a> \u00bb. <em>La Vie \u00e9conomique<\/em>, 7\/2020.<\/li>&#13;\n<\/ul>","post_kasten":null,"post_notes_for_print":"","first_teaser_header_de":"","first_teaser_header_fr":"","first_teaser_text_de":"","first_teaser_text_fr":"","second_teaser_header_de":"","second_teaser_header_fr":"","second_teaser_text_de":"","second_teaser_text_fr":"","kseason_de":"","kseason_fr":"","post_in_pdf":130995,"main_focus":[155918,156747],"serie_email":null,"frontpage_slider_bild":130999,"artikel_bild-slider":null,"legacy_id":"99794","post_abstract":"Les mod\u00e8les commerciaux fond\u00e9s sur des plateformes rencontrent un tr\u00e8s grand succ\u00e8s dans l\u2019\u00e9conomie num\u00e9rique. Faut-il modifier le droit de la concurrence\u00a0? Et une r\u00e9glementation sp\u00e9cifique \u00e0 ces entreprises est-elle n\u00e9cessaire\u00a0? D\u2019un point de vue \u00e9conomique, les march\u00e9s des plateformes pr\u00e9sentent effectivement des particularit\u00e9s. Les d\u00e9fis qui en d\u00e9coulent ne sont cependant pas compl\u00e8tement nouveaux et il est dans la plupart des cas tout \u00e0 fait possible de s\u2019appuyer sur les r\u00e8gles existantes, comme le montrent plusieurs proc\u00e9dures boucl\u00e9es ces derni\u00e8res ann\u00e9es par diff\u00e9rentes autorit\u00e9s, notamment dans l\u2019Union europ\u00e9enne contre Google ou en Suisse contre les plateformes de r\u00e9servation d\u2019h\u00f4tels.","magazine_issue":"20210102","seco_author_reccomended_post":null,"redaktoren":[4127,0],"korrektor":4139,"planned_publication_date":"20210109","original_files":null,"external_release_for_author":"20201213","external_release_for_author_time":"23:00:00","link_for_external_authors":"https:\/\/dievolkswirtschaft.ch\/exedit\/5fa27cc1c4469"},"_links":{"self":[{"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/posts\/130992"}],"collection":[{"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/users\/4053"}],"replies":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/comments?post=130992"}],"version-history":[{"count":1,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/posts\/130992\/revisions"}],"predecessor-version":[{"id":187531,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/posts\/130992\/revisions\/187531"}],"acf:user":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/users\/4139"},{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/users\/4127"},{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/users\/0"},{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/users\/5135"},{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/users\/4053"}],"acf:post":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/main_focus_post\/156747"},{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/main_focus_post\/155918"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/media\/100216"}],"wp:attachment":[{"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/media?parent=130992"}],"wp:term":[{"taxonomy":"post__type","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/post__type?post=130992"},{"taxonomy":"post_opinion","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/post_opinion?post=130992"},{"taxonomy":"post_serie","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/post_serie?post=130992"},{"taxonomy":"post_content_category","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/post_content_category?post=130992"},{"taxonomy":"post_content_subject","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/post_content_subject?post=130992"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}