{"id":132717,"date":"2020-05-05T08:18:48","date_gmt":"2020-05-05T08:18:48","guid":{"rendered":"https:\/\/dievolkswirtschaft.ch\/2020\/05\/kemeny-bachmann-06-2020fr\/"},"modified":"2023-08-24T00:00:22","modified_gmt":"2023-08-23T22:00:22","slug":"kemeny-bachmann-06-2020fr","status":"publish","type":"post","link":"https:\/\/dievolkswirtschaft.ch\/fr\/2020\/05\/kemeny-bachmann-06-2020fr\/","title":{"rendered":"Le coronavirus p\u00e8se sur la confiance des consommateurs"},"content":{"rendered":"<p>L\u2019indice du climat de consommation a chut\u00e9 \u00e0 un niveau historiquement bas en avril. La confiance des consommateurs suisses s\u2019est d\u00e9grad\u00e9e, passant de -9 points en janvier \u00e0 -39 points. M\u00eame le choc p\u00e9trolier des ann\u00e9es\u00a01970 et la crise financi\u00e8re de\u00a02008\u20132009 n\u2019avaient pas engendr\u00e9 un climat si morose. Et l\u2019on n\u2019avait pas enregistr\u00e9 des valeurs semblables depuis la crise immobili\u00e8re des ann\u00e9es\u00a01990. Mais le coronavirus affecte-t-il le moral de tous les consommateurs de la m\u00eame mani\u00e8re\u00a0?&#13;<br \/>\n&#13;<br \/>\nLe Secr\u00e9tariat d\u2019\u00c9tat \u00e0 l\u2019\u00e9conomie (Seco) calcule chaque trimestre <a href=\"https:\/\/www.seco.admin.ch\/seco\/fr\/home\/wirtschaftslage---wirtschaftspolitik\/Wirtschaftslage\/Konsumentenstimmung.html\">l\u2019indice du climat de consommation<\/a> sur la base d\u2019une enqu\u00eate men\u00e9e habituellement aupr\u00e8s de quelque 1200\u00a0personnes \u2013\u00a0contre \u00a01900\u00a0priv\u00e9s en avril\u00a02020. Ces personnes \u00e9tant r\u00e9parties sur l\u2019ensemble du territoire, elles sont expos\u00e9es \u00e0 un risque variable de contamination par le coronavirus. Ce risque est plus marqu\u00e9 dans les cantons de Gen\u00e8ve, du Tessin et de Vaud, qui ont les nombres de cas confirm\u00e9s rapport\u00e9s \u00e0 leur population les plus \u00e9lev\u00e9s du pays. La probabilit\u00e9 que la maladie enregistre une \u00e9volution d\u00e9favorable varie en outre d\u2019un individu \u00e0 l\u2019autre et tend \u00e0 augmenter pour les plus \u00e2g\u00e9s. D\u00e8s lors, les personnes \u00e0 risque ont-elles une vision plus pessimiste de la situation \u00e9conomique que celles qui sont moins menac\u00e9es\u00a0?&#13;<br \/>\n&#13;<br \/>\nLes analyses par r\u00e9gion linguistique ne fournissent aucun \u00e9l\u00e9ment qui corroborerait cette hypoth\u00e8se\u00a0: de janvier \u00e0 avril\u00a02020, l\u2019indice du climat de consommation a chut\u00e9 de fa\u00e7on similaire dans toutes les r\u00e9gions linguistiques (-27\u00a0points en Suisse romande, -31\u00a0points au Tessin et -33\u00a0points en Suisse al\u00e9manique). Toutes r\u00e9gions confondues, les personnes interrog\u00e9es s\u2019attendent \u00e0 une forte d\u00e9gradation de la conjoncture et de leur situation budg\u00e9taire. Leur propension \u00e0 actuellement r\u00e9aliser de grandes acquisitions s\u2019est elle aussi d\u00e9t\u00e9rior\u00e9e de mani\u00e8re similaire dans les diff\u00e9rentes parties du pays.&#13;<\/p>\n<h2>Le spectre du recul des revenus<\/h2>\n<p>&#13;<br \/>\nDes variations importantes apparaissent en revanche en fonction de l\u2019\u00e2ge. Le climat de consommation tend \u00e0 se d\u00e9grader au fur et mesure que l\u2019\u00e2ge avance. Une analyse plus d\u00e9taill\u00e9e montre toutefois que les rapports entre l\u2019\u00e2ge et le moral des consommateurs sont plus complexes qu\u2019il n\u2019y para\u00eet au premier abord\u00a0: les personnes de plus de 65\u00a0ans ont tendance \u00e0 \u00eatre plus optimistes que celles de moins de 65\u00a0ans (voir <em>illustration<\/em>). Cet \u00e9cart existait d\u00e9j\u00e0 avant la pand\u00e9mie, mais s\u2019est encore creus\u00e9 lors de l\u2019enqu\u00eate d\u2019avril\u00a0: le moral des consommateurs de moins de 65\u00a0ans a perdu 34\u00a0points durant le premier trimestre\u00a02020, contre seulement 24\u00a0points pour les 65\u00a0ans et plus. Ce r\u00e9sultat peut \u00e0 premi\u00e8re vue para\u00eetre surprenant dans la mesure o\u00f9 les retrait\u00e9s font partie du groupe \u00e0 risque face au Covid-19.&#13;<br \/>\n&#13;<br \/>\nCe constat a toutefois une explication\u00a0: les plus de 65\u00a0ans craignent moins pour leur emploi et n\u2019essuient gu\u00e8re de pertes de revenus dues au ch\u00f4mage partiel. Leur situation financi\u00e8re attendue n\u2019a donc gu\u00e8re \u00e9volu\u00e9, alors qu\u2019elle s\u2019est nettement d\u00e9grad\u00e9e pour les moins de 65\u00a0ans. Les analyses par profession confirment cette hypoth\u00e8se\u00a0: les personnes dont le revenu est sujet \u00e0 des fluctuations voient leur avenir financier moins positivement. Les attentes des ind\u00e9pendants face \u00e0 leur situation financi\u00e8re se sont ainsi davantage p\u00e9jor\u00e9es (-37\u00a0points) que celles des salari\u00e9s (-22\u00a0points). Cette situation se r\u00e9percute \u00e9galement sur le climat de consommation, qui s\u2019est davantage d\u00e9t\u00e9rior\u00e9 pour les premiers (-44\u00a0points) que pour les seconds (-35\u00a0points).&#13;<\/p>\n<h3 class=\"text__graphic-title\">Climat de consommation en fonction de l\u2019\u00e2ge (avril\u00a02020)<\/h3>\n<p>&#13;<br \/>\n<a href=\"https:\/\/dievolkswirtschaft.ch\/content\/uploads\/2020\/05\/Bildschirmfoto-2020-05-04-um-14.41.37.png\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-95454\" src=\"https:\/\/dievolkswirtschaft.ch\/content\/uploads\/2020\/05\/Bildschirmfoto-2020-05-04-um-14.41.37.png\" alt=\"\" width=\"1780\" height=\"1058\" \/><\/a>&#13;<br \/>\n&#13;<br \/>\n<span class=\"text__legend\">Remarque\u00a0: chaque point repr\u00e9sente l\u2019une des 1896\u00a0personnes interrog\u00e9es.<\/span>&#13;<br \/>\n&#13;<br \/>\n<span class=\"text__quelle--ground\">Source\u00a0: Seco \/ La Vie \u00e9conomique<\/span>&#13;<br \/>\n&#13;<br \/>\nLa pand\u00e9mie de coronavirus affecte les consommateurs de multiples mani\u00e8res\u00a0: la fermeture des commerces et les interdictions rendent impossible la consommation de certains biens, les ind\u00e9pendants et les salari\u00e9s au ch\u00f4mage partiel doivent compter avec une baisse des revenus tandis que l\u2019incertitude face \u00e0 l\u2019\u00e9volution de la conjoncture et l\u2019inqui\u00e9tude pour les emplois ne cesse d\u2019augmenter.&#13;<br \/>\n&#13;<br \/>\nLe dernier sondage fournit \u00e9galement des indications sur les \u00e9l\u00e9ments responsables de ce mauvais climat de consommation\u00a0: il a \u00e9t\u00e9 demand\u00e9 aux participants de pr\u00e9ciser leur r\u00e9ponse \u00e0 la question de savoir si le moment \u00e9tait propice aux grandes acquisitions. R\u00e9sultat\u00a0: 41\u00a0% des personnes convaincues que le moment \u00e9tait peu favorable \u00e0 ces achats ont explicitement invoqu\u00e9 la pand\u00e9mie<a href=\"#footnote_1\" id=\"footnote-anchor_1\" class=\"inline-footnote__anchor\">[1]<\/a>. L\u2019ins\u00e9curit\u00e9 (25\u00a0%) ou la \u00ab\u00a0situation actuelle\u00a0\u00bb (18\u00a0%) sont nettement plus d\u00e9terminantes que la situation au travail (9\u00a0%) ou la fermeture des magasins (7\u00a0%). Seuls 2\u00a0% des personnes interrog\u00e9es ont cit\u00e9 le ch\u00f4mage partiel pour expliquer la faible propension \u00e0 acheter.&#13;<br \/>\n&#13;<br \/>\nCes r\u00e9ponses laissent penser que l\u2019ouverture des commerces n\u2019entra\u00eenera pas \u00e0 elle seule une nette augmentation de la disposition \u00e0 consommer. On ne peut s\u2019attendre \u00e0 une embellie que lorsque l\u2019incertitude li\u00e9e \u00e0 la pand\u00e9mie se sera largement dissip\u00e9e.<\/p>\n<ol class=\"footnote\"><li id=\"footnote_1\" class=\"footnote--item\">Les personnes interrog\u00e9es peuvent indiquer plusieurs raisons, ce qui explique que le total des pourcentages n\u2019est pas \u00e9gal \u00e0 100\u00a0%.&nbsp;<a href=\"#footnote-anchor_1\" class=\"inline-footnote__anchor hidden-print\">[<span class=\"icon-arrow-up\"><\/span>]<\/a><\/li><\/ol>","protected":false},"excerpt":{"rendered":"<p>L\u2019indice du climat de consommation a chut\u00e9 \u00e0 un niveau historiquement bas en avril. La confiance des consommateurs suisses s\u2019est d\u00e9grad\u00e9e, passant de -9 points en janvier \u00e0 -39 points. M\u00eame le choc p\u00e9trolier des ann\u00e9es\u00a01970 et la crise financi\u00e8re de\u00a02008\u20132009 n\u2019avaient pas engendr\u00e9 un climat si morose. Et l\u2019on n\u2019avait pas enregistr\u00e9 des valeurs [&hellip;]<\/p>","protected":false},"author":4638,"featured_media":102209,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"ep_exclude_from_search":false,"footnotes":""},"post__type":[81,83],"post_opinion":[],"post_serie":[],"post_content_category":[],"post_content_subject":[],"acf":{"seco_author":4638,"seco_co_author":[4189,0],"author_override":"","seco_author_post_ocupation_year":"","seco_author_post_occupation_de":"\u00d6konom, Ressort Konjunktur, Staatssekretariat f\u00fcr Wirtschaft (Seco), Bern","seco_author_post_occupation_fr":"\u00c9conomiste, secteur Conjoncture, Secr\u00e9tariat d\u2019\u00c9tat \u00e0 l\u2019\u00e9conomie (Seco), Berne","seco_co_authors_post_ocupation":[{"seco_co_author":4189,"seco_co_author_post_occupation_year":"","seco_co_author_post_occupation_de":"Leiterin Ressort Konjunktur, Staatssekretariat f\u00fcr Wirtschaft (Seco), Bern","seco_co_author_post_occupation_fr":"Cheffe du secteur Conjoncture, Secr\u00e9tariat d\u2019\u00c9tat \u00e0 l\u2019\u00e9conomie (Seco), Berne"}],"short_title":"Coronavirus : les consommateurs moins confiants","post_lead":"Le climat de consommation a chut\u00e9 \u00e0 un niveau historiquement bas. Les ind\u00e9pendants et les personnes proches de l\u2019\u00e2ge de la retraite se montrent particuli\u00e8rement pessimistes concernant la situation.","post_hero_image_description":"","post_hero_image_description_copyright_de":"","post_hero_image_description_copyright_fr":"","post_references_literature":"","post_kasten":null,"post_notes_for_print":"","first_teaser_header_de":"","first_teaser_header_fr":"","first_teaser_text_de":"","first_teaser_text_fr":"","second_teaser_header_de":"","second_teaser_header_fr":"","second_teaser_text_de":"","second_teaser_text_fr":"","kseason_de":"","kseason_fr":"","post_in_pdf":"","main_focus":null,"serie_email":null,"frontpage_slider_bild":132720,"artikel_bild-slider":null,"legacy_id":"95347","post_abstract":"","magazine_issue":"20200601","seco_author_reccomended_post":null,"redaktoren":[3988,0],"korrektor":4139,"planned_publication_date":"20200525","original_files":null,"external_release_for_author":"20200504","external_release_for_author_time":"00:00:00","link_for_external_authors":"https:\/\/dievolkswirtschaft.ch\/exedit\/5eaa777f6c56b"},"_links":{"self":[{"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/posts\/132717"}],"collection":[{"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/users\/4638"}],"replies":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/comments?post=132717"}],"version-history":[{"count":1,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/posts\/132717\/revisions"}],"predecessor-version":[{"id":187662,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/posts\/132717\/revisions\/187662"}],"acf:user":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/users\/4139"},{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/users\/3988"},{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/users\/0"},{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/users\/4189"},{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/users\/4638"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/media\/102209"}],"wp:attachment":[{"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/media?parent=132717"}],"wp:term":[{"taxonomy":"post__type","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/post__type?post=132717"},{"taxonomy":"post_opinion","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/post_opinion?post=132717"},{"taxonomy":"post_serie","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/post_serie?post=132717"},{"taxonomy":"post_content_category","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/post_content_category?post=132717"},{"taxonomy":"post_content_subject","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/post_content_subject?post=132717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}