{"id":134497,"date":"2019-07-18T11:00:23","date_gmt":"2019-07-18T11:00:23","guid":{"rendered":"https:\/\/dievolkswirtschaft.ch\/2019\/07\/wallacher-08-09-2019fr\/"},"modified":"2023-08-24T00:04:16","modified_gmt":"2023-08-23T22:04:16","slug":"wallacher-08-09-2019fr","status":"publish","type":"post","link":"https:\/\/dievolkswirtschaft.ch\/fr\/2019\/07\/wallacher-08-09-2019fr\/","title":{"rendered":"Des crit\u00e8res \u00e9thiques pour un ordre commercial mondial"},"content":{"rendered":"<p>De vifs d\u00e9bats souvent \u00e9motionnels et des contestations publiques accompagnent depuis longtemps les accords commerciaux. Pour leurs d\u00e9tracteurs, ces accords augmentent l\u2019in\u00e9galit\u00e9. Les normes de protection sociale, environnementale et des consommateurs seraient insuffisantes, et les accords sur les investissements ou les tribunaux arbitraux priv\u00e9s restreindraient la marge de man\u0153uvre des pays. Leurs partisans, eux, font \u00e9tat d\u2019effets positifs sur la croissance et sur l\u2019emploi.&#13;<br \/>\n&#13;<br \/>\nDu point de vue de l\u2019\u00e9thique \u00e9conomique, le commerce international ne constitue jamais une fin en soi, mais doit toujours \u00eatre \u00e9valu\u00e9 \u00e0 l\u2019aune de ses cons\u00e9quences sur la prosp\u00e9rit\u00e9 g\u00e9n\u00e9rale, de l\u2019int\u00e9gration et de la participation sociale de tous, ainsi que des perspectives de d\u00e9veloppement des personnes les plus d\u00e9munies. L\u2019\u00e9valuation d\u2019accords commerciaux selon des crit\u00e8res \u00e9thiques requiert donc une analyse objective des corr\u00e9lations concr\u00e8tes.&#13;<br \/>\n&#13;<br \/>\nLes th\u00e9oriques \u00e9conomiques et les \u00e9tudes empiriques montrent que les relations commerciales offrent aux \u00e9conomies nationales impliqu\u00e9es des opportunit\u00e9s d\u2019augmenter la prosp\u00e9rit\u00e9, de cr\u00e9er des emplois et de diminuer la pauvret\u00e9. En effet, la lev\u00e9e des obstacles tarifaires et non tarifaires au commerce ainsi que les normes et standards communs am\u00e9liorent les d\u00e9bouch\u00e9s, intensifient la concurrence et permettent la production \u00e0 grande \u00e9chelle, ce qui r\u00e9duit les co\u00fbts de production, \u00e9largit l\u2019offre et diminue les prix pour les consommateurs. Les relations commerciales internationales donnent aux pays les plus pauvres la possibilit\u00e9 de d\u00e9velopper leur \u00e9conomie gr\u00e2ce \u00e0 la hausse des exportations, aux investissements directs \u00e9trangers et \u00e0 l\u2019utilisation de nouvelles technologies import\u00e9es.&#13;<\/p>\n<h2>Ne pas oublier les perdants de la mondialisation<\/h2>\n<p>&#13;<br \/>\nUne ouverture de l\u2019\u00e9conomie vers l\u2019ext\u00e9rieur comporte cependant des risques. Les \u00e9conomies nationales ouvertes sont davantage expos\u00e9es aux facteurs externes, comme la volatilit\u00e9 des taux de change ou des prix sur les march\u00e9s mondiaux. Il faut en outre tenir compte des effets de r\u00e9partition \u00e0 la fois entre les pays signataires des accords et au sein de chaque pays. Car l\u2019ouverture des march\u00e9s et l\u2019intensification de la concurrence font presque in\u00e9vitablement des gagnants et des perdants. Le commerce ext\u00e9rieur profite avant tout \u00e0 ceux qui disposent de connaissances sp\u00e9cialis\u00e9es, de brevets ou des biens-fonds, machines et structures de distribution n\u00e9cessaires, car il augmente la demande de ces facteurs de production.&#13;<br \/>\n&#13;<br \/>\nL\u2019int\u00e9gration croissante dans le commerce mondial acc\u00e9l\u00e8re les changements structurels et souligne l\u2019urgence des mesures d\u2019adaptation \u00e0 prendre. Si certains facteurs de production ou certaines exploitations traditionnelles ne sont plus comp\u00e9titifs, il y a un risque de fermeture d\u2019entreprises et de hausse du ch\u00f4mage.&#13;<br \/>\n&#13;<br \/>\nM\u00eame lorsque des pays adaptent rapidement leur production aux nouveaux secteurs pris\u00e9s \u00e0 l\u2019international,\u00a0pouvant ainsi obtenir des avantages comp\u00e9titifs, l\u2019ouverture du march\u00e9 profite en g\u00e9n\u00e9ral surtout \u00e0 la main-d\u2019\u0153uvre mieux qualifi\u00e9e. Par cons\u00e9quent, les personnes moins qualifi\u00e9es sont souvent perdantes si elles n\u2019arrivent pas \u00e0 am\u00e9liorer leur niveau de formation, y compris dans les \u00e9conomies florissantes.&#13;<br \/>\n&#13;<br \/>\nC\u2019est pourquoi l\u2019ouverture de l\u2019\u00e9conomie vers l\u2019ext\u00e9rieur dans les d\u00e9mocraties occidentales a souvent \u00e9t\u00e9 pr\u00e9par\u00e9e et accompagn\u00e9e par des mesures sociales de l\u2019\u00c9tat. Une assurance-ch\u00f4mage pour tous, des programmes publics de reconversion et une hausse des d\u00e9penses de formation se sont r\u00e9v\u00e9l\u00e9s \u00eatre des facteurs stabilisateurs tr\u00e8s importants. De nombreux pays ont r\u00e9ussi \u00e0 faire participer une majorit\u00e9 de la population aux avantages du march\u00e9 mondial gr\u00e2ce \u00e0 un \u00e9largissement de l\u2019offre de marchandises, \u00e0 la cr\u00e9ation d\u2019emplois et \u00e0 l\u2019am\u00e9lioration des prestations de l\u2019\u00c9tat.&#13;<br \/>\n&#13;<br \/>\nL\u2019impact des relations commerciales internationales sur l\u2019\u00e9conomie et sur les conditions de vie de la population d\u00e9pend donc fortement des conditions-cadres nationales\u00a0: une politique \u00e9conomique et sociale solide augmente les chances de larges couches de la population de profiter du commerce international et amortit les risques li\u00e9s \u00e0 l\u2019int\u00e9gration dans le commerce mondial. La participation politique et la l\u00e9gitimit\u00e9 d\u00e9mocratique sont \u00e9galement cruciales. Le succ\u00e8s actuel de d\u00e9magogues de haut vol et des mouvements populistes montrent combien il est important que toutes les couches de la population aient non seulement le sentiment \u00ab\u00a0d\u2019\u00eatre \u00e9conomiquement pourvues\u00a0\u00bb, mais qu\u2019elles font partie int\u00e9grante de la soci\u00e9t\u00e9 et ont leur mot \u00e0 dire.&#13;<\/p>\n<h2>Suivre des crit\u00e8res d\u2019\u00e9quit\u00e9<\/h2>\n<p>&#13;<br \/>\nQuelles r\u00e9ponses apporte l\u2019\u00e9thique \u00e9conomique\u00a0? Des crit\u00e8res d\u2019\u00e9quit\u00e9 g\u00e9n\u00e9ralisables sont clairement n\u00e9cessaires pour mieux r\u00e9partir les opportunit\u00e9s et les risques mentionn\u00e9s. Les accords commerciaux doivent les suivre.&#13;<br \/>\n&#13;<br \/>\nPremi\u00e8rement, une \u00e9quit\u00e9 des \u00e9changes s\u2019impose, ce qui signifie que tous les acteurs participent \u00e0 la prosp\u00e9rit\u00e9 \u00e9conomique g\u00e9n\u00e9rale selon leur prestation. Il s\u2019agit pour cela de renforcer le contr\u00f4le de la concurrence et de limiter les subventions.&#13;<br \/>\n&#13;<br \/>\nDeuxi\u00e8mement, l\u2019\u00e9quit\u00e9 des proc\u00e9dures requiert la plus grande transparence possible et une participation appropri\u00e9e des pays et des populations concern\u00e9s. En effet, l\u2019\u00e9quit\u00e9 des relations commerciales d\u00e9pend beaucoup de la mani\u00e8re dont les r\u00e8gles sont \u00e9tablies et de qui d\u00e9cide quand elles s\u2019appliquent ou non.&#13;<br \/>\n&#13;<br \/>\nTroisi\u00e8mement, les r\u00e8gles des accords commerciaux doivent laisser une marge de man\u0153uvre nationale pour garantir la s\u00e9curit\u00e9 sociale et un approvisionnement de base dans tout le pays. La s\u00e9curit\u00e9 alimentaire ainsi que l\u2019acc\u00e8s \u00e0 la formation et aux soins pour tous sont prioritaires. Cette \u00e9quit\u00e9 face aux besoins vise la satisfaction des besoins fondamentaux. On peut par exemple y parvenir dans les accords commerciaux par des dispositions appropri\u00e9es sur la protection de la vie, de la sant\u00e9 et d\u2019autres besoins fondamentaux.&#13;<br \/>\n&#13;<br \/>\nQuatri\u00e8mement, l\u2019\u00e9quit\u00e9 des chances justifie un traitement pr\u00e9f\u00e9rentiel temporaire des pays les plus pauvres pour les produits agricoles ou d\u2019autres biens essentiels \u00e0 l\u2019approvisionnement de base, donc une \u00ab\u00a0discrimination positive\u00a0\u00bb afin d\u2019assurer une concurrence \u00e9quitable lorsque les conditions de d\u00e9part sont in\u00e9gales. Le crit\u00e8re de l\u2019\u00e9quit\u00e9 interg\u00e9n\u00e9rationnelle affirme enfin que les accords commerciaux doivent \u00e9galement renforcer la cause environnementale, par exemple en alignant leurs r\u00e8gles sur les objectifs internationaux contraignants, comme les Objectifs de d\u00e9veloppement durable\u00a02030.&#13;<\/p>\n<h2>Exploiter la marge de man\u0153uvre<\/h2>\n<p>&#13;<br \/>\nCes crit\u00e8res indiquent seulement une direction g\u00e9n\u00e9rale. Ils requi\u00e8rent une analyse d\u00e9taill\u00e9e des probl\u00e8mes pour une mise en \u0153uvre concr\u00e8te. La r\u00e9f\u00e9rence \u00e0 de tels crit\u00e8res risque sinon de s\u2019\u00e9puiser en appels moraux non contraignants ou de conduire pr\u00e9matur\u00e9ment \u00e0 de fausses accusations.&#13;<br \/>\n&#13;<br \/>\nIl est cependant rare que les r\u00e9sultats de telles analyses, m\u00eame approfondies, soient clairs et nets, ce qui peut entra\u00eener sur le fond des divergences d\u2019opinions motiv\u00e9es, donc l\u00e9gitimes. Ce constat vaut aussi pour les actions \u00e0 mener, puisque diff\u00e9rentes options politiques d\u00e9coulent souvent de la m\u00eame analyse. Lorsqu\u2019il n\u2019est pas possible de trouver un accord, on devrait \u00e9galement r\u00e9fl\u00e9chir aux cons\u00e9quences de conflits commerciaux persistants ou au r\u00e9sultat qui serait obtenu sans int\u00e9grer les crit\u00e8res mentionn\u00e9s. Pour parvenir \u00e0 un avis fond\u00e9, il s\u2019agit non seulement de prendre en consid\u00e9ration les \u00e9ventuels effets n\u00e9gatifs de l\u2019accord, mais \u00e9galement les cons\u00e9quences de relations commerciales sans cadre r\u00e9glementaire.<\/p>","protected":false},"excerpt":{"rendered":"<p>De vifs d\u00e9bats souvent \u00e9motionnels et des contestations publiques accompagnent depuis longtemps les accords commerciaux. Pour leurs d\u00e9tracteurs, ces accords augmentent l\u2019in\u00e9galit\u00e9. Les normes de protection sociale, environnementale et des consommateurs seraient insuffisantes, et les accords sur les investissements ou les tribunaux arbitraux priv\u00e9s restreindraient la marge de man\u0153uvre des pays. Leurs partisans, eux, font [&hellip;]<\/p>","protected":false},"author":4884,"featured_media":19202,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"ep_exclude_from_search":false,"footnotes":""},"post__type":[81,83],"post_opinion":[],"post_serie":[],"post_content_category":[106],"post_content_subject":[],"acf":{"seco_author":4884,"seco_co_author":null,"author_override":"","seco_author_post_ocupation_year":"","seco_author_post_occupation_de":"Pr\u00e4sident der Hochschule f\u00fcr Philosophie M\u00fcnchen, Professor f\u00fcr Sozialwissenschaften und Wirtschaftsethik","seco_author_post_occupation_fr":"Pr\u00e9sident de l\u2019\u00c9cole sup\u00e9rieure de philosophie de Munich, professeur de sciences sociales et d\u2019\u00e9thique \u00e9conomique","seco_co_authors_post_ocupation":null,"short_title":"Des crit\u00e8res \u00e9thiques pour un ordre commercial mondial","post_lead":"Les accords commerciaux suscitent des critiques. Des crit\u00e8res \u00e9thiques aident \u00e0 \u00e9laborer des trait\u00e9s \u00e9quitables.","post_hero_image_description":"Les accords commerciaux sont \u00e9quitables lorsque les personnes moins qualifi\u00e9es peuvent \u00e9galement en profiter. Un cultivateur de mandarines en Alg\u00e9rie.","post_hero_image_description_copyright_de":"Keystone","post_hero_image_description_copyright_fr":"Keystone","post_references_literature":"","post_kasten":null,"post_notes_for_print":"","first_teaser_header_de":"","first_teaser_header_fr":"","first_teaser_text_de":"","first_teaser_text_fr":"","second_teaser_header_de":"","second_teaser_header_fr":"","second_teaser_text_de":"","second_teaser_text_fr":"","kseason_de":"","kseason_fr":"","post_in_pdf":134500,"main_focus":[156093,156872],"serie_email":null,"frontpage_slider_bild":134504,"artikel_bild-slider":null,"legacy_id":"87108","post_abstract":"Les adversaires des accords commerciaux mettent en garde contre la hausse des in\u00e9galit\u00e9s, la baisse des normes de protection sociale, environnementale et des consommateurs, ou encore un affaiblissement de la d\u00e9mocratie par la protection des investissements ou par des tribunaux arbitraux priv\u00e9s. Une large opposition a vu le jour, notamment \u00e0 cause de l\u2019opacit\u00e9 des processus de n\u00e9gociation et du manque d\u2019explication sur les objectifs de ces accords. Afin de la contrer et de montrer les avantages de\u00a0tels accords, une analyse objective des corr\u00e9lations entre des trait\u00e9s concrets, y compris les opportunit\u00e9s et les probl\u00e8mes qui y sont li\u00e9s, se r\u00e9v\u00e8le n\u00e9cessaire. Des crit\u00e8res \u00e9thiques indiquent la direction \u00e0 suivre pour \u00e9laborer de tels accords. L\u2019\u00e9valuation \u00e9thique doit toujours tenir compte du r\u00e9sultat en cas de non-accord et de menace de conflits commerciaux, voire de guerres \u00e9conomiques.","magazine_issue":"20190809","seco_author_reccomended_post":null,"redaktoren":[4127,0],"korrektor":4139,"planned_publication_date":"20190719","original_files":null,"external_release_for_author":"20190701","external_release_for_author_time":"23:30:00","link_for_external_authors":"https:\/\/dievolkswirtschaft.ch\/exedit\/5cd962641af4d"},"_links":{"self":[{"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/posts\/134497"}],"collection":[{"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/users\/4884"}],"replies":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/comments?post=134497"}],"version-history":[{"count":1,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/posts\/134497\/revisions"}],"predecessor-version":[{"id":187795,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/posts\/134497\/revisions\/187795"}],"acf:user":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/users\/4139"},{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/users\/0"},{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/users\/4127"},{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/users\/4884"}],"acf:post":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/main_focus_post\/156872"},{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/main_focus_post\/156093"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/media\/19202"}],"wp:attachment":[{"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/media?parent=134497"}],"wp:term":[{"taxonomy":"post__type","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/post__type?post=134497"},{"taxonomy":"post_opinion","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/post_opinion?post=134497"},{"taxonomy":"post_serie","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/post_serie?post=134497"},{"taxonomy":"post_content_category","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/post_content_category?post=134497"},{"taxonomy":"post_content_subject","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/post_content_subject?post=134497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}