{"id":137582,"date":"2018-04-24T10:30:51","date_gmt":"2018-04-24T10:30:51","guid":{"rendered":"https:\/\/dievolkswirtschaft.ch\/2018\/04\/comment-lagenda-mediatique-influence-celui-des-parlementairesa\/"},"modified":"2023-08-24T00:12:21","modified_gmt":"2023-08-23T22:12:21","slug":"comment-lagenda-mediatique-influence-celui-des-parlementairesa","status":"publish","type":"post","link":"https:\/\/dievolkswirtschaft.ch\/fr\/2018\/04\/comment-lagenda-mediatique-influence-celui-des-parlementairesa\/","title":{"rendered":"Comment l\u2019agenda m\u00e9diatique influence celui des parlementaires"},"content":{"rendered":"<p>Le niveau d\u2019attention que l\u2019on peut accorder aux diff\u00e9rents enjeux politiques n\u2019est pas illimit\u00e9. Confront\u00e9s \u00e0 l\u2019abondance des \u00e9v\u00e9nements, les journalistes sont oblig\u00e9s de s\u00e9lectionner ceux qui m\u00e9ritent selon eux une couverture m\u00e9diatique. Il en va de m\u00eame pour les politiciens, \u00e0 plus forte raison lorsqu\u2019ils sont, \u00e0 l\u2019instar des parlementaires suisses, des miliciens aux ressources limit\u00e9es. Le degr\u00e9 d\u2019attention accord\u00e9 aux divers enjeux d\u00e9finit l\u2019\u00ab\u2009agenda\u2009\u00bb d\u2019une organisation ou d\u2019une institution.&#13;<\/p>\n<h2><strong>Les enjeux des parlementaires et ceux des m\u00e9dias s\u2019entrecroisent<\/strong><\/h2>\n<p>&#13;<br \/>\nDans une \u00e9tude men\u00e9e pour le compte du Fonds national suisse de la recherche scientifique (FNS), nous nous sommes int\u00e9ress\u00e9s aux interactions entre agendas m\u00e9diatique et parlementaire. L\u2019<em>illustration<\/em> montre qu\u2019il existe globalement une forte correspondance entre le degr\u00e9 d\u2019attention accord\u00e9 aux enjeux trait\u00e9s dans la sph\u00e8re m\u00e9diatique et ceux soulev\u00e9s par le monde parlementaire.&#13;<\/p>\n<h3 class=\"text__graphic-title\"><strong>Degr\u00e9 d\u2019attention accord\u00e9 aux enjeux en fonction des interventions parlementaires et des articles qui leur sont consacr\u00e9s dans la NZZ<\/strong><\/h3>\n<p>&#13;<br \/>\n<div class='chart chart--normal' id='sciarini_fr_1'>\n\n<\/div>\n\n<script>\n$(function () {\n    $('#sciarini_fr_1').highcharts({\n  chart: {\n        type: 'bubble',\n        plotBorderWidth: 1,\n        zoomType: 'xy'\n    },\n\n    legend: {\n        enabled: false\n    },\n\n    title: {\n        text: ''\n    },\n\n    \n    xAxis: {\n        gridLineWidth: 1,\n        title: {\n            text: 'Articles de la NZZ'\n        },\n        labels: {\n            format: '{value}'\n        },\n        \n    },\n\n    yAxis: {\n        startOnTick: false,\n        endOnTick: false,\n        title: {\n            text: 'Interventions parlementaires '\n        },\n        labels: {\n            format: '{value}'\n        },\n        value: 65,\n        maxPadding: 0.2,\n       \n    },\n\n\n    plotOptions: {\n      bubble: {\n            minSize: 20,\n            maxSize:20\n        },\n        series: {\n            dataLabels: {\n                enabled: false,\n                format: '{point.name}'\n            },\n          \n        }\n    }, tooltip: {\n        useHTML: true,\n        headerFormat: '<table>',\n        pointFormat: '<h3>{point.country}<\/h3>' +\n            'Articles de la NZZ: {point.x}<br\/>' + \n            'Interventions parlementaires: {point.y}',\n           \n        footerFormat: '<\/table>',\n        followPointer: true\n    },\n\n    series: [{\n    \n        data: [\n          { x:7.5, y: 4.4, name: '\u00c9conomie', country: '\u00c9conomie' },\n            { x:3.8, y: 2.7, name: 'Droits et libert\u00e9s', country: 'Droits et libert\u00e9s' },\n           { x:5, y: 7.7, name: 'Sant\u00e9', country: 'Sant\u00e9' },\n           { x:3.3, y: 5.2, name: 'Agriculture', country: 'Agriculture' },\n            { x:4.5, y: 5.9, name: 'Travail et emploi', country: 'Travail et emploi' },\n           { x:5.3, y: 5.5, name: '\u00c9ducation, culture et sports', country: '\u00c9ducation, culture et sports' },\n            { x:1.9, y: 3.6, name: 'Environnement', country: 'Environnement' },\n            { x:2.3, y: 2.1, name: '\u00c9nergie', country: '\u00c9nergie' },\n            { x:4.5, y: 5.6, name: 'Immigration et int\u00e9gration', country: 'Immigration et int\u00e9gration' },\n            { x:11.1, y: 11.6, name: 'Transports', country: 'Transports' },\n            { x:4.2, y: 4.7, name:'Justice', country: 'Justice' },\n           { x:2, y: 2.8, name: 'Affaires sociales', country: 'Affaires sociales' },\n           { x:1.6, y: 2.3, name: 'Logement et d\u00e9veloppement urbain', country: 'Logement et d\u00e9veloppement urbain' },\n            { x:5.9, y: 6.2, name: 'Banques, finance et commerce interne', country: 'Banques, finance et commerce interne' },\n            { x:5.2, y: 4.9, name:'D\u00e9fense', country: 'D\u00e9fensed' },\n         { x:3.2, y: 4.1, name: 'Science, technologie et communication', country: 'Science, technologie et communication' }, \n           { x:1.2, y: 1.3, name:'Commerce ext\u00e9rieur', country: 'Commerce ext\u00e9rieur' }, \n           { x:8.4, y: 7.8, name: 'Politique \u00e9trang\u00e8re', country: 'Politique \u00e9trang\u00e8re' }, \n           { x:18.9, y: 11.1, name: '\u00c9tat', country: '\u00c9tat' }, \n           { x:0.2, y: 0.5, name: 'Terrains publics et ressources naturelles', country: 'Terrains publics et ressources naturelles' }\n        ]\n    },\n    {\n        type: 'line',\n        name: 'Regression Line',\n        data: [[0, 2], [19, 13]],\n        marker: {\n            enabled: false\n        },\n       \n        enableMouseTracking: false\n    }, ]\n\n});\n});\n\n\n\n<\/script>\n&#13;<br \/>\n&#13;<br \/>\n<span class=\"text__legend\">Remarque\u2009: nombre d\u2019interventions parlementaires\u2009: 9948\u2009; nombre d\u2019articles de la NZZ\u2009: 5044.<\/span>&#13;<br \/>\n&#13;<br \/>\n<span class=\"text__quelle--ground\">Source\u2009: FNS \/ La Vie \u00e9conomique<\/span>&#13;<br \/>\n&#13;<br \/>\nLes th\u00e8mes tr\u00e8s pr\u00e9sents dans les m\u00e9dias \u2014 comme les questions \u00e9tatiques, les transports ou la politique \u00e9trang\u00e8re \u2014 le sont aussi dans les interventions parlementaires. Comment expliquer cette correspondance\u2009? Les parlementaires s\u2019inspirent-ils de la couverture m\u00e9diatique pour d\u00e9finir les enjeux qu\u2019ils abordent dans les questions, interpellations, motions et initiatives parlementaires qu\u2019ils d\u00e9posent\u2009? Dans quelle mesure r\u00e9ussissent-ils de leur c\u00f4t\u00e9 \u00e0 influencer, par leurs interventions, le degr\u00e9 de couverture des diff\u00e9rents enjeux abord\u00e9s par les m\u00e9dias\u2009?&#13;<\/p>\n<h2><strong>Des r\u00e9sultats \u00e0 moduler selon le r\u00e9gime politique<\/strong><\/h2>\n<p>&#13;<br \/>\nLes r\u00e9sultats obtenus peuvent \u00eatre r\u00e9sum\u00e9s en trois points. Premi\u00e8rement, une analyse comparative conduite dans sept pays (dont la Suisse) en collaboration avec des chercheurs du projet international \u00ab\u2009Comparative Agendas Project\u2009\u00bb (voir <em>encadr\u00e9<\/em>) montre que l\u2019influence de l\u2019agenda m\u00e9diatique sur celui des parlementaires est plus importante que l\u2019inverse<a href=\"#footnote_1\" id=\"footnote-anchor_1\" class=\"inline-footnote__anchor\">[1]<\/a>. Cette \u00e9tude souligne \u00e9galement que les parlementaires de l\u2019opposition cherchent davantage leur inspiration dans les m\u00e9dias que ceux des partis gouvernementaux. Ces derniers sont en effet contraints par les contrats de coalition, ce qui les incite \u00e0 une certaine retenue. L\u2019opposition peut, en revanche, utiliser librement les informations fournies par les m\u00e9dias pour questionner et d\u00e9fier le gouvernement. Ce constat se v\u00e9rifie encore davantage dans les pays o\u00f9 le gouvernement est le fait d\u2019un seul parti, comme l\u2019Espagne ou le Royaume-Uni, que dans ceux r\u00e9gis par des coalitions, comme le Danemark ou les Pays-Bas.&#13;<br \/>\n&#13;<br \/>\nDeuxi\u00e8mement, nous nous sommes appliqu\u00e9s \u00e0 pr\u00e9ciser les modalit\u00e9s d\u2019interactions entre les agendas m\u00e9diatique et politique en Suisse<a href=\"#footnote_2\" id=\"footnote-anchor_2\" class=\"inline-footnote__anchor\">[2]<\/a>. La situation diff\u00e8re de celle d\u2019autres pays dont le gouvernement r\u00e9unit plusieurs partis. La premi\u00e8re raison r\u00e9side dans le fait que le Conseil f\u00e9d\u00e9ral est \u00e0 la fois tr\u00e8s inclusif \u00e0 l\u2019\u00e9gard des grands partis, qui y sont tous repr\u00e9sent\u00e9s, et tr\u00e8s exclusif pour les petits partis, qui n\u2019ont aucune chance d\u2019y acc\u00e9der. Autre particularit\u00e9 la d\u00e9mocratie directe, qui invite les parlementaires \u00e0 \u00eatre particuli\u00e8rement attentifs aux messages des m\u00e9dias et de l\u2019opinion publique. Nos analyses montrent qu\u2019en Suisse \u00e9galement, l\u2019agenda m\u00e9diatique influence davantage celui du Parlement, que le contraire. De plus, les enjeux couverts par les m\u00e9dias ont un plus grand impact sur le contenu des questions pos\u00e9es par les partis non gouvernementaux que sur l\u2019agenda des formations au pouvoir. Sur ce dernier plan, et c\u2019est un peu paradoxal, la Suisse s\u2019approche m\u00eame davantage des pays gouvern\u00e9s par un seul parti que de ceux r\u00e9gis par des coalitions.&#13;<br \/>\n&#13;<br \/>\nEnfin, l\u2019influence des m\u00e9dias varie selon qu\u2019ils s\u2019int\u00e9ressent \u00e0 des enjeux europ\u00e9anis\u00e9s ou non<a href=\"#footnote_3\" id=\"footnote-anchor_3\" class=\"inline-footnote__anchor\">[3]<\/a>. Ainsi, les parlementaires se servent davantage de l\u2019information fournie par les m\u00e9dias lorsque les articles portent sur des sujets de politique interne que lorsqu\u2019ils ont une forte connotation europ\u00e9enne. Ce r\u00e9sultat va de pair avec le fait que le pouvoir de cod\u00e9cision politique des parlementaires est plus limit\u00e9 dans le second cas que dans le premier. Pour la m\u00eame raison, lorsque les membres des Conseils utilisent les m\u00e9dias comme source d\u2019inspiration sur des sujets europ\u00e9ens, ils le font essentiellement dans le cadre de leurs activit\u00e9s de contr\u00f4le de l\u2019ex\u00e9cutif, au travers de questions et d\u2019interpellations. En politique interne, l\u2019agenda m\u00e9diatique influence \u00e9galement le contenu des interventions parlementaires susceptibles de d\u00e9clencher un processus d\u00e9cisionnel (postulats, motions et initiatives parlementaires).<\/p>\n<ol class=\"footnote\"><li id=\"footnote_1\" class=\"footnote--item\">Vliegenthart, Rens et al. \u00ab\u2009Do the media set the parliamentary agenda? A comparative study in seven countries\u00a0\u00bb, <em>European Journal of Political Research<\/em>, 55, 2016, pp. 283-301.&nbsp;<a href=\"#footnote-anchor_1\" class=\"inline-footnote__anchor hidden-print\">[<span class=\"icon-arrow-up\"><\/span>]<\/a><\/li><li id=\"footnote_2\" class=\"footnote--item\">Sciarini Pascal, Tresch Anke et Vliegenthart Rens,, <em>Partisan moderators of the relationships between media agenda and parliamentary agenda in the Netherlands and Switzerland<\/em>, Gen\u00e8ve, 2018 (non publi\u00e9), D\u00e9partement de science politique et de relations internationales.&nbsp;<a href=\"#footnote-anchor_2\" class=\"inline-footnote__anchor hidden-print\">[<span class=\"icon-arrow-up\"><\/span>]<\/a><\/li><li id=\"footnote_3\" class=\"footnote--item\">Sciarini Pascal et Tresch Anke, <em>The political agenda-setting power of the media: The Europeanisation nexus<\/em>, Gen\u00e8ve, 2018 (non publi\u00e9), D\u00e9partement de science politique et de relations internationales.&nbsp;<a href=\"#footnote-anchor_3\" class=\"inline-footnote__anchor hidden-print\">[<span class=\"icon-arrow-up\"><\/span>]<\/a><\/li><\/ol>","protected":false},"excerpt":{"rendered":"<p>Le niveau d\u2019attention que l\u2019on peut accorder aux diff\u00e9rents enjeux politiques n\u2019est pas illimit\u00e9. Confront\u00e9s \u00e0 l\u2019abondance des \u00e9v\u00e9nements, les journalistes sont oblig\u00e9s de s\u00e9lectionner ceux qui m\u00e9ritent selon eux une couverture m\u00e9diatique. Il en va de m\u00eame pour les politiciens, \u00e0 plus forte raison lorsqu\u2019ils sont, \u00e0 l\u2019instar des parlementaires suisses, des miliciens aux [&hellip;]<\/p>","protected":false},"author":4152,"featured_media":22797,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"ep_exclude_from_search":false,"footnotes":""},"post__type":[81,83],"post_opinion":[],"post_serie":[],"post_content_category":[105],"post_content_subject":[],"acf":{"seco_author":4152,"seco_co_author":[4665,0],"author_override":"","seco_author_post_ocupation_year":"","seco_author_post_occupation_de":"Professor f\u00fcr Schweizer Politik am Departement f\u00fcr Politikwissenschaft und Internationale Beziehungen, Universit\u00e4t Genf","seco_author_post_occupation_fr":"Professeur de politique suisse au d\u00e9partement de science politique et relations internationales, universit\u00e9 de Gen\u00e8ve","seco_co_authors_post_ocupation":[{"seco_co_author":4665,"seco_co_author_post_occupation_year":"","seco_co_author_post_occupation_de":"Assoziierte Professorin, Fakult\u00e4t f\u00fcr Sozial- und Politikwissenschaften sowie Fondation suisse pour la recherche en sciences sociales (Fors), Universit\u00e4t Lausanne","seco_co_author_post_occupation_fr":"Professeure associ\u00e9e \u00e0 la Facult\u00e9 des sciences sociales et politiques de m\u00eame qu\u2019\u00e0 la Fondation suisse pour la recherche en sciences sociales (Fors), universit\u00e9 de Lausanne"}],"short_title":"Agenda m\u00e9diatique et parlementaire","post_lead":"Les m\u00e9dias et le monde politique sont \u00e9troitement li\u00e9s. La question est de savoir qui influence qui, et dans quelles proportions.","post_hero_image_description":"Pour les parlementaires, la d\u00e9mocratie directe donne une grande importance \u00e0 l'opinion publique. Andrea Caroni, conseiller aux \u00c9tats PLR au palais f\u00e9d\u00e9ral.","post_hero_image_description_copyright_de":"Keystone","post_hero_image_description_copyright_fr":"","post_references_literature":"","post_kasten":[{"kasten_title":"Le \u00ab\u2009Comparative Agendas Project\u2009\u00bb","kasten_box":"Lanc\u00e9 par les \u00c9tats-Unis, le \u00ab\u2009<a href=\"http:\/\/www.comparativeagendas.net\/\">Comparative Agendas Project<\/a>\u2009\u00bb, un instrument de comparaison des agendas, r\u00e9unit de nombreux pays europ\u00e9ens (Allemagne, Espagne, France, Danemark, Italie, Pays-Bas, Suisse, etc.). Son atout majeur est que l\u2019agenda th\u00e9matique des partis, des institutions politiques et des m\u00e9dias est syst\u00e9matiquement cod\u00e9 \u00e0 l\u2019aide d\u2019une m\u00eame grille comportant 20\u00a0enjeux politiques (par exemple la sant\u00e9, l\u2019immigration, les affaires internationales) et plus de 250\u00a0sous-enjeux. Cette grille commune facilite la comparaison internationale des agendas. Les donn\u00e9es utilis\u00e9es dans cet article couvrent les ann\u00e9es\u00a01995 \u00e0\u00a02003. Nous avons cod\u00e9 tous les articles de la premi\u00e8re page et de la premi\u00e8re page nationale du quotidien zurichois <em>Neue Z\u00fcrcher Zeitung (NZZ)<\/em>, un jour sur deux, ce qui correspond \u00e0 pr\u00e8s de 10\u2009000\u00a0articles et 10\u2009000\u00a0interventions parlementaires (questions, interpellations, postulats, motions et initiatives parlementaires)."}],"post_notes_for_print":"","first_teaser_header_de":"","first_teaser_header_fr":"","first_teaser_text_de":"","first_teaser_text_fr":"","second_teaser_header_de":"","second_teaser_header_fr":"","second_teaser_text_de":"","second_teaser_text_fr":"","kseason_de":"","kseason_fr":"","post_in_pdf":137585,"main_focus":[156261,156992],"serie_email":null,"frontpage_slider_bild":137589,"artikel_bild-slider":null,"legacy_id":"77127","post_abstract":"Les parlementaires utilisent les m\u00e9dias pour s\u2019informer sur les besoins de la soci\u00e9t\u00e9 et pour obtenir des informations n\u00e9cessaires \u00e0 l\u2019exercice de leurs fonctions l\u00e9gislative et de contr\u00f4le. \u00c0 l\u2019inverse, ils se servent des m\u00e9dias pour rendre visibles leurs activit\u00e9s et convaincre l\u2019opinion publique. Une \u00e9tude men\u00e9e pour le compte du Fonds national suisse de la recherche scientifique (FNS) s\u2019est int\u00e9ress\u00e9e aux interactions entre agendas m\u00e9diatique et parlementaire. Elle sugg\u00e8re, avec d\u2019autres, que les m\u00e9dias influencent davantage les parlementaires qu\u2019inversement. L\u2019intensit\u00e9 varie toutefois selon le pays, le type de parti, l\u2019enjeu et l\u2019activit\u00e9 parlementaire.","magazine_issue":"20180501","seco_author_reccomended_post":null,"redaktoren":[4127,0],"korrektor":4139,"planned_publication_date":"20180425","original_files":null,"external_release_for_author":"19700101","external_release_for_author_time":"00:00:00","link_for_external_authors":"https:\/\/dievolkswirtschaft.ch\/exedit\/5a9d2418b1139"},"_links":{"self":[{"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/posts\/137582"}],"collection":[{"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/users\/4152"}],"replies":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/comments?post=137582"}],"version-history":[{"count":1,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/posts\/137582\/revisions"}],"predecessor-version":[{"id":188069,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/posts\/137582\/revisions\/188069"}],"acf:user":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/users\/4139"},{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/users\/4127"},{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/users\/0"},{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/users\/4665"},{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/users\/4152"}],"acf:post":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/main_focus_post\/156992"},{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/main_focus_post\/156261"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/media\/22797"}],"wp:attachment":[{"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/media?parent=137582"}],"wp:term":[{"taxonomy":"post__type","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/post__type?post=137582"},{"taxonomy":"post_opinion","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/post_opinion?post=137582"},{"taxonomy":"post_serie","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/post_serie?post=137582"},{"taxonomy":"post_content_category","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/post_content_category?post=137582"},{"taxonomy":"post_content_subject","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/post_content_subject?post=137582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}