{"id":137640,"date":"2018-04-24T10:20:59","date_gmt":"2018-04-24T10:20:59","guid":{"rendered":"https:\/\/dievolkswirtschaft.ch\/2018\/04\/le-marche-numerique-intensifie-la-concurrence-des-contenusa\/"},"modified":"2023-08-24T00:12:30","modified_gmt":"2023-08-23T22:12:30","slug":"le-marche-numerique-intensifie-la-concurrence-des-contenusa","status":"publish","type":"post","link":"https:\/\/dievolkswirtschaft.ch\/fr\/2018\/04\/le-marche-numerique-intensifie-la-concurrence-des-contenusa\/","title":{"rendered":"Le march\u00e9 num\u00e9rique intensifie la concurrence des contenus"},"content":{"rendered":"<p>L\u2019histoire se r\u00e9p\u00e8te. La large diffusion des connaissances n\u00e9e de l\u2019invention de l\u2019imprimerie a mis un terme \u00e0 la sombre \u00e9poque des croyances. Elle a ouvert la voie \u00e0 l\u2019\u00e8re moderne, aux Lumi\u00e8res et au capitalisme fond\u00e9 sur l\u2019offre et la demande. Il y a lieu de supposer que la deuxi\u00e8me r\u00e9volution de l\u2019information, que nous traversons actuellement gr\u00e2ce \u00e0 la num\u00e9risation, laissera \u00e9galement une empreinte historique.&#13;<br \/>\n&#13;<br \/>\nNous le remarquons tous dans notre quotidien\u00a0: des r\u00e8gles que l\u2019on pensait immuables doivent \u00eatre red\u00e9finies. L\u2019\u00e9poque o\u00f9 le savoir \u00e9tait synonyme de pouvoir et o\u00f9 une information d\u2019avance repr\u00e9sentait un avantage commercial ind\u00e9niable touche \u00e0 sa fin. Un comparateur de prix identifie aujourd\u2019hui, pour tout un chacun, la moins ch\u00e8re des offres identiques et une majorit\u00e9 de la population peut d\u00e9sormais s\u2019arroger ce bon mot d\u2019\u00e9l\u00e8ve\u00a0: \u00ab\u00a0Savoir, c\u2019est comme googliser, mais grave\u00a0!\u00a0\u00bb&#13;<br \/>\n&#13;<br \/>\nAvant Gutenberg, un livre co\u00fbtait autant qu\u2019un h\u00f4tel particulier. De nos jours, le prix d\u2019un journal \u00e9quivaut \u00e0 celui d\u2019un caf\u00e9 et la plupart des gens trouvent m\u00eame cela excessif. Le journaliste am\u00e9ricain Jeff Jarvis r\u00e9sume ainsi la situation\u00a0: \u00ab\u00a0Aujourd\u2019hui, l\u2019information est une denr\u00e9e que l\u2019on ne peut plus poss\u00e9der, car elle est trop \u00e9ph\u00e9m\u00e8re.\u00a0\u00bb&#13;<\/p>\n<h2><strong>\u00c0 chacun sa d\u00e9finition de la pertinence<\/strong><\/h2>\n<p>&#13;<br \/>\nActuellement, si je d\u00e9sire savoir quelque chose, je sais comment trouver l\u2019information ou, mieux encore, c\u2019est l\u2019information qui me trouve et identifie mes int\u00e9r\u00eats. Cela suscite toutefois certaines questions\u00a0: \u00e0 quels contenus vais-je m\u2019ouvrir\u00a0? Lesquels sont cr\u00e9dibles\u00a0? Lesquels sont importants\u00a0?&#13;<br \/>\n&#13;<br \/>\nTel est le dilemme auquel notre soci\u00e9t\u00e9 des m\u00e9dias est d\u00e9sormais confront\u00e9e. Le matraquage informationnel g\u00e9n\u00e8re la confusion et induit une perte d\u2019autorit\u00e9. Aux marques m\u00e9diatiques classiques, on oppose de plus en plus le \u00ab\u00a0combat rapproch\u00e9\u00a0\u00bb que se livrent directement les acteurs de la communication sur les r\u00e9seaux sociaux.&#13;<br \/>\n&#13;<br \/>\nPersonne ne consulte Internet de fond en comble. Vu le d\u00e9luge d\u2019informations, chacun s\u2019est mis \u00e0 d\u00e9finir soi-m\u00eame la pertinence des contenus, un exercice dans lequel le lieu de domicile ou les int\u00e9r\u00eats propres \u2013 par exemple \u2013 d\u00e9terminent le degr\u00e9 de pertinence individuelle d\u2019une information. Il s\u2019agit aussi de relativiser les donn\u00e9es\u00a0: l\u2019information \u00e9mane-t-elle de son auteur ou s\u2019agit-il d\u2019un troisi\u00e8me r\u00e9sum\u00e9 ou d\u2019une ni\u00e8me traduction\u00a0? Il est en outre d\u00e9cisif qu\u2019une information soit cr\u00e9dible ou non. La marque et la transparence d\u2019un produit m\u00e9diatique jouent \u00e0 cet \u00e9gard un r\u00f4le non n\u00e9gligeable. Pour beaucoup, enfin, les th\u00e8mes de discussion de leurs propres amis sont plus importants que le prochain ouragan en Floride \u00e9voqu\u00e9 par le pr\u00e9sentateur du journal t\u00e9l\u00e9vis\u00e9.&#13;<br \/>\n&#13;<br \/>\nLes contenus qui m\u2019int\u00e9ressent me parviennent sous forme de liens recommand\u00e9s par des amis, par des algorithmes et par des auxiliaires toujours plus intelligents comme \u00ab\u00a0Alexa\u00a0\u00bb d\u2019Amazon ou \u00ab\u00a0Google home\u00a0\u00bb. Ces assistants num\u00e9riques n\u2019attirent pas une sympathie syst\u00e9matique, mais prouvent \u00e0 quel point il nous appara\u00eetra bient\u00f4t absurde de songer \u00e0 payer l\u2019information.&#13;<br \/>\n&#13;<br \/>\n\u00ab\u00a0Alexa, arr\u00eate de me sugg\u00e9rer des articles ennuyeux, payants de surcro\u00eet, ou je te jette par la fen\u00eatre\u00a0!\u00a0\u00bb Tel est le genre de phrase que nous pourrions nous surprendre \u00e0 prononcer dans un avenir pas si lointain. Les informations abondent, et mon attention constitue un bien extr\u00eamement pr\u00e9cieux. Ces informations sont de plus en plus adapt\u00e9es \u00e0 mon profil, ce qui les rend plus pertinentes pour moi et tr\u00e8s pr\u00e9cieuses pour qui sait les connecter les unes aux autres. Cette observation ne s\u2019applique pas qu\u2019aux m\u00e9dias, elle vaut aussi pour d\u2019autres domaines\u00a0: Amazon, l\u2019exploitant d\u2019Alexa, est en passe de p\u00e9n\u00e9trer sur le march\u00e9 de l\u2019assurance. Or, Alexa sait pr\u00e9cis\u00e9ment \u00e0 quelle fr\u00e9quence je pratique la course \u00e0 pied.&#13;<\/p>\n<h2><strong>Facebook n\u2019est pas une plateforme d\u2019information ad\u00e9quate<\/strong><\/h2>\n<p>&#13;<br \/>\nCette interconnexion globale des donn\u00e9es rec\u00e8le un \u00e9norme potentiel de conflits, ce qui a le don de braquer la classe politique dans plusieurs pays. Les tentatives de l\u00e9gif\u00e9rer sur les r\u00e9seaux sociaux (\u00e0 l\u2019image de la \u00ab\u00a0Netzwerkdurchsetzungsgesetz\u00a0\u00bb en Allemagne<a href=\"#footnote_1\" id=\"footnote-anchor_1\" class=\"inline-footnote__anchor\">[1]<\/a>), sont maladroites et peu ad\u00e9quates. Ces tentatives montrent toutefois que l\u2019on a \u2013 enfin\u00a0! \u2013 reconnu que Facebook et les autres r\u00e9seaux sociaux ne constituent pas le support d\u2019une information neutre.&#13;<br \/>\n&#13;<br \/>\nFacebook structure les habitants d\u2019un pays selon les besoins des groupes cibles constitu\u00e9s par ses annonceurs. Du point de vue soci\u00e9tal, cela a des cons\u00e9quences importantes\u00a0: Facebook traite la complexit\u00e9 de la soci\u00e9t\u00e9 \u00e0 la mani\u00e8re dont l\u2019artiste Ursus Wehrli consid\u00e8re les objets \u00e0 organiser dans son opuscule <em>Kunst aufr\u00e4umen<\/em>. Les r\u00e9sultats obtenus par Wehrli sont totalement absurdes et fort amusants. L\u2019avenir dira si la soci\u00e9t\u00e9 organis\u00e9e en groupes cibles sera aussi plaisante. Nous l\u2019\u00e9prouvons actuellement dans la vaste exp\u00e9rience \u00e0 laquelle nous participons en mati\u00e8re de r\u00e9seaux sociaux. L\u2019issue est pour l\u2019heure incertaine.&#13;<br \/>\n&#13;<br \/>\nLes plateformes constituent d\u00e9sormais des infrastructures si importantes que l\u2019\u00e9conomiste allemand Nick Srnicek propose d\u00e9j\u00e0, dans son livre <em>Platform Capitalism<\/em>, de r\u00e9fl\u00e9chir \u00e0 une nationalisation. Seulement, ces r\u00e9seaux \u00e9tant mondialis\u00e9s, une telle mesure n\u2019est plus aussi simple qu\u2019\u00e0 l\u2019\u00e9poque o\u00f9 les chemins de fer et les compagnies d\u2019\u00e9lectricit\u00e9 priv\u00e9s devinrent \u00e0 ce point essentiels pour la soci\u00e9t\u00e9 que les \u00c9tats les transf\u00e9r\u00e8rent \u00e0 la collectivit\u00e9. Ces plateformes aujourd\u2019hui universellement dominantes, dont le principe est \u00ab\u00a0le gagnant emporte toute la mise\u00a0\u00bb, laissent toutefois subsister un espoir \u00e9conomique. Il se trouve dans la d\u00e9centralisation.&#13;<\/p>\n<h2><strong>Un syst\u00e8me m\u00e9diatique d\u00e9centralis\u00e9 <\/strong><\/h2>\n<p>&#13;<br \/>\nLes cha\u00eenes de blocs et les nouveaux syst\u00e8mes de diffusion d\u00e9centralis\u00e9s, comme Ethereum, ne resteront pas longtemps aux portes de l\u2019\u00e9conomie m\u00e9diatique. Ces nouvelles technologies permettront de prendre part \u00e0 la cr\u00e9ation de valeur sur un mode d\u00e9centralis\u00e9 et ouvriront la voie \u00e0 des mod\u00e8les d\u2019activit\u00e9 dont l\u2019\u00e9quilibre sera sensiblement affin\u00e9. Refind, la jeune pousse d\u00e9velopp\u00e9e par l\u2019entrepreneur b\u00e2lois Dominik Grolimund, en t\u00e9moigne actuellement.&#13;<br \/>\n&#13;<br \/>\nSur la plateforme m\u00e9diatique Refind, l\u2019utilisateur est r\u00e9compens\u00e9 pour le temps qu\u2019il y a investi. Les contenus du monde entier sont gratuits, mais quiconque invite des amis ou partage des articles re\u00e7oit entre 20 et 30 pi\u00e8ces virtuelles. Ce n\u2019est pas de la cryptomonnaie, mais des \u00ab\u00a0jetons\u00a0\u00bb dont le nombre a vite atteint le milliard. L\u2019exemple de Refind montre comment pourrait fonctionner un syst\u00e8me de cr\u00e9ation de valeur d\u00e9centralis\u00e9 beaucoup plus diff\u00e9renci\u00e9\u00a0: quiconque a \u00e9crit un article re\u00e7oit de l\u2019argent, de m\u00eame que les administrateurs qui ont partag\u00e9 et diffus\u00e9 les contenus.&#13;<br \/>\n&#13;<br \/>\nNous le savons depuis longtemps\u00a0: la \u00ab\u00a0centralisation\u00a0\u00bb n\u2019a aucune chance contre la \u00ab\u00a0d\u00e9centralisation\u00a0\u00bb. Wikip\u00e9dia a supplant\u00e9 les encyclop\u00e9dies traditionnelles et les plateformes apparemment toutes-puissantes aujourd\u2019hui ne pourront gu\u00e8re rivaliser \u00e0 long terme avec les m\u00e9canismes \u00e9conomiques d\u00e9centralis\u00e9s. Les articles et les int\u00e9r\u00eats se rencontrent de plus en plus \u2013 m\u00eame sans interm\u00e9diaires &#8211; gr\u00e2ce \u00e0 l\u2019intelligence artificielle et aux syst\u00e8mes apprenants. La politique de Facebook, qui n\u2019autorise pas l\u2019exportation de liens, para\u00eetra bient\u00f4t aussi novatrice que les verrous d\u2019acc\u00e8s payants (\u00ab\u00a0paywalls\u00a0\u00bb) des maisons d\u2019\u00e9dition. Cependant, qui produira les contenus si le journalisme n\u2019en vaut plus la peine\u00a0?&#13;<\/p>\n<h2><strong>R\u00e9organiser la concurrence des contenus<\/strong><\/h2>\n<p>&#13;<br \/>\nSi plus personne ne croit vraiment au journal d\u2019information classique, le journalisme reste n\u00e9anmoins n\u00e9cessaire. Nous observons actuellement comment la production d\u2019informations se transforme en un march\u00e9 du don. Le milliardaire Christoph Blocher finance g\u00e9n\u00e9reusement la <em>Weltwoche<\/em> et la <em>Basler Zeitung<\/em>, tandis que les \u00e9diteurs du nouveau magazine suisse en ligne <em>Republik<\/em> font la queue au sein du collectif pour pouvoir verser leur contribution individuelle. En d\u00e9finitive, le motif est le m\u00eame dans les deux cas\u00a0: la conviction et l\u2019identification au produit.&#13;<br \/>\n&#13;<br \/>\nOr, une sc\u00e8ne m\u00e9diatique p\u00e9renne ne se construit pas uniquement \u00e0 l\u2019aide de dons. Une comparaison avec la branche des transports permet de comprendre comment le journalisme peut se pratiquer en Suisse sur une base ind\u00e9pendante et concurrentielle. Aucune entreprise de transport helv\u00e9tique ne gagnerait de l\u2019argent s\u2019il n\u2019y avait qu\u2019une seule autoroute priv\u00e9e \u00e0 disposition et si son propri\u00e9taire, \u00e0 l\u2019instar de Facebook aujourd\u2019hui, modifiait continuellement les prix, la largeur des voies et les r\u00e8gles de la circulation sans aucun pr\u00e9avis.&#13;<br \/>\n&#13;<br \/>\nLa t\u00e2che essentielle \u2013 en l\u2019occurrence le transport \u2013 requiert une infrastructure commune et un certain nombre de r\u00e8gles respect\u00e9es par les parties prenantes. Une telle base n\u2019inciterait personne \u00e0 pr\u00e9tendre que la concurrence est absente de la branche des transports ou qu\u2019elle y est insuffisante. Assur\u00e9ment, il ne viendrait jamais \u00e0 l&#8217;esprit d&#8217;un chauffeur de camion de construire lui-m\u00eame une route pour contr\u00f4ler ses concurrents. Les co\u00fbts de l\u2019infrastructure commune sont financ\u00e9s conjointement par tous, de sorte que chacun peut se vouer \u00e0 l\u2019activit\u00e9 centrale de son entreprise\u00a0: fournir des prestations de transport au b\u00e9n\u00e9fice de tous, en toute ind\u00e9pendance et dans un contexte de vive concurrence.&#13;<br \/>\n&#13;<br \/>\nL\u2019\u00e8re des \u00e9diteurs termin\u00e9e, le journalisme se trouve aujourd\u2019hui au seuil de cette nouvelle \u00e9tape. Diverses offres d\u2019infrastructures techniques et de contenus (plut\u00f4t qu\u2019une seule) sont n\u00e9cessaires. Telle est la condition sine qua non pour qu\u2019apparaissent de nouveaux m\u00e9dias ind\u00e9pendants et pour que le paysage m\u00e9diatique reste diversifi\u00e9. Dans cet espace num\u00e9rique commun, les frais g\u00e9n\u00e9raux de chaque acteur seront fortement r\u00e9duits et les moyens ad\u00e9quats seront enfin disponibles pour assurer la diffusion de l\u2019information vers les int\u00e9ress\u00e9s. Il faudrait aussi que les contenus d\u00e9j\u00e0 produits et financ\u00e9s de la SSR, tout comme les services de base d\u2019une agence de presse probablement bient\u00f4t subventionn\u00e9e par des fonds publics, soient accessibles \u00e0 tous.&#13;<br \/>\n&#13;<br \/>\nCette base avantageuse en mati\u00e8re de co\u00fbts permettra par exemple de d\u00e9velopper \u00e0 nouveau des titres locaux ou r\u00e9gionaux. L\u2019aide directe consacr\u00e9e au journalisme en ligne, qui s\u2019esquisse dans la nouvelle loi sur les m\u00e9dias, sera nettement plus efficace, puisque les subventions soutiendront directement les contenus et le profil de la marque plut\u00f4t que le d\u00e9veloppement d\u2019un canal.&#13;<br \/>\n&#13;<br \/>\nLa demande d\u2019infrastructure commune est d\u00e9j\u00e0 comprise dans la proposition de la Commission f\u00e9d\u00e9rale des m\u00e9dias. Les \u00e9diteurs et leurs lobbyistes veulent assur\u00e9ment tout hormis des concurrents suppl\u00e9mentaires. Ils n&#8217;ont toutefois pas plus le pouvoir de s&#8217;opposer \u00e0 la conception logique d\u2019une infrastructure commune que Facebook ou d\u2019autres plateformes de l\u2019\u00e9conomie de la cha\u00eene de blocs d\u00e9centralis\u00e9e.<\/p>\n<ol class=\"footnote\"><li id=\"footnote_1\" class=\"footnote--item\">En vertu de la loi allemande d\u2019application du droit aux r\u00e9seaux sociaux (\u00ab\u00a0Netzwerkdurchsetzungsgesetz\u00a0\u00bb), les exploitants de r\u00e9seaux sociaux sont tenus de supprimer les contenus illicites dans les 24\u00a0heures.&nbsp;<a href=\"#footnote-anchor_1\" class=\"inline-footnote__anchor hidden-print\">[<span class=\"icon-arrow-up\"><\/span>]<\/a><\/li><\/ol>","protected":false},"excerpt":{"rendered":"<p>L\u2019histoire se r\u00e9p\u00e8te. La large diffusion des connaissances n\u00e9e de l\u2019invention de l\u2019imprimerie a mis un terme \u00e0 la sombre \u00e9poque des croyances. Elle a ouvert la voie \u00e0 l\u2019\u00e8re moderne, aux Lumi\u00e8res et au capitalisme fond\u00e9 sur l\u2019offre et la demande. Il y a lieu de supposer que la deuxi\u00e8me r\u00e9volution de l\u2019information, que [&hellip;]<\/p>","protected":false},"author":4656,"featured_media":22869,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"ep_exclude_from_search":false,"footnotes":""},"post__type":[83],"post_opinion":[],"post_serie":[],"post_content_category":[105],"post_content_subject":[],"acf":{"seco_author":4656,"seco_co_author":null,"author_override":"","seco_author_post_ocupation_year":"","seco_author_post_occupation_de":"Gr\u00fcnder der Open-Source-Plattform Wepublish, Partner beim Beratungsunternehmen DasNetz.ch und ehemaliger Chefredaktor des Newsportals Watson, Z\u00fcrich","seco_author_post_occupation_fr":"Fondateur de la plateforme source ouverte \u00ab Wepublish \u00bb, partenaire de la soci\u00e9t\u00e9 de conseil DasNetz.ch et ancien r\u00e9dacteur en chef du site d\u2019information \u00ab Watson \u00bb, Zurich","seco_co_authors_post_ocupation":null,"short_title":"La concurrence des contenus s'intensifie","post_lead":"Internet nous l\u2019apprend : la d\u00e9centralisation l\u2019emporte sur la centralisation. Tel a \u00e9t\u00e9 le cas de Wikip\u00e9dia face aux dictionnaires encyclop\u00e9diques traditionnels et tel sera le cas de Facebook face au reste du monde. Au moment m\u00eame o\u00f9 les anciennes maisons de presse ont compris l\u2019\u00e9conomie de plateforme, les acteurs des cha\u00eenes de blocs annoncent leur derni\u00e8re heure. Tant mieux !","post_hero_image_description":"L'euphorie des d\u00e9buts s'est dissip\u00e9e. Facebook est-il une infrastructure adapt\u00e9e \u00e0 l'information ?","post_hero_image_description_copyright_de":"Keystone","post_hero_image_description_copyright_fr":"","post_references_literature":"","post_kasten":null,"post_notes_for_print":"","first_teaser_header_de":"","first_teaser_header_fr":"","first_teaser_text_de":"","first_teaser_text_fr":"","second_teaser_header_de":"","second_teaser_header_fr":"","second_teaser_text_de":"","second_teaser_text_fr":"","kseason_de":"","kseason_fr":"","post_in_pdf":137643,"main_focus":[156261,156992],"serie_email":null,"frontpage_slider_bild":137647,"artikel_bild-slider":null,"legacy_id":"76956","post_abstract":"Gr\u00e2ce \u00e0 la num\u00e9risation, l\u2019information devient de plus en plus accessible et bon march\u00e9. Le journalisme ne fait plus recette et l\u2019ancien r\u00e9gime m\u00e9diatique se dissout sous nos yeux. Au lieu de s\u2019en remettre \u00e0 des plateformes inad\u00e9quates telles que Facebook, l\u2019\u00e9conomie m\u00e9diatique de l\u2019avenir devrait \u2013 dans de nombreux domaines \u2013 miser sur la coop\u00e9ration et sur le fonctionnement d\u00e9centralis\u00e9 des cha\u00eenes de blocs. \u00c0 cet \u00e9gard, l\u2019aide aux m\u00e9dias pourrait constituer un levier tr\u00e8s efficace pour stimuler la concurrence ind\u00e9pendante entre les contenus journalistiques qui cherchent \u00e0 capter notre attention. Or, les \u00e9diteurs s\u2019y opposent.","magazine_issue":"20180501","seco_author_reccomended_post":null,"redaktoren":[3988,0],"korrektor":4139,"planned_publication_date":"20180425","original_files":null,"external_release_for_author":"20180329","external_release_for_author_time":"00:00:00","link_for_external_authors":"https:\/\/dievolkswirtschaft.ch\/exedit\/5a9505754601c"},"_links":{"self":[{"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/posts\/137640"}],"collection":[{"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/users\/4656"}],"replies":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/comments?post=137640"}],"version-history":[{"count":1,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/posts\/137640\/revisions"}],"predecessor-version":[{"id":188072,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/posts\/137640\/revisions\/188072"}],"acf:user":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/users\/4139"},{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/users\/0"},{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/users\/3988"},{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/users\/4656"}],"acf:post":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/main_focus_post\/156992"},{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/main_focus_post\/156261"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/media\/22869"}],"wp:attachment":[{"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/media?parent=137640"}],"wp:term":[{"taxonomy":"post__type","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/post__type?post=137640"},{"taxonomy":"post_opinion","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/post_opinion?post=137640"},{"taxonomy":"post_serie","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/post_serie?post=137640"},{"taxonomy":"post_content_category","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/post_content_category?post=137640"},{"taxonomy":"post_content_subject","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/post_content_subject?post=137640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}