{"id":137693,"date":"2018-04-16T08:40:01","date_gmt":"2018-04-16T08:40:01","guid":{"rendered":"https:\/\/dievolkswirtschaft.ch\/2018\/04\/spillmann2018-5\/"},"modified":"2023-08-24T00:11:54","modified_gmt":"2023-08-23T22:11:54","slug":"spillmann2018-5","status":"publish","type":"post","link":"https:\/\/dievolkswirtschaft.ch\/fr\/2018\/04\/spillmann2018-5\/","title":{"rendered":"Davantage de service public sur le march\u00e9 des m\u00e9dias, svp&nbsp;!"},"content":{"rendered":"<p>La bataille est termin\u00e9e, le vainqueur est connu\u00a0: la radiot\u00e9l\u00e9vision publique pourra continuer d\u2019\u00e9mettre en Suisse. Pourtant, le net rejet de l\u2019initiative \u00ab\u00a0No-Billag\u00a0\u00bb ne saurait \u00eatre interpr\u00e9t\u00e9 comme un encouragement \u00e0 continuer comme si rien ne s\u2019\u00e9tait pass\u00e9<a href=\"#footnote_1\" id=\"footnote-anchor_1\" class=\"inline-footnote__anchor\">[1]<\/a>. La votation avait uniquement pour objet le financement de la radiot\u00e9l\u00e9vision publique et des cha\u00eenes priv\u00e9es concessionnaires. Nous n\u2019avons pu nous exprimer ni sur les limites de la desserte m\u00e9diatique de base assur\u00e9e par les pouvoirs publics, ni sur l\u2019opportunit\u00e9 de cette desserte \u00e0 l\u2019\u00e8re num\u00e9rique. Or c\u2019est v\u00e9ritablement sur ce dernier point qu\u2019une discussion sur l\u2019avenir du service public devrait s\u2019engager.&#13;<\/p>\n<h2><strong>Le journal quotidien&nbsp;: un mod\u00e8le d\u00e9pass\u00e9<\/strong><\/h2>\n<p>&#13;<br \/>\nLa question fondamentale consiste \u00e0 savoir comment s\u2019assurer que la soci\u00e9t\u00e9 reste inform\u00e9e \u00e0 l\u2019avenir, condition indispensable pour l\u2019exercice de la d\u00e9mocratie. \u00c0 cet effet, la Suisse aura sans doute besoin de davantage de m\u00e9dias relevant du service public \u2013 et non l\u2019inverse\u00a0!&#13;<br \/>\n&#13;<br \/>\nPourquoi cela\u00a0? D\u2019abord, parce que le march\u00e9 des m\u00e9dias grand public va subir de nouvelles concentrations au d\u00e9triment des r\u00e9dactions autonomes. Les quotidiens payants perdront de plus en plus de lecteurs et leur tirage diminuera\u00a0; le mod\u00e8le des produits imprim\u00e9s est condamn\u00e9. Il est vrai qu\u2019en face, les offres num\u00e9ris\u00e9es augmentent, mais leur refinancement reste insuffisant, malgr\u00e9 le fait que le nombre d\u2019utilisateurs pr\u00eats \u00e0 payer augmente l\u00e9g\u00e8rement. En outre, dans la plupart des formes de publicit\u00e9 en ligne, la valeur ajout\u00e9e reste inf\u00e9rieure aux attentes.&#13;<br \/>\n&#13;<br \/>\nAux mutations structurelles s\u2019ajoute un d\u00e9veloppement favoris\u00e9 par la num\u00e9risation\u00a0: les limites entre journalisme engag\u00e9 \u00e0 servir l\u2019opinion publique et communication dict\u00e9e par des int\u00e9r\u00eats s\u2019estompent de plus en plus. Cela n\u2019est pas forc\u00e9ment mauvais pour le consommateur, mais reste quand m\u00eame probl\u00e9matique si l\u2019on veut que la population participe aux processus politiques et sociaux. En effet, il ne peut exister de d\u00e9bats, de participation, de savoir, de formation de l\u2019opinion et de prise de d\u00e9cision qu\u2019\u00e0 travers une information aussi ind\u00e9pendante que possible, vou\u00e9e avant tout aux faits et \u00e0 l\u2019objectivit\u00e9, et produite selon des principes journalistiques et \u00e9thiques pr\u00e9cis. La disparition d\u2019une information objective, ou son accessibilit\u00e9 r\u00e9serv\u00e9e \u00e0 de rares consommateurs et sur un nombre limit\u00e9 de sujets constituent un danger pour la d\u00e9mocratie.&#13;<br \/>\n&#13;<br \/>\nLa troisi\u00e8me tendance est un effacement progressif de la distinction entre les diverses formes de journalisme, en particulier dans les offres d\u2019information et de divertissement. Textes, sons, images anim\u00e9es, infographies, visualisation des donn\u00e9es, r\u00e9alit\u00e9 augment\u00e9e ou virtuelle constituent d\u00e9sormais une exp\u00e9rience m\u00e9diatique int\u00e9gr\u00e9e, pas n\u00e9cessairement produite par une seule main, mais le r\u00e9sultat d\u2019un assemblage de sources diff\u00e9rentes, soit humaines, soit algorithmiques.&#13;<\/p>\n<h2><strong>Le journalisme menac\u00e9<\/strong><\/h2>\n<p>&#13;<br \/>\nLe changement sera aussi tranch\u00e9 sur le march\u00e9 publicitaire. S\u2018adresser directement \u00e0 un particulier sur un terminal num\u00e9rique pourrait devenir la norme, que ce soit par le biais d\u2019un smartphone, d\u2019une montre connect\u00e9e ou d\u2019une tablette, en voiture, en tram ou par affiches num\u00e9ris\u00e9es. Sur la base de nos profils d\u2019utilisateurs, nous ne verrons plus que ce qui pourrait nous int\u00e9resser, individuellement ou en tant que membres d\u2018un groupe cible. Le facteur d\u00e9cisif ne sera plus seulement ce que nous consommons sur les m\u00e9dias, mais aussi o\u00f9 et comment.&#13;<br \/>\n&#13;<br \/>\nCette \u00e9volution et de nouveaux d\u00e9veloppements transforment radicalement le journalisme. Dans son organisation r\u00e9dactionnelle, il est accul\u00e9, parce que sa production est d\u00e9sormais beaucoup trop on\u00e9reuse par rapport \u00e0 sa valeur ajout\u00e9e. Cela ne posait pas de probl\u00e8mes au cours des deux cents derni\u00e8res ann\u00e9es, car ce que le consommateur n\u2019\u00e9tait pas pr\u00eat \u00e0 payer pouvait \u00eatre compens\u00e9 par le march\u00e9 publicitaire. En exag\u00e9rant un peu, on pourrait dire que notre attention au contenu \u00e9tait achet\u00e9e par notre tol\u00e9rance vis-\u00e0-vis des annonces et des blocs publicitaires. Cette \u00e9poque est r\u00e9volue et ne reviendra plus.&#13;<\/p>\n<h2><strong>Un march\u00e9 trop exigu<\/strong><\/h2>\n<p>&#13;<br \/>\nDeux autres \u00e9l\u00e9ments rendent cette \u00e9volution particuli\u00e8rement probl\u00e9matique pour la Suisse, \u00e0 commencer par la singularit\u00e9 du march\u00e9 m\u00e9diatique local \u2013 minuscule en comparaison internationale, fortement fragment\u00e9 par les quatre langues nationales et le f\u00e9d\u00e9ralisme, et entour\u00e9 de puissants concurrents \u00e9trangers. Songeons que l\u2019agglom\u00e9ration munichoise compte \u00e0 peu pr\u00e8s autant d\u2019habitants que l\u2019ensemble de la Suisse al\u00e9manique.&#13;<br \/>\n&#13;<br \/>\nDeuxi\u00e8mement, le contenu occupe une place particuli\u00e8re sur le march\u00e9 des biens. Certes, son emploi peut \u00eatre limit\u00e9 comme jamais \u00e0 l\u2019\u00e8re num\u00e9rique, ce qui est essentiel pour la valeur ajout\u00e9e. Il reste cependant la probl\u00e9matique des biens publics\u00a0: en pratique, la transmission gratuite de l\u2019information ne peut \u00eatre jugul\u00e9e et son noyau dur ne peut \u00eatre prot\u00e9g\u00e9. Pour les consommateurs, l\u2019information est en outre un produit de confiance, dont la qualit\u00e9, la pertinence et la valeur d\u2019usage sont impossibles \u00e0 estimer \u00e0 l\u2019achat. Ces deux caract\u00e9ristiques ne renforcent pas la disposition \u00e0 payer.&#13;<br \/>\n&#13;<br \/>\nLe march\u00e9 local des m\u00e9dias devrait donc continuer \u00e0 s\u2019amenuiser. Seuls quelques groupes m\u00e9diatiques pourront encore s\u2019offrir le luxe d\u2019un journalisme ax\u00e9 sur les valeurs, structur\u00e9 et sp\u00e9cialis\u00e9 quant au fond. En effet, en vertu d\u2019une froide logique commerciale, un tel journalisme ne devrait pas \u00eatre structurellement d\u00e9ficitaire et devrait se financer par ses propres moyens. Voil\u00e0 pourquoi les co\u00fbts continuent \u00e0 \u00eatre rogn\u00e9s par une diminution des d\u00e9penses ou des \u00e9conomies d\u2019\u00e9chelle, ce qui ne favorise pas l\u2019\u00e9tendue, la diversit\u00e9 et la qualit\u00e9 de l\u2019offre. Pour les produits de niche, il est concevable que des offres de haute qualit\u00e9 survivent gr\u00e2ce au financement participatif, au m\u00e9c\u00e9nat, aux fondations ou \u00e0 d\u2019autres formes de subventionnement crois\u00e9. Sur le march\u00e9 de masse, cela ne devrait plus \u00eatre possible que dans des cas isol\u00e9s.&#13;<\/p>\n<h2><strong>Pas de politique industrielle<\/strong><\/h2>\n<p>&#13;<br \/>\nActuellement, le monde des m\u00e9dias est scind\u00e9 en deux\u00a0: d\u2019un c\u00f4t\u00e9, la radiot\u00e9l\u00e9vision publique, financ\u00e9e par la redevance obligatoire, et de l\u2019autre, des fournisseurs priv\u00e9s soumis \u00e0 une concurrence f\u00e9roce et produisant des contenus fortement ax\u00e9s sur l\u2019\u00e9crit, et quelques offres radio-t\u00e9l\u00e9visuelles \u00e0 rayonnement local. Cette situation ne tient aucun compte des utilisateurs, qui s\u2019informent depuis longtemps aupr\u00e8s d\u2019interm\u00e9diaires et de fournisseurs de programmes mondiaux comme Google, Facebook, YouTube, Spotify, Netflix, etc., et qui ne souhaitent pas une r\u00e9partition des march\u00e9s selon des crit\u00e8res g\u00e9ographiques ou par m\u00e9dia (t\u00e9l\u00e9vision, radio, presse) ni un regroupement sous la tutelle d\u2019un seul fournisseur.&#13;<br \/>\n&#13;<br \/>\nLe d\u00e9bat sur l\u2019avenir du service public devrait donc abandonner l\u2019id\u00e9e d\u2019un d\u00e9veloppement progressif du statu quo, dont le socle remonte au milieu du XX<sup>e<\/sup>\u00a0si\u00e8cle. Il devrait mettre en lumi\u00e8re les contradictions parfois fortes entre ce qui est souhaitable du point de vue constitutionnel, d\u2019une part, et du point de vue social, d\u2019autre part. Il ne faut surtout pas que le march\u00e9 suisse des m\u00e9dias prenne le m\u00eame chemin que l\u2019agriculture ou le syst\u00e8me de sant\u00e9\u00a0: r\u00e9glementation s\u00e9v\u00e8re, taux de subventionnement \u00e9lev\u00e9, verrouillage de la concurrence et chert\u00e9 pour le consommateur. En outre, la division entre \u00c9tat et march\u00e9 n\u2019a plus lieu d\u2019\u00eatre face au bouleversement du march\u00e9 des m\u00e9dias, car elle ne r\u00e9pond pas aux d\u00e9fis \u00e9conomiques et technologiques de demain.&#13;<br \/>\n&#13;<br \/>\nL\u2019offre de prestations concessionnaires financ\u00e9es par les pouvoirs publics doit \u00eatre d\u00e9finie clairement, de fa\u00e7on \u00e0 la distinguer nettement des options commerciales, non seulement en mati\u00e8re de qualit\u00e9 et de pertinence, mais aussi quant \u00e0 ses objectifs, son orientation client et l\u2019effet social global recherch\u00e9. La fourniture de services par des m\u00e9dias publics doit \u00eatre neutre d\u2019un point de vue technologique et ind\u00e9pendante des prestataires. Il ne faut donc pas prononcer d\u2019interdiction pour l\u2019exploitation de canaux sp\u00e9cifiques comme les services en ligne ni accorder de mandat de prestataire \u00e0 un seul fournisseur tout-puissant tel que la SSR.&#13;<\/p>\n<h2><strong>L\u2019\u00e9pouvantail de l\u2019aide directe aux m\u00e9dias<\/strong><\/h2>\n<p>&#13;<br \/>\nLes critiques devraient d\u00e8s maintenant donner de la voix puisque l\u2019auteur plaide en faveur d\u2019une aide directe aux m\u00e9dias\u00a0! En fait, celle-ci existe d\u00e9j\u00e0 et devra m\u00eame \u00eatre augment\u00e9e pour les raisons expos\u00e9es plus haut, si nous tenons \u00e0 la diversit\u00e9 et \u00e0 la qualit\u00e9 du march\u00e9 suisse des m\u00e9dias. Il est vrai que la conception de cette aide est une gageure. Il faut en effet garantir la libert\u00e9 inconditionnelle vis-\u00e0-vis de l\u2019\u00c9tat, le mod\u00e8le de financement, son montant, le mandat concret de prestations, le r\u00e8glement du consentement des prestataires et un traitement constitutionnel aussi correct que possible des concurrents qui souhaitent continuer \u00e0 exercer sur le march\u00e9 libre.&#13;<br \/>\n&#13;<br \/>\nUne premi\u00e8re \u00e9tape pourrait consister \u00e0 imposer effectivement un plafonnement de la redevance vers\u00e9e \u00e0 la SSR. Pour un m\u00e9nage moyen de quatre personnes, une redevance de 25\u00a0centimes par personne et par jour permettrait d\u2019obtenir un journalisme de qualit\u00e9 \u00e0 un prix d\u00e9risoire. Si la SSR continue \u00e0 diffuser de la publicit\u00e9, on pourrait l\u2019astreindre \u00e0 partager ses recettes publicitaires avec des tiers, dans le cadre des normes journalistiques, ou d\u2019organiser la commercialisation en partenariat avec d\u2019autres groupes m\u00e9diatiques et sous un statut juridique propre. Il serait \u00e9galement concevable de d\u00e9signer au moins une cha\u00eene \u2013\u00a0<em>SRF Info<\/em>, par exemple \u2013 pour qu\u2019elle serve de champ d\u2019exp\u00e9rimentation et permette de d\u00e9finir un programme complet auquel participeraient la SSR et des fournisseurs priv\u00e9s. Cela signifie que, sous un statut juridique propre et des mandats de prestations sp\u00e9cifiques, d\u2019autres fournisseurs que la SSR pourraient produire des \u00e9missions \u00e0 caract\u00e8re de service public. Celles-ci pourraient, en outre, \u00eatre diffus\u00e9es sur d\u2019autres supports m\u00e9diatiques.&#13;<br \/>\n&#13;<br \/>\nPourquoi les hautes \u00e9coles, par exemple, n\u2019auraient-elles pas le droit de produire des contenus culturels si elles se plient \u00e0 des crit\u00e8res journalistiques pr\u00e9cis\u00a0? Pourquoi un r\u00e9seau de jeunes journalistes cr\u00e9atifs ne g\u00e9rerait-il pas une rubrique \u00e9conomique\u00a0? Pourquoi la <em>NZZ<\/em> ne ferait-elle pas b\u00e9n\u00e9ficier le public de sa connaissance de l\u2019\u00e9tranger\u00a0? Pourquoi Ringier ne produirait-il pas l\u2019\u00e9mission populaire \u00ab\u00a0Glanz und Gloria\u00a0\u00bb\u00a0? Si de tels contenus contribuent \u00e0 informer la population, que les diff\u00e9rents fournisseurs respectent les prestations convenues li\u00e9es aux fonds d\u2019encouragement et que l\u2019offre produite ne peut \u00eatre financ\u00e9e \u2013 ou insuffisamment\u00a0\u2013 par le march\u00e9, on assurerait ainsi un minimum de contenus divers et de qualit\u00e9.&#13;<\/p>\n<h2><strong>Le co\u00fbt n\u2019est pas le probl\u00e8me<\/strong><\/h2>\n<p>&#13;<br \/>\nL\u2019important n\u2019est pas de faire de la politique industrielle et de maintenir sous perfusion une branche \u00e0 l\u2019agonie. Il faut bien plus nous int\u00e9resser au fait que, en tant que nation, soci\u00e9t\u00e9, citoyens et individus, nous continuerons \u00e0 b\u00e9n\u00e9ficier de contenus journalistiques nous permettant de participer volontairement \u00e0 la vie communautaire et aux processus d\u00e9mocratiques.&#13;<br \/>\n&#13;<br \/>\nLes co\u00fbts aff\u00e9rents sont une chose, certes, mais le probl\u00e8me est tr\u00e8s franchement soluble. Ce qui est plus difficile, dans le contexte politique actuel et au vu des possibilit\u00e9s constitutionnelles, est de concevoir les services de m\u00e9dias publics comme un syst\u00e8me global, apr\u00e8s avoir soigneusement tent\u00e9 de trouver un \u00e9quilibre entre une intervention ind\u00e9sirable sur le march\u00e9 et la d\u00e9fense des int\u00e9r\u00eats communautaires. La question ne doit plus se r\u00e9duire au seul financement de la SSR ou \u00e0 sa mise au pas. La nouvelle loi sur les m\u00e9dias, qui sera mise en consultation cet \u00e9t\u00e9 et qui, sur la base de la Constitution, ne peut se concentrer que sur les m\u00e9dias \u00e9lectroniques, ne r\u00e9pondra probablement pas \u00e0 cette exigence. Il serait cependant souhaitable qu\u2019elle n\u2019entrave pas pour des ann\u00e9es une politique des m\u00e9dias plus souple, novatrice et courageuse pour le pays.<\/p>\n<ol class=\"footnote\"><li id=\"footnote_1\" class=\"footnote--item\">Les opinions exprim\u00e9es ici n\u2019engagent que leur auteur.&nbsp;<a href=\"#footnote-anchor_1\" class=\"inline-footnote__anchor hidden-print\">[<span class=\"icon-arrow-up\"><\/span>]<\/a><\/li><\/ol>","protected":false},"excerpt":{"rendered":"<p>La bataille est termin\u00e9e, le vainqueur est connu\u00a0: la radiot\u00e9l\u00e9vision publique pourra continuer d\u2019\u00e9mettre en Suisse. Pourtant, le net rejet de l\u2019initiative \u00ab\u00a0No-Billag\u00a0\u00bb ne saurait \u00eatre interpr\u00e9t\u00e9 comme un encouragement \u00e0 continuer comme si rien ne s\u2019\u00e9tait pass\u00e9. La votation avait uniquement pour objet le financement de la radiot\u00e9l\u00e9vision publique et des cha\u00eenes priv\u00e9es concessionnaires. [&hellip;]<\/p>","protected":false},"author":4663,"featured_media":22922,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"ep_exclude_from_search":false,"footnotes":""},"post__type":[81,83],"post_opinion":[],"post_serie":[],"post_content_category":[105],"post_content_subject":[],"acf":{"seco_author":4663,"seco_co_author":null,"author_override":"","seco_author_post_ocupation_year":"","seco_author_post_occupation_de":"Pr\u00e4sident der Stiftung Schweizer Presserat, Mitglied der Eidgen\u00f6ssischen Medienkommission und Gesch\u00e4ftsf\u00fchrer beim Beratungsunternehmen Spillmann Publizistik Strategie Management, Z\u00fcrich","seco_author_post_occupation_fr":"Pr\u00e9sident de la fondation du Conseil suisse de la presse, membre de la Commission f\u00e9d\u00e9rale des m\u00e9dias, et directeur de l\u2019entreprise de consultants Spillmann Publizistik Strategie Management, Zurich","seco_co_authors_post_ocupation":null,"short_title":"Plus de service public pour les m\u00e9dias","post_lead":"Plaidoyer pour des m\u00e9dias de service public novateurs, sans monopole de la SSR et avec davantage de concurrence entre les contenus.","post_hero_image_description":"Ringier devrait-il produire \u00ab Glanz & Gloria \u00bb, une \u00e9mission de la t\u00e9l\u00e9vision suisse al\u00e9manique ? La mod\u00e9ratrice Annina Frey en studio.","post_hero_image_description_copyright_de":"Keystone","post_hero_image_description_copyright_fr":"","post_references_literature":"","post_kasten":null,"post_notes_for_print":"","first_teaser_header_de":"","first_teaser_header_fr":"","first_teaser_text_de":"","first_teaser_text_fr":"","second_teaser_header_de":"","second_teaser_header_fr":"","second_teaser_text_de":"","second_teaser_text_fr":"","kseason_de":"","kseason_fr":"","post_in_pdf":137696,"main_focus":[156261,156992],"serie_email":null,"frontpage_slider_bild":137700,"artikel_bild-slider":null,"legacy_id":"77346","post_abstract":"Les discussions sur les m\u00e9dias relevant du service public s\u2019arr\u00eatent la plupart du temps \u00e0 la question du financement et de la taille de la SSR. Le net rejet de l\u2019initiative \u00ab\u00a0No Billag\u00a0\u00bb pourrait \u00eatre interpr\u00e9t\u00e9 comme une prolongation du statu quo. Ce serait fatal, car les habitudes de consommation et les int\u00e9r\u00eats des consommateurs changent de fa\u00e7on fondamentale, tandis que, parall\u00e8lement, le refinancement sur le march\u00e9 libre du journalisme ax\u00e9 sur les valeurs devient de plus en plus difficile. Cette tendance constitue une menace pour l\u2019information de la population, pourtant indispensable au d\u00e9bat d\u00e9mocratique.\u00a0\u00c0 l\u2019avenir, il faudra vraisemblablement plus\u00a0\u2013 et non moins\u00a0\u2013 d\u2019offres m\u00e9diatiques (co)financ\u00e9es par l\u2019\u00c9tat. Ce service public de demain doit \u00eatre envisag\u00e9 comme un syst\u00e8me impliquant des prestataires priv\u00e9s trait\u00e9s sur un pied d\u2019\u00e9galit\u00e9. La technologie et les fournisseurs doivent, en outre, rester neutres et l\u2019exploitation \u00e9chapper \u00e0 l\u2019\u00c9tat.","magazine_issue":"20180501","seco_author_reccomended_post":null,"redaktoren":[3988,0],"korrektor":4139,"planned_publication_date":"20180425","original_files":null,"external_release_for_author":"20180329","external_release_for_author_time":"00:00:00","link_for_external_authors":"https:\/\/dievolkswirtschaft.ch\/exedit\/5aaf7396393b9"},"_links":{"self":[{"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/posts\/137693"}],"collection":[{"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/users\/4663"}],"replies":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/comments?post=137693"}],"version-history":[{"count":1,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/posts\/137693\/revisions"}],"predecessor-version":[{"id":188058,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/posts\/137693\/revisions\/188058"}],"acf:user":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/users\/4139"},{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/users\/0"},{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/users\/3988"},{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/users\/4663"}],"acf:post":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/main_focus_post\/156992"},{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/main_focus_post\/156261"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/media\/22922"}],"wp:attachment":[{"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/media?parent=137693"}],"wp:term":[{"taxonomy":"post__type","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/post__type?post=137693"},{"taxonomy":"post_opinion","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/post_opinion?post=137693"},{"taxonomy":"post_serie","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/post_serie?post=137693"},{"taxonomy":"post_content_category","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/post_content_category?post=137693"},{"taxonomy":"post_content_subject","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/post_content_subject?post=137693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}