{"id":140555,"date":"2017-04-27T15:50:24","date_gmt":"2017-04-27T15:50:24","guid":{"rendered":"https:\/\/dievolkswirtschaft.ch\/2017\/04\/krone-germann-05-2017fr\/"},"modified":"2023-08-24T00:17:57","modified_gmt":"2023-08-23T22:17:57","slug":"krone-germann-05-2017fr","status":"publish","type":"post","link":"https:\/\/dievolkswirtschaft.ch\/fr\/2017\/04\/krone-germann-05-2017fr\/","title":{"rendered":"Le partage d\u2019emploi en Suisse&nbsp;: un monde en d\u00e9veloppement"},"content":{"rendered":"<p>L\u2019environnement professionnel se transforme rapidement avec la num\u00e9risation des flux d\u2019information et la flexibilisation du travail. T\u00e9l\u00e9travail, r\u00e9organisation des \u00e9quivalents plein temps, \u00ab\u00a0crowd working\u00a0\u00bb, intelligence collective du travail rendue horizontale par les r\u00e9seaux num\u00e9riques\u00a0: tout cela symbolise le travail 4.0. Dans ce contexte particulier, le partage d\u2019emploi, que ce soit au niveau ordinaire (\u00ab\u00a0job sharing\u00a0\u00bb) ou en haut de l\u2019\u00e9chelle (\u00ab\u00a0top sharing\u00a0\u00bb), est un mod\u00e8le particuli\u00e8rement int\u00e9ressant.&#13;<br \/>\n&#13;<br \/>\nLe partage d\u2019emploi n\u2019est pas un concept nouveau. Il fait son apparition dans les ann\u00e9es soixante aux \u00c9tats-Unis. L\u2019\u00e9conomiste Barney Olmsted est la premi\u00e8re \u00e0 en faire \u00e9tat dans la litt\u00e9rature \u00e9conomique en 1977. La nouveaut\u00e9 vient de son \u00e9volution sous la pouss\u00e9e du num\u00e9rique et de l\u2019int\u00e9r\u00eat croissant qu\u2019il suscite tant pour les employ\u00e9s de toutes g\u00e9n\u00e9rations (\u00ab\u00a0babyboomers\u00a0\u00bb, g\u00e9n\u00e9rations X, Y et Z) que pour les employeurs et les responsables des ressources humaines. Ces derniers cherchent \u00e0 conserver leurs talents dans un monde o\u00f9 l\u2019\u00e9quilibre entre vies professionnelle et priv\u00e9e, de m\u00eame que la recherche de diversit\u00e9 par des d\u2019activit\u00e9s professionnelles en parall\u00e8le constituent des attentes majeures qui impliquent une meilleure flexibilit\u00e9 de l\u2019emploi.&#13;<br \/>\n&#13;<br \/>\nLe \u00ab\u00a0job sharing\u00a0\u00bb reste un mod\u00e8le innovant tant pour l\u2019employeur que pour l\u2019employ\u00e9. Le principe est simple\u00a0: deux employ\u00e9s (ou plus) se partagent un poste \u00e0 temps plein avec des t\u00e2ches interd\u00e9pendantes et une responsabilit\u00e9 commune. Ils forment un bin\u00f4me professionnel aux r\u00f4les interchangeables, dont le r\u00e9sultat commun est \u00e9valu\u00e9. Le \u00ab\u00a0top sharing\u00a0\u00bb applique ce m\u00eame principe aux postes \u00e0 haute responsabilit\u00e9 incluant la gestion de collaborateurs. Diriger \u00e0 temps partiel, et en plus \u00e0 deux, \u00e9tait une option \u00e0 peine \u00e9voqu\u00e9e autrefois. Elle a d\u00e9sormais le vent en poupe et s\u2019applique d\u00e9j\u00e0 \u00e0 divers \u00e9chelons hi\u00e9rarchiques dans les entreprises priv\u00e9es et les administrations publiques.&#13;<br \/>\n&#13;<br \/>\nEn Suisse, 27\u00a0% des entreprises comportent des postes en \u00ab\u00a0job sharing\u00a0\u00bb, dont un quart concernent les cadres<a href=\"#footnote_1\" id=\"footnote-anchor_1\" class=\"inline-footnote__anchor\">[1]<\/a>. C\u2019est dans les administrations publiques, de m\u00eame que dans le secteur des services financiers et les assurances que ce mod\u00e8le est le plus pratiqu\u00e9<a href=\"#footnote_2\" id=\"footnote-anchor_2\" class=\"inline-footnote__anchor\">[2]<\/a>. Ces chiffres illustrent l\u2019importance qu\u2019il a prise ces derni\u00e8res ann\u00e9es. Dans des positions de cadres, plusieurs firmes en Suisse pratiquent et cherchent \u00e0 promouvoir activement ce mod\u00e8le. Parmi elles, on trouve les TIC, les banques et les assurances, le secteur de l\u2019\u00e9nergie, les milieux artistiques, les administrations cantonales et f\u00e9d\u00e9rales, de m\u00eame que la recherche et l\u2019enseignement<a href=\"#footnote_3\" id=\"footnote-anchor_3\" class=\"inline-footnote__anchor\">[3]<\/a>.&#13;<\/p>\n<h2><strong>La num\u00e9risation facilite le partage d\u2019emploi<\/strong><\/h2>\n<p>&#13;<br \/>\nLa num\u00e9risation donne un nouvel essor au \u00ab\u00a0job sharing\u00a0\u00bb. Les technologies de l\u2019information permettent d\u2019optimiser les flux de communication entre \u00ab\u00a0job sharers\u00a0\u00bb, assurant ainsi le bon suivi des dossiers ou des t\u00e2ches. Les prises de d\u00e9cision rapides et communes am\u00e9liorent la productivit\u00e9 cumul\u00e9e du tandem. Les activit\u00e9s professionnelles partag\u00e9es peuvent se d\u00e9rouler en un m\u00eame endroit ou sur plusieurs sites simultan\u00e9s, gr\u00e2ce \u00e0 une connexion quasi permanente.&#13;<br \/>\n&#13;<br \/>\nEn ce qui concerne le recrutement et la recherche de partenaire, les plateformes collaboratives tirent parti des m\u00e9gadonn\u00e9es (\u00ab\u00a0big data\u00a0\u00bb) pour acc\u00e9l\u00e9rer les contacts professionnels au moyen d\u2019algorithmes et aboutir \u00e0 des partenariats&#13;<br \/>\n&#13;<br \/>\nLes entreprises s\u2019int\u00e9ressent de plus en plus \u00e0 ce mod\u00e8le, car leur pourcentage d\u2019employ\u00e9s \u00e0 temps partiel est en constante augmentation et qu\u2019il est plus simple d\u2019engager un duo pour un poste \u00e0 responsabilit\u00e9 en raison de sa plus grande pr\u00e9sence au sein de l\u2019entreprise. Plus d\u2019un tiers des personnes actives occup\u00e9es en Suisse (36\u00a0%) sont dans cette situation. Le niveau g\u00e9n\u00e9ralement \u00e9lev\u00e9 des salaires permet \u00e0 de nombreuses personnes bien form\u00e9es de ne pas travailler \u00e0 plein temps. Plus de 60\u00a0% des femmes de formation universitaire, m\u00e8res d\u2019un enfant au moins, travaillent aujourd\u2019hui \u00e0 temps r\u00e9duit<a href=\"#footnote_4\" id=\"footnote-anchor_4\" class=\"inline-footnote__anchor\">[4]<\/a>.&#13;<\/p>\n<h2><strong>Retenir les talents, un objectif central<\/strong><\/h2>\n<p>&#13;<br \/>\nLes sp\u00e9cialistes en ressources humaines et la direction doivent retenir les talents dont ils disposent. Une femme hautement qualifi\u00e9e qui, apr\u00e8s une dizaine d\u2019ann\u00e9es de vie professionnelle, attend son premier enfant, peut vouloir travailler \u00e0 temps partiel. Si son poste \u00e0 responsabilit\u00e9 ne le lui permet pas, l\u2019entreprise risque de la perdre pour toujours. Face \u00e0 une telle situation, le partage d\u2019emploi, qu\u2019il s\u2019agisse de \u00ab\u00a0job sharing\u00a0\u00bb ou de \u00ab\u00a0top sharing\u00a0\u00bb, est une solution particuli\u00e8rement int\u00e9ressante. Il offre \u00e0 l\u2019entreprise la possibilit\u00e9 de rester attractive face \u00e0 la concurrence et de conserver son capital le plus pr\u00e9cieux\u00a0: le savoir-faire de son personnel. Celui-ci peut \u00e9galement se transmettre au travers de \u00ab\u00a0job sharings\u00a0\u00bb interg\u00e9n\u00e9rationnels.&#13;<br \/>\n&#13;<br \/>\nEn 2014, la Haute \u00e9cole sp\u00e9cialis\u00e9e de la Suisse du Nord-Ouest (FHNW) a men\u00e9 une enqu\u00eate d\u2019envergure nationale sur le partage d\u2019emploi en Suisse. Les 382 entreprises qui y ont r\u00e9pondu repr\u00e9sentaient 180&nbsp;000 employ\u00e9s (voir <em>illustration<\/em>)<a href=\"#footnote_5\" id=\"footnote-anchor_5\" class=\"inline-footnote__anchor\">[5]<\/a>. Pour les dirigeants interrog\u00e9s, la premi\u00e8re raison \u00e0 l\u2019introduction du \u00ab\u00a0job sharing\u00a0\u00bb est <em>de r\u00e9pondre \u00e0 la demande du personnel qualifi\u00e9<\/em> et d\u2019augmenter ainsi sa motivation (r\u00e9tention de talent). La deuxi\u00e8me raison est <em>le maintien et le transfert du savoir-faire<\/em>, d\u00e9cisif pour la comp\u00e9titivit\u00e9 de l\u2019entreprise. Les dispositions visant \u00e0 p\u00e9renniser l\u2019emploi qualifi\u00e9 au sein de l\u2019entreprise rev\u00eatent donc une importance croissante, notamment lorsque la main-d\u2019\u0153uvre comp\u00e9tente se fait rare. La troisi\u00e8me raison la plus fr\u00e9quemment cit\u00e9e est <em>la promotion des femmes \u00e0 des postes de direction<\/em>.&#13;<\/p>\n<h3 class=\"text__graphic-title\"><strong>Motifs \u00e9voqu\u00e9s pour l\u2019introduction du \u00ab\u00a0job sharing\u00a0\u00bb aux niveaux sup\u00e9rieurs de la hi\u00e9rarchie<\/strong><\/h3>\n<p>&#13;<br \/>\n<div class='chart chart--normal' id='krone_germann_fr'>\n\n<\/div>\n\n<script>\n$(function () {\n    $('#krone_germann_fr').highcharts({\n    \n  chart: {\n        type: 'bar'\n    },\n    title: {\n        text: ''\n    },\n   \n    xAxis: {\n        categories: ['Augmenter la motivation du personnel qualifi\u00e9 en r\u00e9pondant \u00e0 leur demande', 'P\u00e9renniser le savoir-faire qualifi\u00e9 de l\u2019entreprise\/l\u2019organisation ', 'Favoriser l\u2019acc\u00e8s aux femmes \u00e0 certains postes \u00e0 responsabilit\u00e9', 'Augmenter l\u2019attractivit\u00e9 de l\u2019employeur', 'Par conviction (le partage de pouvoir \u00e0 des postes \u00e0 responsabilit\u00e9 est propice \u00e0 l\u2019entreprise)','Transmettre l\u2019exp\u00e9rience des seniors aux juniors (jobsharing interg\u00e9n\u00e9rationnel)','Autres raisons'],\n        title: {\n            text: null\n        }\n    },\n    yAxis: {labels: {\n            format: '{value}%'\n        },\n        title: {\n            text: ''\n        },\n    \n    }, legend: {\n                     enabled: false,\n\n\n    },\n   tooltip: {\n        pointFormat: '{point.y:.1f} %'\n    },\n    plotOptions: {\n        bar: {\n            dataLabels: {\n                enabled: false\n            }\n        }\n    },\n    \n    credits: {\n        enabled: false\n    },\n    series: [{\n        name: 'Motivations de l\u2019introduction du jobsharing',\n        data: [68,40,32,24,12,8,28]\n    }]\n});\n});\n\n\n\n<\/script>\n&#13;<br \/>\n&#13;<br \/>\n<span class=\"text__legend\">Remarque\u00a0: plusieurs r\u00e9ponses possibles.<\/span>&#13;<br \/>\n&#13;<br \/>\n<span class=\"text__quelle--ground\">Source\u00a0: FHNW (2014) \/ La Vie \u00e9conomique<\/span>&#13;<br \/>\n&#13;<br \/>\nCes objectifs sont d\u2019autant plus importants que les processus internes au sein des entreprises se num\u00e9risent de plus en plus. Pour un grand nombre d\u2019employ\u00e9s, \u0153uvrer dans des environnements souples et ouverts \u00e0 l\u2019innovation permet d\u2019\u00eatre aussi actif dans d\u2019autres domaines professionnels, voire d\u2019entamer en parall\u00e8le une carri\u00e8re d\u2019ind\u00e9pendant. Occuper plusieurs activit\u00e9s professionnelles \u00e0 titre volontaire devient de plus en plus fr\u00e9quent. Les partisans de ces doubles ou multiples carri\u00e8res en parall\u00e8le pratiquent ce que l\u2019on appelle les \u00ab\u00a0slash careers\u00a0\u00bb, un concept introduit aux \u00c9tats-Unis en 2007 par la chercheuse am\u00e9ricaine Marci Alboher.&#13;<\/p>\n<h2><strong>D\u00e9couvrir le mod\u00e8le, se rencontrer et tester un duo<\/strong><\/h2>\n<p>&#13;<br \/>\nTrouver un bon partenaire reste toutefois une condition sine qua non pour assurer un partage d\u2019emploi efficace. Il faut tout d\u2019abord trouver quelqu\u2019un avec qui partager un certain nombre de valeurs. Il faut ensuite se rencontrer et tester la collaboration. Une postulation commune n\u2019est envisageable qu\u2019\u00e0 ce prix (voir <em>encadr\u00e9<\/em>).<\/p>\n<ol class=\"footnote\"><li id=\"footnote_1\" class=\"footnote--item\">Amstutz N. et Jochem A., <a href=\"http:\/\/www.go-for-jobsharing.ch\/js\/kcfinder\/upload\/files\/Enquete_fr_PTO_FHNW_final.pdf\"><em>Travail \u00e0 temps partiel et job sharing en Suisse, R\u00e9sultats de l\u2019enqu\u00eate<\/em><\/a>, FHNW, 2014.&nbsp;<a href=\"#footnote-anchor_1\" class=\"inline-footnote__anchor hidden-print\">[<span class=\"icon-arrow-up\"><\/span>]<\/a><\/li><li id=\"footnote_2\" class=\"footnote--item\">Voir <a href=\"http:\/\/www.go-for-jobsharing.ch\/fr\/publications\/enquete-jobsharing.html\">enqu\u00eate FHNW <\/a>(2014).&nbsp;<a href=\"#footnote-anchor_2\" class=\"inline-footnote__anchor hidden-print\">[<span class=\"icon-arrow-up\"><\/span>]<\/a><\/li><li id=\"footnote_3\" class=\"footnote--item\">(voir les t\u00e9moignages sur <a href=\"http:\/\/www.go-for-jobsharing.ch\">www.go-for-jobsharing.ch<\/a>.&nbsp;<a href=\"#footnote-anchor_3\" class=\"inline-footnote__anchor hidden-print\">[<span class=\"icon-arrow-up\"><\/span>]<\/a><\/li><li id=\"footnote_4\" class=\"footnote--item\">OFS (2015).&nbsp;<a href=\"#footnote-anchor_4\" class=\"inline-footnote__anchor hidden-print\">[<span class=\"icon-arrow-up\"><\/span>]<\/a><\/li><li id=\"footnote_5\" class=\"footnote--item\"><a href=\"http:\/\/dievolkswirtschaft.ch\/fr\/2014\/06\/le-partage-demploi-en-suisse-enquete-nationale-et-plateforme-dinformations\/\">Krone-Germann Irenka, De Chambrier Anne Aymone et Amstutz Nathalie, \u00ab\u00a0Le partage d\u2019emploi en Suisse\u00a0: enqu\u00eate nationale et plateforme d\u2019informations\u00a0\u00bb, <em>La Vie \u00e9conomique<\/em><\/a>, 6-2014, pp. 22-23.&nbsp;<a href=\"#footnote-anchor_5\" class=\"inline-footnote__anchor hidden-print\">[<span class=\"icon-arrow-up\"><\/span>]<\/a><\/li><\/ol>","protected":false},"excerpt":{"rendered":"<p>L\u2019environnement professionnel se transforme rapidement avec la num\u00e9risation des flux d\u2019information et la flexibilisation du travail. T\u00e9l\u00e9travail, r\u00e9organisation des \u00e9quivalents plein temps, \u00ab\u00a0crowd working\u00a0\u00bb, intelligence collective du travail rendue horizontale par les r\u00e9seaux num\u00e9riques\u00a0: tout cela symbolise le travail 4.0. Dans ce contexte particulier, le partage d\u2019emploi, que ce soit au niveau ordinaire (\u00ab\u00a0job sharing\u00a0\u00bb) [&hellip;]<\/p>","protected":false},"author":3910,"featured_media":26142,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"ep_exclude_from_search":false,"footnotes":""},"post__type":[81,83],"post_opinion":[],"post_serie":[],"post_content_category":[90],"post_content_subject":[],"acf":{"seco_author":3910,"seco_co_author":null,"author_override":"","seco_author_post_ocupation_year":"","seco_author_post_occupation_de":"Dr. oec., Co-Leiterin Netzwerke, Wissensmanagement und Kommunikation, Zentrum f\u00fcr Information, Beratung und Bildung f\u00fcr Berufe in der internationalen Zusammenarbeit (Cinfo), Biel","seco_author_post_occupation_fr":"Co-cheffe R\u00e9seaux, gestion des connaissances et communication, Centre d'information, de conseil et de formation pour les professions de la coop\u00e9ration internationale (Cinfo), Bienne (BE)","seco_co_authors_post_ocupation":null,"short_title":"Le d\u00e9veloppement du partage d\u2019emploi","post_lead":"Le partage d\u2019emploi se d\u00e9veloppe de plus en plus rapidement gr\u00e2ce \u00e0 la num\u00e9risation et aux flux d\u2019information. Il permet \u00e0 l\u2019employ\u00e9 de concilier vies familiale et professionnelle ou de travailler \u00e0 temps partiel dans divers champs d'activit\u00e9, tout en conservant ses responsabilit\u00e9s. L\u2019employeur s\u2019attache, de son c\u00f4t\u00e9, ses meilleurs \u00e9l\u00e9ments.","post_hero_image_description":"Le partage d'emploi est particuli\u00e8rement r\u00e9pandu dans l'administration publique. C'est, par exemple, le cas \u00e0 l'Administration f\u00e9d\u00e9rale des  contributions, \u00e0 Berne.","post_hero_image_description_copyright_de":"Keystone","post_hero_image_description_copyright_fr":"","post_references_literature":"","post_kasten":[{"kasten_title":"R\u00e9ussir un partage d\u2019emploi : un ouvrage de r\u00e9f\u00e9rence et des sites Internet","kasten_box":"L\u2019association PTO est \u00e0 l\u2019origine de l\u2019initiative Go-for-jobsharing et de l\u2019ouvrage collectif <em>Le partage d\u2019emploi \u2013 Job sharing. Nouvelles opportunit\u00e9s et d\u00e9fis du travail<\/em>, \u00e9d. L\u2019Harmattan, codirig\u00e9 par Irenka Krone-Germann et Alain Max Gu\u00e9nette, professeur \u00e0 la HEG-Arc, auquel ont contribu\u00e9 34 auteurs de cinq pays. L\u2019association est soutenue par le Bureau f\u00e9d\u00e9ral de l\u2019\u00e9galit\u00e9 entre femmes et hommes (BFEG) et divers sponsors priv\u00e9s. Elle propose d\u2019accompagner des duos et organise des \u00ab\u00a0meet-ups jobsharing\u00a0\u00bb dans diverses villes de Suisse. Elle r\u00e9alise des ateliers cibl\u00e9s au sein des entreprises \u00e0 l\u2019intention des cadres, des sp\u00e9cialistes en ressources humaines et des \u00ab\u00a0job sharers\u00a0\u00bb potentiels. Le 6 novembre prochain, PTO et ses partenaires organisent \u00e0 B\u00e2le le deuxi\u00e8me colloque international sur le \u00ab\u00a0job sharing\u00a0\u00bb et le \u00ab\u00a0top sharing\u00a0\u00bb.&#13;\n&#13;\nIl existe plusieurs plateformes collaboratives permettant de faciliter les partenariats. Citons, \u00e0 titre d\u2019exemples, <a href=\"http:\/\/www.wejobshare.ch\/\">www.wejobshare.ch<\/a> et <a href=\"http:\/\/www.tandemploy.com\/\">www.tandemploy.com<\/a>).&#13;\n&#13;\nPour toute information sur la mise en \u0153uvre du \u00ab\u00a0job sharing\u00a0\u00bb, voir le site destin\u00e9 aux employeurs, sp\u00e9cialistes RH et employ\u00e9s\u00a0: <a href=\"http:\/\/www.go-for-jobsharing.ch\/\">www.go-for-jobsharing.ch<\/a><u>.<\/u>"}],"post_notes_for_print":"","first_teaser_header_de":"","first_teaser_header_fr":"","first_teaser_text_de":"","first_teaser_text_fr":"","second_teaser_header_de":"","second_teaser_header_fr":"","second_teaser_text_de":"","second_teaser_text_fr":"","kseason_de":"","kseason_fr":"","post_in_pdf":140558,"main_focus":[156382,157079],"serie_email":null,"frontpage_slider_bild":140562,"artikel_bild-slider":null,"legacy_id":"67724","post_abstract":"Le \u00ab\u00a0job sharing\u00a0\u00bb permet \u00e0 deux employ\u00e9s (ou plus) de se partager un emploi \u00e0 temps plein avec des t\u00e2ches interd\u00e9pendantes et une responsabilit\u00e9 commune. Lorsque ce mod\u00e8le s\u2019applique \u00e0 des postes \u00e0 responsabilit\u00e9, on parle de \u00ab\u00a0top sharing\u00a0\u00bb. La num\u00e9risation optimise les flux de communication entre \u00ab\u00a0job sharers\u00a0\u00bb, assurant ainsi le bon suivi des dossiers ou des t\u00e2ches. Gr\u00e2ce \u00e0 ce syst\u00e8me, les entreprises peuvent retenir leurs employ\u00e9s talentueux. Elles p\u00e9rennisent ainsi leur savoir-faire et restent attractives sur le march\u00e9 du travail. Trouver le bon partenaire n\u2019est cependant pas toujours ais\u00e9 d\u2019o\u00f9 la n\u00e9cessit\u00e9 de plateformes de mise en partenariat professionnel.","magazine_issue":"05-2017","seco_author_reccomended_post":null,"redaktoren":[4127,0],"korrektor":4139,"planned_publication_date":"20170428","original_files":[{"file":140570}],"external_release_for_author":"20170331","external_release_for_author_time":"23:30:00","link_for_external_authors":"https:\/\/dievolkswirtschaft.ch\/exedit\/58bd1c193bea2"},"_links":{"self":[{"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/posts\/140555"}],"collection":[{"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/users\/3910"}],"replies":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/comments?post=140555"}],"version-history":[{"count":1,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/posts\/140555\/revisions"}],"predecessor-version":[{"id":188254,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/posts\/140555\/revisions\/188254"}],"acf:user":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/users\/4139"},{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/users\/0"},{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/users\/4127"},{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/users\/3910"}],"acf:post":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/main_focus_post\/157079"},{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/main_focus_post\/156382"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/media\/26142"}],"wp:attachment":[{"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/media?parent=140555"}],"wp:term":[{"taxonomy":"post__type","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/post__type?post=140555"},{"taxonomy":"post_opinion","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/post_opinion?post=140555"},{"taxonomy":"post_serie","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/post_serie?post=140555"},{"taxonomy":"post_content_category","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/post_content_category?post=140555"},{"taxonomy":"post_content_subject","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/post_content_subject?post=140555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}