{"id":147536,"date":"2015-01-10T08:43:47","date_gmt":"2015-01-10T08:43:47","guid":{"rendered":"https:\/\/dievolkswirtschaft.ch\/2015\/01\/identifier-les-reformes-necessaires-et-sy-attaquer\/"},"modified":"2023-08-24T00:32:17","modified_gmt":"2023-08-23T22:32:17","slug":"identifier-les-reformes-necessaires-et-sy-attaquer","status":"publish","type":"post","link":"https:\/\/dievolkswirtschaft.ch\/fr\/2015\/01\/identifier-les-reformes-necessaires-et-sy-attaquer\/","title":{"rendered":"Identifier les r\u00e9formes n\u00e9cessaires et s\u2019y attaquer"},"content":{"rendered":"<p>Toute statistique internationale en mati\u00e8re de prosp\u00e9rit\u00e9 le montre clairement: la Suisse fait partie du peloton de t\u00eate plan\u00e9taire. Ainsi, l\u2019indice de l\u2019OCDE du bien-\u00eatre social et \u00e9conomique met nettement en \u00e9vidence le fait que la Suisse l\u2019emporte dans plusieurs domaines concernant le niveau de vie<a href=\"#footnote_1\" id=\"footnote-anchor_1\" class=\"inline-footnote__anchor\">[1]<\/a>. Notre pays se d\u00e9fend bien aussi sur le plan de la performance \u00e9conomique, qui est la source de la prosp\u00e9rit\u00e9. Selon les donn\u00e9es du Fonds mon\u00e9taire international (FMI), l\u2019\u00e9conomie suisse g\u00e9n\u00e8re actuellement chaque ann\u00e9e un produit int\u00e9rieur brut (PIB) particuli\u00e8rement \u00e9lev\u00e9, soit plus de 81\u2009000 USD par habitant (voir graphique\u00a01). \u00c0 cela s\u2019ajoute la place de choix occup\u00e9e par la Suisse dans divers classements de la comp\u00e9titivit\u00e9<a href=\"#footnote_2\" id=\"footnote-anchor_2\" class=\"inline-footnote__anchor\">[2]<\/a>. Or, contrairement \u00e0 d\u2019autres pays prosp\u00e8res, elle ne dispose pas de ressources consid\u00e9rables de mati\u00e8res premi\u00e8res naturelles. Dans toute discussion portant sur la politique \u00e9conomique, on ne saurait donc souligner assez \u00e0 quel point la forte performance \u00e9conomique et la prosp\u00e9rit\u00e9 de la Suisse ne vont pas de soi.&#13;<br \/>\n&#13;<br \/>\n&nbsp;&#13;<br \/>\n&#13;<br \/>\n<div class=\"legacy_chart chart--normal\" id=\"chart_95943_fr\"><\/div>\n        \n<script>\n        $(function () {\n            $('#chart_95943_fr').highcharts({\n                chart: {\n                    type: 'column',\n\t\t\t\t    style: {\n\t\t\t\t\t\tfontFamily: 'IBM Plex Sans Condensed, sans-serif',\n\t\t\t\t\t\tfontSize: '15px',\n\t\t\t\t    },\n                },\n                title: {\n                    text: ''\n                },\n                xAxis: {\n                    title: { text: '' },\n                    categories: [\"Norw\\u00e8ge\",\"Suisse\",\"Danemark\",\"Su\\u00e8de\",\"\\u00c9tats-Unis\",\"Pays-Bas\",\"Finlande\",\"Autriche\",\"Irlande\",\"Belgique\",\"Allemanie\",\"France\",\"Grande-Bretagne\",\"Japon\",\"Italie\",\"Espagne\"],\n                },\n                yAxis: {\n                    title: { text: '' },\n                },\n                plotOptions: {\n                    \n                },\n                exporting: {\n                    sourceHeight: 600,\n                },\n                series: [{ name: 'PIB',data: [100578,81276,59129,58014,53000,50815,49055,49038,48607,45537,44999,44098,39371,38467,34714,29150]}, ],\n\t\t\t\tcolors: [ '#327775', '#655c99', '#666666', '#4b8684', '#766ca4', '#999999', '#649795', '#887db1', '#cccccc', '#7ea8a7', '#9c92bf', '#e5e4e4', '#9bbcbc', '#b4a9ce', '#f6f4f4', '#bcd3d3', '#cdc5df' ]\n            });\n        });\n\t\t<\/script>\n    <div class=\"legacy_chart legacy_chart__print chart--normal\" id=\"chart_95943_fr_p\"><\/div>\n        \n<script>\n        $(function () {\n            $('#chart_95943_fr_p').highcharts({\n\t\t\t\tchart: {\n                    type: 'column',\n\t\t\t\t    style: {\n\t\t\t\t\t\tfontFamily: 'IBM Plex Sans Condensed, sans-serif',\n\t\t\t\t\t\tfontSize: '15px',\n\t\t\t\t    },\n                },\n                title: {\n                    text: ''\n                },\n                xAxis: {\n                    title: { text: '' },\n                    categories: [\"Norw\\u00e8ge\",\"Suisse\",\"Danemark\",\"Su\\u00e8de\",\"\\u00c9tats-Unis\",\"Pays-Bas\",\"Finlande\",\"Autriche\",\"Irlande\",\"Belgique\",\"Allemanie\",\"France\",\"Grande-Bretagne\",\"Japon\",\"Italie\",\"Espagne\"],\n                },\n                yAxis: {\n                    title: { text: '' },\n                },\n                plotOptions: {\n                    \n                },\n                exporting: {\n                    sourceHeight: 600,\n                },\n                series: [{ name: 'PIB',data: [100578,81276,59129,58014,53000,50815,49055,49038,48607,45537,44999,44098,39371,38467,34714,29150]}, ],\n\t\t\t\tcolors: [ '#327775', '#655c99', '#666666', '#4b8684', '#766ca4', '#999999', '#649795', '#887db1', '#cccccc', '#7ea8a7', '#9c92bf', '#e5e4e4', '#9bbcbc', '#b4a9ce', '#f6f4f4', '#bcd3d3', '#cdc5df' ]\n            });\n        });\n\t\t<\/script>\n    &#13;<\/p>\n<h2>Un succ\u00e8s d\u00fb \u00e0 de bonnes &shy;conditions-cadres<\/h2>\n<p>&#13;<br \/>\nLes raisons de cette \u00e9volution sont multiples<a href=\"#footnote_3\" id=\"footnote-anchor_3\" class=\"inline-footnote__anchor\">[3]<\/a>, mais il est indubitable que le cadre \u00e9conomique mis en place par l\u2019\u00c9tat joue un r\u00f4le crucial. Si les r\u00e9glementations officielles entravent excessivement le bon d\u00e9roulement des affaires, cela aura rapidement un impact direct sur la prosp\u00e9rit\u00e9 de la population. En revanche, si les conditions-cadres sont fix\u00e9es habilement, les perspectives sont tr\u00e8s prometteuses. La concurrence entre les agents \u00e9conomiques est l\u2019aiguillon principal d\u2019un d\u00e9veloppement durable de l\u2019\u00e9conomie.&#13;<br \/>\nSi l\u2019on revient sur la derni\u00e8re d\u00e9cennie, on peut dire que la politique suisse a g\u00e9n\u00e9ralement \u00e9t\u00e9 efficace en mati\u00e8re d\u2019\u00e9conomie. Cette derni\u00e8re s\u2019est redress\u00e9e extr\u00eamement rapidement apr\u00e8s la crise financi\u00e8re et s\u2019est ensuite d\u00e9velopp\u00e9e de mani\u00e8re \u00e9tonnante<a href=\"#footnote_4\" id=\"footnote-anchor_4\" class=\"inline-footnote__anchor\">[4]<\/a>. Sa performance est impressionnante, surtout si l\u2019on consid\u00e8re la situation de ses voisins.&#13;<br \/>\nRappeler que la situation actuelle ne durera pas ind\u00e9finiment est une lapalissade \u00e9conomique. Les structures de l\u2019\u00e9conomie mondiale changent \u00e0 une vitesse foudroyante avec l\u2019\u00e9mergence des Bric (Br\u00e9sil, Russie, Inde, Chine); les relations de la Suisse avec ses principaux partenaires commerciaux \u2013 l\u2019UE, par exemple\u00a0\u2013 sont sans cesse mises \u00e0 l\u2019\u00e9preuve; le progr\u00e8s technologique avance \u00e0 grands pas. Toute \u00e9conomie doit s\u2019adapter en permanence \u00e0 ces \u00e9volutions et r\u00e9am\u00e9nager ses structures. Cela ne peut cependant se produire que si le corset r\u00e9glementaire n\u2019est pas trop serr\u00e9 et que l\u2019on r\u00e9forme la politique \u00e9conomique mod\u00e9r\u00e9ment, mais constamment.&#13;<\/p>\n<h2>Objectifs de la politique de croissance<\/h2>\n<p>&#13;<br \/>\nLe Conseil f\u00e9d\u00e9ral a toujours \u00e9t\u00e9 conscient de cette n\u00e9cessit\u00e9. Depuis quelque temps, il attache beaucoup d\u2019importance \u00e0 une politique \u00e9conomique ax\u00e9e sur le long terme et favorable \u00e0 la concurrence. En particulier depuis la faiblesse persistante de la croissance au cours des ann\u00e9es nonante, le gouvernement a \u00e9tudi\u00e9 divers projets de r\u00e9forme dont il attendait un effet positif sur le d\u00e9veloppement \u00e9conomique du pays. Diverses mesures, cens\u00e9es stimuler, en particulier \u00e0 long terme, la croissance de la productivit\u00e9 du travail, ont \u00e9t\u00e9 regroup\u00e9es sous le titre de \u00abpolitique de croissance\u00bb.&#13;<br \/>\nD\u00e8s cette \u00e9poque, il \u00e9tait clair pour le Conseil f\u00e9d\u00e9ral qu\u2019une politique \u00e9conomique durable et \u00e0 long terme devrait veiller sp\u00e9cialement \u00e0 la qualit\u00e9 \u2013 et non \u00e0 la seule quantit\u00e9 \u2013 de la croissance \u00e9conomique. La performance \u00e9conomique ne s\u2019am\u00e9liorerait pas seulement en augmentant l\u2019emploi et le capital, mais aussi et surtout en usant plus rationnellement des facteurs de production. L\u2019accroissement de la concurrence sur le march\u00e9 int\u00e9rieur devrait \u00eatre le principal moteur de cette \u00e9volution.&#13;<br \/>\nMalgr\u00e9 cela, la notion de croissance \u00e9conomique\u00a0et surtout les \u00abeffets collat\u00e9raux\u00bb que l\u2019on y associe\u00a0n\u2019ont jamais \u00e9t\u00e9 autant critiqu\u00e9s qu\u2019aujourd\u2019hui; du moins est-ce notre impression subjective. Or, une partie de cette critique passe \u00e0 c\u00f4t\u00e9 du sujet. Ainsi, les questions li\u00e9es au \u00abstress d\u00e9mographique\u00bb se rapportent plut\u00f4t \u00e0 la croissance de la population. Il n\u2019en reste pas moins que les d\u00e9cideurs politiques doivent toujours assumer les pr\u00e9occupations de la population et les prendre au s\u00e9rieux.&#13;<\/p>\n<h2>La politique de croissance peut revendiquer quelques succ\u00e8s\u2009\u2026<\/h2>\n<p>&#13;<br \/>\nGr\u00e2ce \u00e0 sa politique de croissance, le Conseil f\u00e9d\u00e9ral a pu enregistrer divers succ\u00e8s en politique \u00e9conomique. Ainsi, deux r\u00e9formes de la fiscalit\u00e9 des entreprises (volets I et II) ont constitu\u00e9 des jalons importants pour rehausser l\u2019attrait de la place \u00e9conomique suisse. Sur le plan du march\u00e9 int\u00e9rieur, la r\u00e9vision de la loi correspondante a \u00e9t\u00e9 un acte important. L\u2019extension du r\u00e9seau d\u2019accords de libre-\u00e9change, qui permet aux entreprises de diversifier leurs d\u00e9bouch\u00e9s \u00e0 l\u2019\u00e9tranger, le fut \u00e9galement pour l\u2019industrie exportatrice. Une place particuli\u00e8re revient \u00e0 l\u2019introduction du frein \u00e0 l\u2019endettement\u00a0\u2013 et en particulier \u00e0 la planification financi\u00e8re \u00e0 moyen et long termes qui y est li\u00e9e\u00a0et qui vise \u00e0 \u00e9viter les d\u00e9ficits structurels r\u00e9currents.&#13;<\/p>\n<h2>\u2026\u2009mais plusieurs r\u00e9formes restent inabouties<\/h2>\n<p>&#13;<br \/>\nMis \u00e0 part ces succ\u00e8s, toute une s\u00e9rie de r\u00e9formes ont \u00e9t\u00e9 lanc\u00e9es qui, pour diverses raisons, n\u2019ont pas encore \u00e9t\u00e9 mises en \u0153uvre. On citera l\u2019introduction d\u2019un taux unique de TVA, la 11e r\u00e9vision de l\u2019AVS, l\u2019ouverture compl\u00e8te du march\u00e9 de l\u2019\u00e9lectricit\u00e9, l\u2019assouplissement du monopole de la Poste pour les lettres jusqu\u2019\u00e0 50 g ou encore un syst\u00e8me de financement des transports qui reporte davantage les co\u00fbts sur les utilisateurs.&#13;<br \/>\nEn r\u00e9sum\u00e9, on peut dire que la politique de croissance a \u00e9t\u00e9 un des moteurs de notre expansion \u00e9conomique. Le regard que l\u2019on peut exercer sur la mise en \u0153uvre des nombreuses mesures d\u00e9cid\u00e9es \u00e0 ce niveau d\u00e9bouche, toutefois, sur un bilan mitig\u00e9, comme le montre le tableau 1.&#13;<br \/>\n&#13;<br \/>\n<a href=\"http:\/\/dievolkswirtschaft.ch\/content\/uploads\/2015\/02\/Tabelle_Jaeggi_1_FR.png\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-10058 size-full\" src=\"http:\/\/dievolkswirtschaft.ch\/content\/uploads\/2015\/02\/Tabelle_Jaeggi_1_FR.png\" alt=\"Tabelle_Jaeggi_1_FR\" width=\"1530\" height=\"2298\" \/><\/a>&#13;<\/p>\n<h2>Lutte contre les aggravations\u00a0et l\u2019exc\u00e8s de r\u00e9glementations<\/h2>\n<p>&#13;<br \/>\nLes derni\u00e8res d\u00e9cennies ont donc nettement d\u00e9montr\u00e9 qu\u2019il est fonci\u00e8rement difficile de r\u00e9former la politique \u00e9conomique suisse en profondeur. On ne saurait cependant juger la situation en bloc et n\u00e9gativement. La stabilit\u00e9 des conditions-cadres peut aussi am\u00e9liorer la s\u00e9curit\u00e9 du droit et la planification des entreprises, ce qui contribue au bon d\u00e9veloppement de l\u2019\u00e9conomie\u00a0\u2013 pour autant que ces conditions restent convenables. D\u2019autre part, un nombre suffisant de petits pas peut aussi conduire au but. Ces derni\u00e8res ann\u00e9es, cependant, certains \u00e9v\u00e9nements n\u2019ont pas seulement compliqu\u00e9 la progression, mais \u00e9galement remis en cause le cadre juridique existant.&#13;<br \/>\nOn citera en tout premier lieu les nombreuses initiatives populaires \u00e0 incidence \u00e9conomique, comme l\u2019initiative 1:12, celle contre l\u2019immigration de masse, celle sur le salaire minimum, celle en faveur d\u2019un revenu de base inconditionnel ou l\u2019initiative Ecopop. Toutes ont en commun de poursuivre un objectif sp\u00e9cifique\u00a0\u2013 et parfois souhaitable\u00a0\u2013, qui endommagerait fortement le cadre \u00e9conomique existant. Ainsi, les accords bilat\u00e9raux I sont tout particuli\u00e8rement menac\u00e9s par l\u2019acceptation de l\u2019initiative contre l\u2019immigration de masse. Leur d\u00e9nonciation n\u2019aboutirait pas seulement \u00e0 des dommages \u00e9conomiques consid\u00e9rables pour la Suisse, mais d\u00e9truirait encore le cadre juridique jusqu\u2019ici stable et s\u00fbr dans lequel \u00e9voluent nos entreprises.&#13;<br \/>\nIl faut \u00e9galement mentionner les efforts actuels de r\u00e9gulation du secteur financier. Dans le monde entier, les l\u00e9gislateurs cherchent \u00e0 tirer les le\u00e7ons de la crise financi\u00e8re et \u00e0 ma\u00eetriser celles qui pourraient advenir par de nouvelles r\u00e9glementations. Ces derni\u00e8res ann\u00e9es, une v\u00e9ritable mar\u00e9e de nouvelles dispositions ont donc \u00e9t\u00e9 \u00e9dict\u00e9es pour renforcer la stabilit\u00e9 du secteur financier. Ce faisant, on a peu pris garde au fait que plusieurs projets entra\u00eenaient des surco\u00fbts pour les \u00e9tablissements bancaires et leurs clients. \u00c0 l\u2019heure actuelle, il est difficile de pr\u00e9dire quelles cons\u00e9quences cela aura \u00e0 moyen et long termes sur la structure du secteur.&#13;<\/p>\n<h2>Une n\u00e9cessit\u00e9 bien pr\u00e9sente de r\u00e9formes \u00e9conomiques<\/h2>\n<p>&#13;<br \/>\nComme cela a \u00e9t\u00e9 mentionn\u00e9 en exorde, la Suisse fait actuellement bonne figure en comparaison avec l\u2019\u00e9tranger. Comment peut-elle am\u00e9liorer son cadre \u00e9conomique et se muscler face au d\u00e9veloppement de la concurrence internationale? Une approche pragmatique permet de dire que les domaines \u00e0 r\u00e9former ne manquent pas. Nous en discuterons bri\u00e8vement quelques-uns<a href=\"#footnote_5\" id=\"footnote-anchor_5\" class=\"inline-footnote__anchor\">[5]<\/a>.&#13;<\/p>\n<h2>Concurrence sur le march\u00e9 int\u00e9rieur<\/h2>\n<p>&#13;<br \/>\nVoyons d\u2019abord le march\u00e9 int\u00e9rieur. Il n\u2019est pas \u00e9tonnant de constater que sa productivit\u00e9 reste \u00e0 la tra\u00eene de celle, extr\u00eamement forte, de l\u2019industrie exportatrice. Cette derni\u00e8re doit en effet se mesurer \u00e0 de nombreux concurrents internationaux, alors que beaucoup de branches int\u00e9rieures ne connaissent pas la m\u00eame pression. Citons par exemple les infrastructures de r\u00e9seau (rail, t\u00e9l\u00e9communications, poste, gaz ou \u00e9lectricit\u00e9, etc.), qui sont en grande partie aux mains de l\u2019\u00c9tat (directement ou indirectement) et ne sont expos\u00e9es que partiellement \u00e0 la concurrence.&#13;<br \/>\nLe potentiel de r\u00e9forme est \u00e9galement immense en ce qui concerne les droits de douane et les quotas d\u2019importation qui prot\u00e8gent toujours fortement l\u2019agriculture nationale contre la concurrence \u00e9trang\u00e8re. Cela pourrait contribuer \u00e0 d\u00e9manteler l\u2019\u00eelot de chert\u00e9 suisse. Le Conseil f\u00e9d\u00e9ral entendait aussi lutter contre ce probl\u00e8me avec le principe du \u00abCassis de Dijon\u00bb, qui permet d\u2019admettre automatiquement en Suisse des produits d\u00e9j\u00e0 autoris\u00e9s dans l\u2019UE. Les nombreuses d\u00e9rogations l\u2019ont, toutefois, si fortement dilu\u00e9 qu\u2019un grand nombre d\u2019entraves techniques au commerce subsistent et contribuent \u00e0 verrouiller le march\u00e9 suisse. Il est probable qu\u2019au printemps 2015, le Conseil national d\u00e9cidera si les denr\u00e9es alimentaires doivent \u00eatre g\u00e9n\u00e9ralement exclues du champ d\u2019application du principe du \u00abCassis de Dijon\u00bb.&#13;<\/p>\n<h2>Entreprises d\u2019\u00c9tat concurrentes du secteur priv\u00e9<\/h2>\n<p>&#13;<br \/>\nOn a jusqu\u2019ici peu pr\u00eat\u00e9 attention au grand nombre d\u2019entreprises d\u2019\u00c9tat qui ont \u00e9tendu leur mandat ou l\u2019interpr\u00e8tent largement, entrant ainsi en concurrence avec les fournisseurs priv\u00e9s. La seule chose r\u00e9jouissante est que, gr\u00e2ce \u00e0 la concurrence avec le secteur priv\u00e9, ces soci\u00e9t\u00e9s travaillent plus efficacement que si elles disposaient d\u2019un monopole r\u00e9galien. D\u2019un autre c\u00f4t\u00e9, les entreprises publiques b\u00e9n\u00e9ficient souvent de garanties ou de subventions sur des march\u00e9s comp\u00e9titifs, ce qui diminue leur risque entrepreneurial. En fin de compte, les co\u00fbts d\u2019un \u00e9chec pourraient \u00eatre assum\u00e9s par les contribuables, ce qui procure \u00e0 ces entreprises un avantage comp\u00e9titif par rapport \u00e0 leurs concurrentes du secteur priv\u00e9. On citera par exemple les banques cantonales au b\u00e9n\u00e9fice d\u2019une garantie d\u2019\u00c9tat, la radio et la t\u00e9l\u00e9vision publiques, les assurances-b\u00e2timents, les services de m\u00e9t\u00e9orologie ou les fournisseurs d\u2019\u00e9lectricit\u00e9.&#13;<\/p>\n<h2>Un foisonnement d\u00e9sordonn\u00e9 d\u2019aides \u00e9tatiques<\/h2>\n<p>&#13;<br \/>\nIl y a \u00e9galement distorsion de la concurrence quand des entreprises ou des branches b\u00e9n\u00e9ficient de subventions ou d\u2019autres aides de l\u2019\u00c9tat. Il peut \u00eatre s\u00e9duisant d\u2019attirer des soci\u00e9t\u00e9s en leur promettant un soutien \u00e9tatique, mais un tel syst\u00e8me n\u2019est pas acceptable \u00e0 moyen et \u00e0 long termes, parce qu\u2019il peut d\u00e9favoriser les autres entreprises et niveler les d\u00e9penses de l\u2019\u00c9tat vers le bas. M\u00e9nager de bonnes conditions-cadres est plus efficace \u00e9conomiquement.&#13;<br \/>\nLa Suisse ne conna\u00eet pas de v\u00e9ritable droit aux aides d\u2019\u00c9tat, qui couvre toutes les collectivit\u00e9s territoriales. La transparence n\u2019existe qu\u2019au niveau f\u00e9d\u00e9ral, par exemple dans l\u2019agriculture. Cela vaudrait donc la peine d\u2019examiner s\u2019il est possible d\u2019accro\u00eetre la transparence du syst\u00e8me et s\u2019il ne convient pas de r\u00e9duire progressivement les subventions inefficaces du point de vue \u00e9conomique.&#13;<\/p>\n<h2>Un potentiel inexploit\u00e9 en ce qui concerne l\u2019ouverture des march\u00e9s<\/h2>\n<p>&#13;<br \/>\nSi la concurrence doit se renforcer sur le march\u00e9 int\u00e9rieur, il faut aussi ouvrir la Suisse \u00e0 l\u2019ext\u00e9rieur, car le potentiel est consid\u00e9rable en ce domaine. Gr\u00e2ce \u00e0 l\u2019accord de libre-\u00e9change et \u00e0 ses accords bilat\u00e9raux avec l\u2019UE, la Suisse dispose d\u2019une base solide pour commercer avec ses voisins. Or, ces relations sont remises en question par l\u2019acceptation de l\u2019initiative contre l\u2019immigration de masse. En outre, aucun cadre institutionnel n\u2019est actuellement en vue pour une adaptation dynamique du droit, alors qu\u2019il s\u2019agit l\u00e0, selon l\u2019UE, d\u2019une condition n\u00e9cessaire pour de nouveaux accords. De nouvelles possibilit\u00e9s en ce domaine existent, en particulier dans les services. Or, c\u2019est surtout un accord sur les \u00e9changes de services financiers qui a retenu l\u2019attention politique ces derniers temps<a href=\"#footnote_6\" id=\"footnote-anchor_6\" class=\"inline-footnote__anchor\">[6]<\/a>.&#13;<br \/>\nLes possibilit\u00e9s d\u2019une nouvelle ouverture sont aussi limit\u00e9es par la position d\u00e9fensive de la Suisse en mati\u00e8re de lib\u00e9ralisation du commerce des produits agricoles. Cela restreint aussi les perspectives d\u2019exportation du secteur agro-alimentaire et emp\u00eache de n\u00e9gocier avec d\u2019autres partenaires \u00e9conomiques importants. Enfin, l\u2019un des plus grands d\u00e9fis de la politique commerciale r\u00e9side dans les n\u00e9gociations actuellement en cours entre l\u2019UE et les \u00c9tats-Unis en vue d\u2019un Partenariat transatlantique de commerce et d\u2019investissement (PTCI, ou TTIP en anglais). Un tel accord aurait indubitablement un effet significatif sur la Suisse et son industrie exportatrice.&#13;<\/p>\n<h2>Conclusion: il y aurait beaucoup \u00e0 faire<\/h2>\n<p>&#13;<br \/>\nLa Suisse est actuellement en excellente forme, mais cela ne devrait pas l\u2019inciter \u00e0 se reposer sur ses lauriers et \u00e0 n\u00e9gliger les r\u00e9formes. Comme le montre l\u2019exemple de divers pays de l\u2019UE, il n\u2019est pas plus facile d\u2019imposer des r\u00e9formes structurelles en p\u00e9riode de faible conjoncture. Au contraire, les manquements commis pendant les ann\u00e9es de vaches grasses se paient au prix fort. Contrairement \u00e0 de nombreux pays europ\u00e9ens, la Suisse est en position favorable, mais il faut savoir en profiter. C\u2019est \u00e0 cette seule condition que l\u2019on pr\u00e9servera\u00a0\u2013 voire augmentera\u00a0\u2013 durablement la prosp\u00e9rit\u00e9 de la population.<\/p>\n<ol class=\"footnote\"><li id=\"footnote_1\" class=\"footnote--item\">www.oecd.org\/fr\/regional\/politique-regionale.&nbsp;<a href=\"#footnote-anchor_1\" class=\"inline-footnote__anchor hidden-print\">[<span class=\"icon-arrow-up\"><\/span>]<\/a><\/li><li id=\"footnote_2\" class=\"footnote--item\">Exemples: n\u00b0 1 dans le WEF Global Competitiveness Index 2014-2015, n\u00b0 2 dans le IMD World Competitiveness Scoreboard 2014, n\u00b0 1 dans le Innovation Union Scoreboard 2014 de la Commission europ\u00e9enne.&nbsp;<a href=\"#footnote-anchor_2\" class=\"inline-footnote__anchor hidden-print\">[<span class=\"icon-arrow-up\"><\/span>]<\/a><\/li><li id=\"footnote_3\" class=\"footnote--item\">Voir p. ex. R. J. Breiding et G. Schwarz (2011), Wirtschaftswunder Schweiz, NZZ Verlag, Zurich; Secr\u00e9tariat d\u2019\u00c9tat \u00e0 l\u2019\u00e9conomie (2002), Le rapport sur la croissance. D\u00e9terminants de la croissance \u00e9conomique de la Suisse et jalons pour une politique \u00e9conomique ax\u00e9e sur la croissance, Grundlagen der Wirtschafts\u00adpolitik no 3F.&nbsp;<a href=\"#footnote-anchor_3\" class=\"inline-footnote__anchor hidden-print\">[<span class=\"icon-arrow-up\"><\/span>]<\/a><\/li><li id=\"footnote_4\" class=\"footnote--item\">Voir l\u2019article de Frank Schmidbauer, pp. 4ss de ce \u00adnum\u00e9ro.&nbsp;<a href=\"#footnote-anchor_4\" class=\"inline-footnote__anchor hidden-print\">[<span class=\"icon-arrow-up\"><\/span>]<\/a><\/li><li id=\"footnote_5\" class=\"footnote--item\">Voir le rapport \u00abPrincipes pour une nouvelle politique de croissance\u00bb sur www.seco.admin.ch.&nbsp;<a href=\"#footnote-anchor_5\" class=\"inline-footnote__anchor hidden-print\">[<span class=\"icon-arrow-up\"><\/span>]<\/a><\/li><li id=\"footnote_6\" class=\"footnote--item\">Groupe d\u2019experts \u00abD\u00e9veloppement de la strat\u00e9gie en mati\u00e8re de services financiers\u00bb, rapport final, 1er\u00a0d\u00e9cembre 2014.&nbsp;<a href=\"#footnote-anchor_6\" class=\"inline-footnote__anchor hidden-print\">[<span class=\"icon-arrow-up\"><\/span>]<\/a><\/li><\/ol>","protected":false},"excerpt":{"rendered":"<p>Toute statistique internationale en mati\u00e8re de prosp\u00e9rit\u00e9 le montre clairement: la Suisse fait partie du peloton de t\u00eate plan\u00e9taire. Ainsi, l\u2019indice de l\u2019OCDE du bien-\u00eatre social et \u00e9conomique met nettement en \u00e9vidence le fait que la Suisse l\u2019emporte dans plusieurs domaines concernant le niveau de vie. Notre pays se d\u00e9fend bien aussi sur le plan [&hellip;]<\/p>","protected":false},"author":3072,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"ep_exclude_from_search":false,"footnotes":""},"post__type":[81,83],"post_opinion":[],"post_serie":[],"post_content_category":[],"post_content_subject":[],"acf":{"seco_author":3072,"seco_co_author":null,"author_override":"","seco_author_post_ocupation_year":"","seco_author_post_occupation_de":"Dr. rer. oec., Leiter Ressort Wachstum und Wettbewerbspolitik, Staatssekretariat f\u00fcr Wirtschaft (Seco), Bern","seco_author_post_occupation_fr":"Chef du secteur Croissance et politique de la concurrence, Secr\u00e9tariat d\u2019\u00c9tat \u00e0 l\u2019\u00e9conomie (Seco), Berne","seco_co_authors_post_ocupation":null,"short_title":"","post_lead":"La Suisse est l\u2019un des pays les plus prosp\u00e8res du monde. Pour que cette assertion reste vraie, &#13;\nil faut que ses entreprises, qui assurent cette prosp\u00e9rit\u00e9, continuent \u00e0 b\u00e9n\u00e9ficier des meilleures conditions-cadres possibles, car ce n\u2019est qu\u2019ainsi qu\u2019elles subsisteront face \u00e0 la concurrence tant int\u00e9rieure qu\u2019\u00e9trang\u00e8re. Ce constat force aussi la politique \u00e9conomique \u00e0 \u00e9voluer constamment. Or, les r\u00e9formes fondamentales et de grande envergure ne sont pas dans nos habitudes. Il est donc important de proc\u00e9der pas \u00e0 pas, mais constamment, \u00e0 des r\u00e9formes structurelles judicieuses.","post_hero_image_description":"","post_hero_image_description_copyright_de":"","post_hero_image_description_copyright_fr":"","post_references_literature":"","post_kasten":null,"post_notes_for_print":"","first_teaser_header_de":"","first_teaser_header_fr":"","first_teaser_text_de":"","first_teaser_text_fr":"","second_teaser_header_de":"","second_teaser_header_fr":"","second_teaser_text_de":"","second_teaser_text_fr":"","kseason_de":"","kseason_fr":"","post_in_pdf":147539,"main_focus":[156647,157268],"serie_email":null,"frontpage_slider_bild":"","artikel_bild-slider":null,"legacy_id":"10054","post_abstract":"","magazine_issue":"20150101","seco_author_reccomended_post":null,"redaktoren":null,"korrektor":null,"planned_publication_date":null,"original_files":null,"external_release_for_author":"19700101","external_release_for_author_time":"00:00:00","link_for_external_authors":"https:\/\/dievolkswirtschaft.ch\/exedit\/54daf9ef518f5"},"_links":{"self":[{"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/posts\/147536"}],"collection":[{"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/users\/3072"}],"replies":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/comments?post=147536"}],"version-history":[{"count":1,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/posts\/147536\/revisions"}],"predecessor-version":[{"id":188711,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/posts\/147536\/revisions\/188711"}],"acf:post":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/main_focus_post\/157268"},{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/main_focus_post\/156647"}],"acf:user":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/users\/3072"}],"wp:attachment":[{"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/media?parent=147536"}],"wp:term":[{"taxonomy":"post__type","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/post__type?post=147536"},{"taxonomy":"post_opinion","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/post_opinion?post=147536"},{"taxonomy":"post_serie","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/post_serie?post=147536"},{"taxonomy":"post_content_category","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/post_content_category?post=147536"},{"taxonomy":"post_content_subject","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/post_content_subject?post=147536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}