{"id":152524,"date":"2009-09-01T12:00:00","date_gmt":"2009-09-01T12:00:00","guid":{"rendered":"https:\/\/dievolkswirtschaft.ch\/2009\/09\/dietl-4\/"},"modified":"2023-08-24T01:03:32","modified_gmt":"2023-08-23T23:03:32","slug":"dietl-4","status":"publish","type":"post","link":"https:\/\/dievolkswirtschaft.ch\/fr\/2009\/09\/dietl-4\/","title":{"rendered":"Les liens entre le service universel et la concurrence"},"content":{"rendered":"<p>La lib\u00e9ralisation du march\u00e9 postal suscite fr\u00e9quemment la crainte que les normes minimales du service public ne soient plus garanties. C&#8217;est pourquoi le mandat qui oblige la Poste \u00e0 assurer la desserte de base constitue un \u00e9l\u00e9ment central de la nouvelle l\u00e9gislation postale pr\u00e9sent\u00e9e par le Conseil f\u00e9d\u00e9ral. Cependant, sa mise en oeuvre se heurte \u00e0 certaines difficult\u00e9s pratiques: la d\u00e9finition de ce mandat, son ampleur et son type de financement influencent consid\u00e9rablement le fonctionnement de la concurrence.<img fetchpriority=\"high\" decoding=\"async\" class=\"article_rect\" src=\"\/dynBase\/images\/article_rect\/200909_24_Dietl_01.eps.jpg\" alt=\"\" width=\"370\" height=\"253\" \/>&#13;<br \/>\n&#13;<br \/>\nLa Suisse accuse un temps de retard sur l&#8217;Europe en mati\u00e8re de lib\u00e9ralisation du march\u00e9 postal. Alors que celui-ci devrait \u00eatre compl\u00e8tement ouvert dans la plupart des pays europ\u00e9ens d&#8217;ici fin 2010, la loi sur la poste pr\u00e9sent\u00e9e par le Conseil f\u00e9d\u00e9ral planifie son ouverture pour l&#8217;ann\u00e9e 2013 au plus t\u00f4t. Le monopole des lettres de la Poste suisse a \u00e9t\u00e9 abaiss\u00e9 de 100 \u00e0 50 grammes le 1er juillet 2009 &#8211; il n&#8217;en reste pas moins qu&#8217;environ 75% d&#8217;entre elles continuent d&#8217;\u00e9chapper \u00e0 toute concurrence. L&#8217;ouverture int\u00e9grale du march\u00e9 fera l&#8217;objet d&#8217;un arr\u00eat\u00e9 f\u00e9d\u00e9ral qui, comme dans le cas du march\u00e9 de l&#8217;\u00e9lectricit\u00e9, sera soumis au r\u00e9f\u00e9rendum facultatif.\u00a0Ces h\u00e9sitations montrent \u00e0 quel point la lib\u00e9ralisation du march\u00e9 postal est un th\u00e8me politique sensible. Les pays de l&#8217;Union europ\u00e9enne (UE) et les \u00c9tats-Unis en ont d\u00e9j\u00e0 fait l&#8217;exp\u00e9rience. Cela provient du fait qu&#8217;il s&#8217;agit d&#8217;un secteur \u00e0 haute intensit\u00e9 de main-d&#8217;oeuvre. En r\u00e8gle g\u00e9n\u00e9rale, les entreprises postales figurent parmi les plus gros employeurs d&#8217;un pays. De nombreux contrats de travail sont donc directement touch\u00e9s par la lib\u00e9ralisation du march\u00e9 ainsi que par les changements qui l&#8217;accompagnent aux plans commercial et structurel.&#13;<\/p>\n<h2>Service public et structure des co\u00fbts<\/h2>\n<p>&#13;<br \/>\nOutre sa haute intensit\u00e9 de main-d&#8217;oeuvre, le secteur postal se distingue surtout des autres branches pour deux raisons: le service public et la structure sp\u00e9cifique des co\u00fbts. L&#8217;ouverture du march\u00e9 doit faire na\u00eetre une concurrence; en m\u00eame temps, il importe que les prestations du service universel continuent d&#8217;\u00eatre disponibles sur l&#8217;ensemble du territoire. On admet implicitement que tel ne serait pas le cas dans un r\u00e9gime de libre concurrence, alors que le public en a besoin. Ces prestations sont \u00e9galement connues sous les termes de \u00abservice public\u00bb, \u00abservice universel\u00bb ou \u00abdesserte de base\u00bb. On les met souvent en relation avec l&#8217;accessibilit\u00e9 des offices de poste et des bo\u00eetes aux lettres, avec les objectifs de qualit\u00e9 en mati\u00e8re de d\u00e9lais de distribution ainsi qu&#8217;avec des tarifs uniformes et ind\u00e9pendants de la distance &#8211; les r\u00e9gions p\u00e9riph\u00e9riques ne doivent pas \u00eatre p\u00e9nalis\u00e9es par la lib\u00e9ralisation. Le \u00abprestataire universel\u00bb (g\u00e9n\u00e9ralement l&#8217;ancien monopoleur) peut \u00eatre explicitement charg\u00e9 de les fournir, afin de garantir une desserte de base qui couvre l&#8217;ensemble du pays.\u00a0La question du service public est \u00e9troitement li\u00e9e \u00e0 l&#8217;aspect des co\u00fbts. Il faut prendre en consid\u00e9ration le fait que, dans le secteur postal, ces derniers sont, en priorit\u00e9, influenc\u00e9s par les \u00e9conomies d&#8217;\u00e9chelle et de densit\u00e9. Par \u00e9conomies de densit\u00e9, on entend le fait que les co\u00fbts des prestations postales s&#8217;amenuisent \u00e0 mesure que la densit\u00e9 de la population augmente. La distribution d&#8217;une lettre engendre des frais nettement moins \u00e9lev\u00e9s si son destinataire se trouve \u00e0 Zurich plut\u00f4t qu&#8217;en Valais. Compte tenu de ces \u00e9conomies de densit\u00e9, tout tarif standard exig\u00e9 par le mandat de service public suppose un subventionnement crois\u00e9 des r\u00e9gions rurales. Des rendements d&#8217;\u00e9chelle interviennent lorsque les co\u00fbts unitaires diminuent avec l&#8217;augmentation de la quantit\u00e9 de courrier \u00e0 acheminer. Ils ne sont pas de la m\u00eame ampleur dans tout le secteur postal. En ce qui concerne les services de coursier, les envois express et les colis, ces \u00e9conomies sont nettement plus faibles que dans le domaine des lettres. C&#8217;est la raison pour laquelle la concurrence fonctionne relativement bien depuis la lib\u00e9ralisation des services de coursier, des envois express et des colis. Il y a davantage de probl\u00e8mes dans le domaine des lettres, o\u00f9 les \u00e9conomies d&#8217;\u00e9chelle sont beaucoup plus cons\u00e9quentes. Leur niveau n&#8217;est, toutefois, pas le m\u00eame sur l&#8217;ensemble de la cha\u00eene de valeur. En fait, elles se concentrent surtout sur le domaine de la distribution (voir encadr\u00e9 1 Pour les prestations postales (lettres), la cha\u00eene de valeur est compos\u00e9e pour l&#8217;essentiel des maillons suivants: collecte (environ 12% des co\u00fbts), triage \u00e0 l&#8217;entr\u00e9e et \u00e0 la sortie (15%), transport (7%) et distribution (50%). Les 16% restants sont constitu\u00e9s par les co\u00fbts indirects. Ainsi, la partie de loin la plus importante de la valeur ajout\u00e9e &#8211; et donc aussi le principal potentiel d&#8217;am\u00e9lioration de l&#8217;efficience par la concurrence &#8211; se trouve dans le domaine de la distribution. C&#8217;est justement l\u00e0 que les avantages li\u00e9s \u00e0 la taille (\u00e9conomies d&#8217;\u00e9chelle) jouent le plus grand r\u00f4le. La mise en place d&#8217;un r\u00e9seau de distribution sur l&#8217;ensemble du territoire entra\u00eene des co\u00fbts (fixes) \u00e9lev\u00e9s. Un facteur planifie g\u00e9n\u00e9ralement sa tourn\u00e9e en fonction d&#8217;un certain parcours. S&#8217;il y a une lettre de plus \u00e0 acheminer, cela ne change pratiquement rien aux co\u00fbts de la distribution, puisque le facteur ne va pas modifier son itin\u00e9raire pour d\u00e9livrer la lettre suppl\u00e9mentaire et que son temps de travail reste donc le m\u00eame. Dans ce domaine, les rendements d&#8217;\u00e9chelle d\u00e9pendent du volume du courrier et de la fr\u00e9quence de la distribution. Ils augmentent donc si cette fr\u00e9quence diminue, puisque le nombre de lettres distribu\u00e9es lors de chaque tourn\u00e9e est alors plus \u00e9lev\u00e9 et que les co\u00fbts moyens, eux, s&#8217;inscrivent \u00e0 la baisse.).&#13;<\/p>\n<h2>\u00c9conomies d&#8217;\u00e9chelle et de densit\u00e9 sur le \u00abdernier kilom\u00e8tre\u00bb<\/h2>\n<p>&#13;<br \/>\nEn raison de la structure sp\u00e9cifique des co\u00fbts dans le secteur postal, le maillon \u00abdistribution\u00bb de la cha\u00eene de valeur est comparable au dernier kilom\u00e8tre dans le domaine des t\u00e9l\u00e9communications. S&#8217;il est absurde \u00e9conomiquement d&#8217;enfouir dans le sol plusieurs raccordements domestiques, il l&#8217;est tout autant de faire distribuer des lettres par plusieurs facteurs concurrents. Par analogie avec le march\u00e9 des t\u00e9l\u00e9communications, on pourrait donc garantir en mati\u00e8re de prestations postales le libre acc\u00e8s au dernier kilom\u00e8tre\u00a0de l&#8217;ancien monopoleur. Les concurrents n&#8217;auraient pas leur propre service de distribution. Ils introduiraient leurs lettres dans la fili\u00e8re de l&#8217;ancien monopoleur, lequel se chargerait contre r\u00e9mun\u00e9ration (\u00abprix de l&#8217;utilisation du r\u00e9seau\u00bb) de les faire parvenir \u00e0 destination. Ce sch\u00e9ma rec\u00e8le toutefois le danger d&#8217;un acc\u00e8s s\u00e9lectif au r\u00e9seau: de nouveaux venus sur le march\u00e9 pourraient n&#8217;acheminer des lettres que vers les villes int\u00e9ressantes, profitant ainsi des \u00e9conomies naturellement inh\u00e9rentes \u00e0 la quantit\u00e9 et \u00e0 la densit\u00e9; dans les r\u00e9gions rurales, en revanche, ils confieraient les lettres au r\u00e9seau de distribution de l&#8217;ancien monopoleur. \u00c9tant donn\u00e9 la concurrence r\u00e9gnant dans les villes \u00e0 forte densit\u00e9 de population, celui-ci n&#8217;aurait alors pas la marge b\u00e9n\u00e9ficiaire suffisante pour financer le subventionnement crois\u00e9 des tarifs (r\u00e9duits) dans les zones rurales. Le syst\u00e8me de tarif unique pour l&#8217;ensemble du pays, d\u00e9crit ci-dessus, serait menac\u00e9 dans de telles conditions.\u00a0Si l&#8217;on tient au service public, et donc au tarif standard, un dilemme se pose: en ouvrant le march\u00e9 des lettres \u00e0 d&#8217;autres entreprises et en leur garantissant l&#8217;acc\u00e8s au r\u00e9seau de distribution de la Poste, on peut certes mieux exploiter les avantages de la concurrence, comme la discipline des co\u00fbts, l&#8217;orientation client et la dynamique de la branche. Il faudrait alors que le financement du service public soit assur\u00e9 s\u00e9par\u00e9ment. Il convient, par ailleurs, de se demander si le prix d&#8217;utilisation du r\u00e9seau ne devrait pas faire l&#8217;objet d&#8217;une r\u00e9gulation, pour \u00e9viter que l&#8217;ancien monopoleur ne puisse tenir syst\u00e9matiquement ses concurrents \u00e0 l&#8217;\u00e9cart du march\u00e9. \u00c0\u00a0l&#8217;inverse, si l&#8217;on ne garantit pas aux autres entreprises un acc\u00e8s l\u00e9gal au r\u00e9seau, il est peu probable qu&#8217;une concurrence puisse v\u00e9ritablement s&#8217;installer, compte tenu des \u00e9conomies d&#8217;\u00e9chelle dont profite l&#8217;op\u00e9rateur historique.&#13;<\/p>\n<h2>Le monopole de la distribution aux \u00c9tats-Unis<\/h2>\n<p>&#13;<br \/>\nLes \u00c9tats-Unis ont \u00abr\u00e9solu\u00bb ce dilemme de la mani\u00e8re suivante: dans le domaine des lettres, ils n&#8217;ont lib\u00e9ralis\u00e9 que les maillons de la cha\u00eene de valeur qui pr\u00e9c\u00e8dent la distribution, o\u00f9 la concurrence reste interdite. L&#8217;entreprise postale nationale est ainsi la seule habilit\u00e9e \u00e0 distribuer les lettres pesant jusqu&#8217;\u00e0 350 grammes. Ses concurrents ont le droit de les collecter, de les trier, de les transporter et ils peuvent les introduire en diff\u00e9rents endroits dans le r\u00e9seau de la compagnie postale nationale. Ils b\u00e9n\u00e9ficient d&#8217;un rabais en \u00e9change de ces prestations fournies en amont. De cette fa\u00e7on, le domaine des lettres am\u00e9ricain a pu devenir tr\u00e8s concurrentiel et novateur, sans que le service public en soit menac\u00e9. Son financement est assur\u00e9 par les prix d&#8217;acc\u00e8s et d&#8217;utilisation du r\u00e9seau, qui sont li\u00e9s au monopole de la distribution. On a donc d\u00e9lib\u00e9r\u00e9ment renonc\u00e9 \u00e0 la concurrence dans la distribution. Ce choix est raisonnable d&#8217;un point de vue \u00e9conomique. \u00c9tant donn\u00e9 la faible dynamique d&#8217;innovation que pr\u00e9sente ce domaine, les avantages potentiels d\u00e9coulant de la concurrence y sont plus limit\u00e9s que les inconv\u00e9nients en termes de co\u00fbts engendr\u00e9s par la coexistence de r\u00e9seaux de distribution concurrents. Dans les maillons pr\u00e9c\u00e9dents de la cha\u00eene de valeur, en revanche, c&#8217;est exactement le contraire: les \u00e9conomies d&#8217;\u00e9chelle et de densit\u00e9 sont moins importantes que les avantages produits par la concurrence Voir, par exemple, Dietl et al., 2009.. Dans ces secteurs, l&#8217;ouverture du march\u00e9 am\u00e9liore l&#8217;orientation client et renforce la dynamique d&#8217;innovation, ce qui se traduit par une augmentation du volume de distribution et b\u00e9n\u00e9ficie donc \u00e9galement \u00e0 la compagnie postale nationale. La principale critique adress\u00e9e \u00e0 ce mod\u00e8le porte sur le fait que la distribution est de loin le maillon qui g\u00e9n\u00e8re le plus de co\u00fbts \u00e0 l&#8217;int\u00e9rieur de la cha\u00eene de valeur (voir encadr\u00e9 1 Pour les prestations postales (lettres), la cha\u00eene de valeur est compos\u00e9e pour l&#8217;essentiel des maillons suivants: collecte (environ 12% des co\u00fbts), triage \u00e0 l&#8217;entr\u00e9e et \u00e0 la sortie (15%), transport (7%) et distribution (50%). Les 16% restants sont constitu\u00e9s par les co\u00fbts indirects. Ainsi, la partie de loin la plus importante de la valeur ajout\u00e9e &#8211; et donc aussi le principal potentiel d&#8217;am\u00e9lioration de l&#8217;efficience par la concurrence &#8211; se trouve dans le domaine de la distribution. C&#8217;est justement l\u00e0 que les avantages li\u00e9s \u00e0 la taille (\u00e9conomies d&#8217;\u00e9chelle) jouent le plus grand r\u00f4le. La mise en place d&#8217;un r\u00e9seau de distribution sur l&#8217;ensemble du territoire entra\u00eene des co\u00fbts (fixes) \u00e9lev\u00e9s. Un facteur planifie g\u00e9n\u00e9ralement sa tourn\u00e9e en fonction d&#8217;un certain parcours. S&#8217;il y a une lettre de plus \u00e0 acheminer, cela ne change pratiquement rien aux co\u00fbts de la distribution, puisque le facteur ne va pas modifier son itin\u00e9raire pour d\u00e9livrer la lettre suppl\u00e9mentaire et que son temps de travail reste donc le m\u00eame. Dans ce domaine, les rendements d&#8217;\u00e9chelle d\u00e9pendent du volume du courrier et de la fr\u00e9quence de la distribution. Ils augmentent donc si cette fr\u00e9quence diminue, puisque le nombre de lettres distribu\u00e9es lors de chaque tourn\u00e9e est alors plus \u00e9lev\u00e9 et que les co\u00fbts moyens, eux, s&#8217;inscrivent \u00e0 la baisse.). Si l&#8217;on soustrait ce secteur \u00e0 la loi du march\u00e9, le potentiel d&#8217;am\u00e9lioration de l&#8217;efficience par le biais de la concurrence se limite aux prestations pr\u00e9alables, lesquelles n\u00e9cessitent moins de ressources. Ce ne serait pas sans cons\u00e9quences pr\u00e9cis\u00e9ment sur un march\u00e9 comme celui de la Suisse, o\u00f9 il existe d\u00e9j\u00e0 de nombreux distributeurs priv\u00e9s de journaux ou de courrier non adress\u00e9. En fin de compte, ces acteurs pourraient eux aussi r\u00e9aliser des \u00e9conomies d&#8217;\u00e9chelle avec leurs r\u00e9seaux de distribution.&#13;<\/p>\n<h2>Une taxe d&#8217;incitation en Finlande<\/h2>\n<p>&#13;<br \/>\nL&#8217;UE poursuit, quant \u00e0 elle, une autre strat\u00e9gie de lib\u00e9ralisation. Conform\u00e9ment aux directives communautaires, tous les \u00c9tats membres doivent ouvrir leur march\u00e9 des lettres sur l&#8217;ensemble de la cha\u00eene de valeur, y compris dans la distribution. Toutefois, cela replace le service public au centre du d\u00e9bat sur la lib\u00e9ralisation. \u00c9tant donn\u00e9 qu&#8217;il perd la source de financement que repr\u00e9sentait pour lui le monopole de la distribution, d&#8217;autres solutions doivent \u00eatre trouv\u00e9es. L&#8217;une d&#8217;elles consiste \u00e0 pr\u00e9lever une taxe d&#8217;incitation aupr\u00e8s des prestataires de services postaux. La Finlande, par exemple, fait payer une redevance aux entreprises qui limitent leurs activit\u00e9s \u00e0 des r\u00e9gions dens\u00e9ment peupl\u00e9es et donc \u00e9conomiquement int\u00e9ressantes, laissant \u00e0 la soci\u00e9t\u00e9 charg\u00e9e du service universel le soin de distribuer les lettres dans les zones p\u00e9riph\u00e9riques. En effet, cette entreprise est d\u00e9savantag\u00e9e si son mandat de service universel l&#8217;oblige \u00e0 pratiquer partout le m\u00eame tarif. En Finlande, la taxe peut aller jusqu&#8217;\u00e0 20% du chiffre d&#8217;affaires. Son produit ne sert, toutefois, pas \u00e0 constituer un fonds destin\u00e9 \u00e0 financer le service public. Il s&#8217;agit plut\u00f4t d&#8217;\u00e9liminer l&#8217;avantage relatif dont jouissent les op\u00e9rateurs qui n&#8217;ont pas l&#8217;obligation de l&#8217;assurer. Bien que la Finlande ait compl\u00e8tement lib\u00e9ralis\u00e9 son march\u00e9 de la poste aux lettres d\u00e8s 1993, aucun concurrent ne s&#8217;y est \u00e9tabli \u00e0 ce jour. Le probl\u00e8me de la taxe est \u00e9vident: si elle (et le fonds, le cas \u00e9ch\u00e9ant) est trop \u00e9lev\u00e9e, le prestataire du service universel b\u00e9n\u00e9ficiera d&#8217;un avantage unilat\u00e9ral en mati\u00e8re de concurrence.&#13;<\/p>\n<h2>La nouvelle loi postale en Suisse<\/h2>\n<p>&#13;<br \/>\nDans son message relatif \u00e0 la loi sur la poste, le Conseil f\u00e9d\u00e9ral a \u00e9galement ancr\u00e9 le principe selon lequel une desserte de base doit \u00eatre assur\u00e9e sur l&#8217;ensemble du territoire dans le domaine des services postaux et des prestations en mati\u00e8re de trafic de paiements. C&#8217;est ainsi que la loi pr\u00e9voit l&#8217;attribution d&#8217;un mandat \u00e0 la Poste suisse, puisqu&#8217;\u00e0 l&#8217;issue de la proc\u00e9dure de consultation, le Conseil f\u00e9d\u00e9ral a renonc\u00e9 \u00e0 lancer un appel d&#8217;offres public. Ce mandat contiendra l&#8217;obligation d&#8217;accepter les lettres et les colis, de transporter et de distribuer les envois postaux, ainsi que d&#8217;entretenir un r\u00e9seau d&#8217;offices de poste qui garantisse l&#8217;acc\u00e8s aux prestations du service universel. La distribution sera assur\u00e9e cinq jours ouvrables par semaine et six jours par semaine pour les quotidiens en abonnement. Le projet de loi stipule par ailleurs que les prix des lettres et des colis distribu\u00e9s en Suisse dans le cadre de la desserte de base devront \u00eatre fix\u00e9s ind\u00e9pendamment de la distance. Le Conseil f\u00e9d\u00e9ral doit encore \u00e9tablir des prescriptions relatives \u00e0 la qualit\u00e9 des points d&#8217;acc\u00e8s ainsi qu&#8217;\u00e0 leur accessibilit\u00e9.\u00a0Cependant, l&#8217;\u00e9laboration de ces prescriptions de qualit\u00e9 constitue un \u00e9l\u00e9ment particuli\u00e8rement critique de la lib\u00e9ralisation. Le fait de d\u00e9terminer l&#8217;accessibilit\u00e9 des points d&#8217;acc\u00e8s revient \u00e0 d\u00e9finir la majeure partie du (co\u00fbteux) r\u00e9seau d&#8217;offices de poste. Cela limite consid\u00e9rablement la Poste dans ses efforts visant \u00e0 l&#8217;optimiser, par exemple en cr\u00e9ant des agences dont l&#8217;offre est plus modeste ou en appliquant le concept de \u00abla poste dans l&#8217;\u00e9picerie du village\u00bb. \u00c9tant donn\u00e9 que la Poste remplit \u00e9galement un mandat de service universel en mati\u00e8re de trafic de paiements, son offre de prestations et les normes de s\u00e9curit\u00e9 des points d&#8217;acc\u00e8s doivent r\u00e9pondre \u00e0 des exigences \u00e9lev\u00e9es de mani\u00e8re g\u00e9n\u00e9rale. En d&#8217;autres termes, le mandat de service universel g\u00e9n\u00e8re in\u00e9vitablement des co\u00fbts que la Poste ne conna\u00eetrait gu\u00e8re si elle op\u00e9rait sur le march\u00e9 libre et sans mandat. Afin de compenser ce d\u00e9savantage, il faudrait la d\u00e9dommager pour le service universel qu&#8217;elle assume. L&#8217;indemnisation \u00e9quitable sur le plan \u00e9conomique correspond \u00e0 la diff\u00e9rence entre le r\u00e9sultat d&#8217;exploitation de la Poste dans un r\u00e9gime de concurrence sans obligation de garantir le service universel et le m\u00eame r\u00e9sultat d&#8217;exploitation avec ladite obligation. C&#8217;est d&#8217;ailleurs sur cette id\u00e9e que se fonde l&#8217;indemnisation actuellement accord\u00e9e \u00e0 la Poste pour les frais suppl\u00e9mentaires li\u00e9s au service public. L&#8217;entreprise peut en effet facturer une participation aux co\u00fbts d&#8217;infrastructure pour la mise \u00e0 disposition des offices de poste dont l&#8217;existence n&#8217;est pas n\u00e9cessaire \u00e0 l&#8217;exploitation optimale du r\u00e9seau. Cette participation n&#8217;est pas financ\u00e9e par un subside \u00e9tatique, mais par une majoration de prix dans le segment du monopole (des lettres). Conform\u00e9ment \u00e0 la nouvelle l\u00e9gislation, ce principe sera maintenu tel quel jusqu&#8217;\u00e0 l&#8217;ouverture compl\u00e8te du march\u00e9. Il s&#8217;inspire en r\u00e9alit\u00e9 de l&#8217;approche pratiqu\u00e9e aux \u00c9tats-Unis, o\u00f9 le financement est assur\u00e9 par le monopole de la distribution. Cependant, cette possibilit\u00e9 dispara\u00eetra avec la lib\u00e9ralisation totale. C&#8217;est pourquoi la loi pr\u00e9voit que la Poste puisse exiger un d\u00e9dommagement lorsque le mandat de desserte de base engendre des co\u00fbts nets (voir encadr\u00e9 2 Les co\u00fbts nets de la desserte de base correspondent \u00e0 la diff\u00e9rence entre le r\u00e9sultat d&#8217;exploitation de la Poste avec et sans le mandat de service universel. Pour effectuer ce calcul, il faut proc\u00e9der par \u00e9tapes. Premi\u00e8rement, il s&#8217;agit d&#8217;identifier les aspects du mandat de service universel que la Poste n&#8217;assumerait plus compl\u00e8tement de sa propre initiative &#8211; c&#8217;est-\u00e0-dire sans en avoir l&#8217;obligation l\u00e9gale &#8211; apr\u00e8s l&#8217;ouverture du march\u00e9. On peut par exemple pr\u00e9sumer que la distribution sur l&#8217;ensemble du territoire n&#8217;entrerait pas dans cette cat\u00e9gorie, car la Poste a tout avantage \u00e0 pouvoir offrir \u00e0 ses clients une distribution nationale. En revanche, la densit\u00e9 et la structure du r\u00e9seau d&#8217;offices de poste poseraient \u00e0 cet \u00e9gard des questions d\u00e9licates. Si elle n&#8217;avait pas l&#8217;obligation d&#8217;assurer la desserte de base, la Poste exploiterait vraisemblablement moins d&#8217;offices de poste et davantage d&#8217;agences apr\u00e8s l&#8217;ouverture du march\u00e9. Deuxi\u00e8mement, il convient de calculer les co\u00fbts que la Poste pourrait \u00e9conomiser si elle ne devait plus assumer compl\u00e8tement les volets d\u00e9licats du mandat de service universel. On devrait \u00e9valuer notamment ici les co\u00fbts qu&#8217;elle \u00e9conomiserait en fermant des offices ou en les transformant en agences. Troisi\u00e8mement, il faut calculer les revenus que cette r\u00e9duction de l&#8217;offre ferait perdre \u00e0 la Poste. Par exemple, la fermeture ou la transformation d&#8217;offices de poste entra\u00eenent certes des \u00e9conomies, mais elles ont \u00e9galement pour effet de diminuer les recettes.La quatri\u00e8me \u00e9tape consiste donc \u00e0 faire le solde de cette contraction des recettes et des co\u00fbts \u00e9conomis\u00e9s.Le r\u00e9sultat donne les co\u00fbts nets li\u00e9s \u00e0 la desserte de base (voir Dietl et al., 2007).).&#13;<\/p>\n<h2>Le r\u00e9seau postal, un avantage strat\u00e9gique<\/h2>\n<p>&#13;<br \/>\nLe calcul des \u00e9ventuels co\u00fbts nets s&#8217;av\u00e8re complexe dans la pratique, comme l&#8217;ont d\u00e9j\u00e0 montr\u00e9 les discussions pass\u00e9es sur le niveau de la participation aux frais d&#8217;infrastructure. La red\u00e9finition de cette contribution, que l&#8217;autorit\u00e9 de r\u00e9gulation postale a obtenue pour 2007, l&#8217;a r\u00e9duite de 400 \u00e0 200 millions de francs. La diff\u00e9rence provenait d&#8217;une nouvelle m\u00e9thode de calcul, fond\u00e9e sur la notion de r\u00e9seau postal optimal ainsi que de la non-reconnaissance des co\u00fbts suppl\u00e9mentaires pour la distribution et le transport. Cela illustre bien la difficult\u00e9 de calcul: on ne peut pas simplement extraire les co\u00fbts additionnels de la comptabilit\u00e9. Il faut, au contraire, \u00e9laborer des hypoth\u00e8ses sur la strat\u00e9gie optimale de la Poste avec et sans l&#8217;obligation d&#8217;assurer le service universel. Avec l&#8217;ouverture du march\u00e9, ces r\u00e9flexions sont encore plus complexes que par le pass\u00e9. Par exemple, le r\u00e9seau postal pourrait \u00eatre consid\u00e9r\u00e9 comme un syst\u00e8me de filiales, \u00e0 la mani\u00e8re des banques. En d\u00e9pit des co\u00fbts additionnels qu&#8217;elle engendre, sa densit\u00e9 induit \u00e9galement des avantages commerciaux strat\u00e9giques, car les filiales sont en fin de compte des points de vente de proximit\u00e9 polyvalents qui g\u00e9n\u00e8rent des recettes (voir encadr\u00e9 3 Un r\u00e9seau postal dense n&#8217;implique pas que des co\u00fbts pour la Poste, il lui offre aussi des avantages strat\u00e9giques. Cela devient \u00e9vident si l&#8217;on consid\u00e8re les entreprises postales comme des exploitants de plates-formes qui offrent aux exp\u00e9diteurs d&#8217;un c\u00f4t\u00e9 et aux destinataires de l&#8217;autre la possibilit\u00e9 de communiquer. Dans ce sens, le r\u00e9seau postal avec ses points d&#8217;acc\u00e8s (offices de poste et bo\u00eetes aux lettres) repr\u00e9sente la plateforme id\u00e9ale. Les services postaux sont cr\u00e9ateurs de valeurs aussi bien pour les exp\u00e9diteurs que pour les destinataires. Du c\u00f4t\u00e9 des premiers, l&#8217;importance de la valeur d\u00e9pend en premier lieu du nombre de destinataires potentiels. Si la plate-forme ne permettait d&#8217;atteindre, par exemple, que 20% de la population, la valeur d&#8217;un envoi serait tr\u00e8s limit\u00e9e pour un exp\u00e9diteur actif sur le plan national. Vu sous cet angle, chaque destinataire potentiel suppl\u00e9mentaire augmente la valeur ajout\u00e9e pour les \u00e9metteurs. Dans ces conditions, on comprend aussi pourquoi les entreprises postales ne facturent leurs services qu&#8217;aux exp\u00e9diteurs et pas aux destinataires, bien que ces derniers en profitent \u00e9galement. Contrairement \u00e0 des plates-formes comme les bourses de titres, qui pr\u00e9l\u00e8vent des taxes des deux c\u00f4t\u00e9s du march\u00e9 (aupr\u00e8s des acheteurs et des vendeurs), les entreprises postales subventionnent ceux qui re\u00e7oivent les envois. Il est, en effet, \u00e9conomiquement int\u00e9ressant de raccorder le plus possible de destinataires au r\u00e9seau postal. Le service public ne fait donc pas qu&#8217;engendrer des co\u00fbts: l&#8217;acc\u00e8s \u00e0 chaque m\u00e9nage sur l&#8217;ensemble du territoire repr\u00e9sente \u00e9galement un pr\u00e9cieux avantage par rapport aux concurrents potentiels. S&#8217;ils ne disposent pas encore d&#8217;un r\u00e9seau similaire de points d&#8217;acc\u00e8s, ces derniers souffrent d&#8217;un d\u00e9savantage strat\u00e9gique certain.). Cependant, la Poste est incit\u00e9e \u00e0 sous-estimer vis-\u00e0-vis du r\u00e9gulateur l&#8217;importance du r\u00e9seau optimal n\u00e9cessaire \u00e0 l&#8217;exploitation, afin d&#8217;augmenter le d\u00e9dommagement potentiel qui lui sera accord\u00e9 pour les offices suppos\u00e9s inutiles du point de vue \u00e9conomique. D&#8217;un autre c\u00f4t\u00e9, si le montant de l&#8217;indemnisation \u00e9tait trop faible, en raison d&#8217;une surestimation du r\u00e9seau optimal par le r\u00e9gulateur, la Poste en subirait un d\u00e9savantage concurrentiel. En d&#8217;autres termes, l&#8217;autorit\u00e9 de r\u00e9gulation doit v\u00e9ritablement r\u00e9ussir un \u00abatterrissage de pr\u00e9cision\u00bb lorsqu&#8217;elle d\u00e9finit le r\u00e9seau postal optimal, au risque de fausser le jeu de la concurrence. Elle devrait \u00e9galement \u00eatre en mesure de fixer la structure des offices de poste. En fin de compte, la Poste pourrait \u00e9galement assurer le service public dans le cadre de coop\u00e9rations avec des magasins d&#8217;alimentation ou des stations-service (sur le mod\u00e8le de \u00abla poste dans l&#8217;\u00e9picerie du village\u00bb).&#13;<\/p>\n<h2>Le v\u00e9ritable service universel<\/h2>\n<p>&#13;<br \/>\nPlus la d\u00e9finition du service public est \u00e9tendue et plus les distorsions potentielles du march\u00e9 s&#8217;accroissent. Les incertitudes et les marges de tol\u00e9rance, au niveau de la d\u00e9finition ou du financement, ont deux cons\u00e9quences possibles: elles peuvent cr\u00e9er pour le prestataire du service universel aussi bien un pr\u00e9judice syst\u00e9matique qu&#8217;un avantage strat\u00e9gique. Plus le service public est important, plus \u00abl&#8217;atterrissage de pr\u00e9cision\u00bb mentionn\u00e9 plus haut s&#8217;av\u00e8re difficile. On doit donc en d\u00e9duire que sa limitation tend \u00e0 stimuler la concurrence. Il faudrait, toutefois, \u00e9valuer les \u00abpertes de qualit\u00e9\u00bb qui en r\u00e9sultent effectivement: par exemple en abandonnant les directives concernant le r\u00e9seau postal suisse, dont le maillage est tr\u00e8s serr\u00e9 aujourd&#8217;hui (voir graphique 1), en limitant la distribution \u00e0 domicile dans des zones peu habit\u00e9es ou encore en ne prescrivant pas un tarif standard. Il y a beaucoup d&#8217;aspects du service public que la Poste ne serait de toute fa\u00e7on pas pr\u00eate \u00e0 abandonner, encore moins si cela la privait d&#8217;avantages strat\u00e9giques ou nuirait \u00e0 sa r\u00e9putation de prestataire de haute qualit\u00e9.\u00a0\u00c0 ce jour, on ne dispose pas d&#8217;\u00e9tudes empiriques scientifiquement fond\u00e9es sur les co\u00fbts et l&#8217;utilit\u00e9 des mandats de service universel. Par cons\u00e9quent, la d\u00e9finition des prestations li\u00e9es \u00e0 la desserte de base rel\u00e8ve, dans la pratique, de motifs plut\u00f4t politiques. Souvent, c&#8217;est \u00e9galement un moyen de justifier le maintien de subventions Voir Crew et Kleindorfer, 2008.. \u00c9tant donn\u00e9 les nouvelles technologies de l&#8217;information et de la communication ainsi que le changement de comportement qu&#8217;elles impliquent de la part des consommateurs, il faut de toute fa\u00e7on envisager une red\u00e9finition du service public dans le domaine postal Voir Finger et al. 2005.. Pour transmettre des messages importants et urgents, on utilise aujourd&#8217;hui de plus en plus des canaux de communication tels que le courrier \u00e9lectronique, le fax ou le t\u00e9l\u00e9phone. La Poste, en revanche, achemine toujours plus d&#8217;avis bancaires ou de factures p\u00e9riodiques, envois pour lesquels la ponctualit\u00e9 ne joue pas un r\u00f4le crucial. Pour ce qui est du trafic des paiements, il existe aujourd&#8217;hui un r\u00e9seau dense de filiales de banques (cantonales). En outre, un nombre croissant de paiements s&#8217;effectuent \u00e9lectroniquement, donc par Internet. La Su\u00e8de en a tir\u00e9 les cons\u00e9quences et supprim\u00e9 en 2008 l&#8217;obligation faite \u00e0 son entreprise postale nationale d&#8217;assurer le trafic des paiements. Cette substitution progressive des prestations de la Poste par les services \u00e9lectroniques finit m\u00eame par cr\u00e9er un chevauchement avec le mandat de service universel de Swisscom, qui pr\u00e9voit depuis 2008 un acc\u00e8s Internet \u00e0 large bande offrant un d\u00e9bit de transmission de 600\/100 Kbit\/s.\u00a0La lenteur de l&#8217;ouverture du march\u00e9 en Suisse et les exigences \u00e9lev\u00e9es pos\u00e9es au service public ne font pas qu&#8217;entraver s\u00e9rieusement la concurrence au niveau national. Elles menacent \u00e9galement de marginaliser la Poste suisse sur un march\u00e9 qui s&#8217;internationalise de plus en plus, celui des lettres, des colis et des services logistiques. Tandis que la l\u00e9gislation suisse se concentre sur le service public national, rien n&#8217;est envisag\u00e9 pour faire de la Poste une entreprise adapt\u00e9e au march\u00e9 europ\u00e9en. \u00c0 elle seule, sa transformation en soci\u00e9t\u00e9 anonyme ne suffira pas \u00e0 faire de la Poste un acteur comp\u00e9titif. Sur un march\u00e9 (europ\u00e9en) toujours plus ouvert, o\u00f9 les \u00e9conomies d&#8217;\u00e9chelle rev\u00eatent une importance croissante, des entreprises telles que la soci\u00e9t\u00e9 n\u00e9erlandaise TNT Post ou l&#8217;allemande Post World Net ne cessent d&#8217;accro\u00eetre leur domination.&#13;<br \/>\n&#13;<br \/>\nGraphique 1 \u00abOffices de poste: densit\u00e9 suivant les pays\u00bb&#13;<br \/>\n&#13;<br \/>\nEncadr\u00e9 1: Structure des co\u00fbts dans le secteur postal Pour les prestations postales (lettres), la cha\u00eene de valeur est compos\u00e9e pour l&#8217;essentiel des maillons suivants: collecte (environ 12% des co\u00fbts), triage \u00e0 l&#8217;entr\u00e9e et \u00e0 la sortie (15%), transport (7%) et distribution (50%). Les 16% restants sont constitu\u00e9s par les co\u00fbts indirects. Ainsi, la partie de loin la plus importante de la valeur ajout\u00e9e &#8211; et donc aussi le principal potentiel d&#8217;am\u00e9lioration de l&#8217;efficience par la concurrence &#8211; se trouve dans le domaine de la distribution. C&#8217;est justement l\u00e0 que les avantages li\u00e9s \u00e0 la taille (\u00e9conomies d&#8217;\u00e9chelle) jouent le plus grand r\u00f4le. La mise en place d&#8217;un r\u00e9seau de distribution sur l&#8217;ensemble du territoire entra\u00eene des co\u00fbts (fixes) \u00e9lev\u00e9s. Un facteur planifie g\u00e9n\u00e9ralement sa tourn\u00e9e en fonction d&#8217;un certain parcours. S&#8217;il y a une lettre de plus \u00e0 acheminer, cela ne change pratiquement rien aux co\u00fbts de la distribution, puisque le facteur ne va pas modifier son itin\u00e9raire pour d\u00e9livrer la lettre suppl\u00e9mentaire et que son temps de travail reste donc le m\u00eame. Dans ce domaine, les rendements d&#8217;\u00e9chelle d\u00e9pendent du volume du courrier et de la fr\u00e9quence de la distribution. Ils augmentent donc si cette fr\u00e9quence diminue, puisque le nombre de lettres distribu\u00e9es lors de chaque tourn\u00e9e est alors plus \u00e9lev\u00e9 et que les co\u00fbts moyens, eux, s&#8217;inscrivent \u00e0 la baisse.&#13;<br \/>\n&#13;<br \/>\nEncadr\u00e9 2: Calcul des co\u00fbts nets du service universel Les co\u00fbts nets de la desserte de base correspondent \u00e0 la diff\u00e9rence entre le r\u00e9sultat d&#8217;exploitation de la Poste avec et sans le mandat de service universel. Pour effectuer ce calcul, il faut proc\u00e9der par \u00e9tapes. Premi\u00e8rement, il s&#8217;agit d&#8217;identifier les aspects du mandat de service universel que la Poste n&#8217;assumerait plus compl\u00e8tement de sa propre initiative &#8211; c&#8217;est-\u00e0-dire sans en avoir l&#8217;obligation l\u00e9gale &#8211; apr\u00e8s l&#8217;ouverture du march\u00e9. On peut par exemple pr\u00e9sumer que la distribution sur l&#8217;ensemble du territoire n&#8217;entrerait pas dans cette cat\u00e9gorie, car la Poste a tout avantage \u00e0 pouvoir offrir \u00e0 ses clients une distribution nationale. En revanche, la densit\u00e9 et la structure du r\u00e9seau d&#8217;offices de poste poseraient \u00e0 cet \u00e9gard des questions d\u00e9licates. Si elle n&#8217;avait pas l&#8217;obligation d&#8217;assurer la desserte de base, la Poste exploiterait vraisemblablement moins d&#8217;offices de poste et davantage d&#8217;agences apr\u00e8s l&#8217;ouverture du march\u00e9. Deuxi\u00e8mement, il convient de calculer les co\u00fbts que la Poste pourrait \u00e9conomiser si elle ne devait plus assumer compl\u00e8tement les volets d\u00e9licats du mandat de service universel. On devrait \u00e9valuer notamment ici les co\u00fbts qu&#8217;elle \u00e9conomiserait en fermant des offices ou en les transformant en agences. Troisi\u00e8mement, il faut calculer les revenus que cette r\u00e9duction de l&#8217;offre ferait perdre \u00e0 la Poste. Par exemple, la fermeture ou la transformation d&#8217;offices de poste entra\u00eenent certes des \u00e9conomies, mais elles ont \u00e9galement pour effet de diminuer les recettes.La quatri\u00e8me \u00e9tape consiste donc \u00e0 faire le solde de cette contraction des recettes et des co\u00fbts \u00e9conomis\u00e9s.Le r\u00e9sultat donne les co\u00fbts nets li\u00e9s \u00e0 la desserte de base (voir Dietl et al., 2007).&#13;<br \/>\n&#13;<br \/>\nEncadr\u00e9 3: Les avantages d&#8217;un r\u00e9seau dense du point de vue \u00e9conomique Un r\u00e9seau postal dense n&#8217;implique pas que des co\u00fbts pour la Poste, il lui offre aussi des avantages strat\u00e9giques. Cela devient \u00e9vident si l&#8217;on consid\u00e8re les entreprises postales comme des exploitants de plates-formes qui offrent aux exp\u00e9diteurs d&#8217;un c\u00f4t\u00e9 et aux destinataires de l&#8217;autre la possibilit\u00e9 de communiquer. Dans ce sens, le r\u00e9seau postal avec ses points d&#8217;acc\u00e8s (offices de poste et bo\u00eetes aux lettres) repr\u00e9sente la plateforme id\u00e9ale. Les services postaux sont cr\u00e9ateurs de valeurs aussi bien pour les exp\u00e9diteurs que pour les destinataires. Du c\u00f4t\u00e9 des premiers, l&#8217;importance de la valeur d\u00e9pend en premier lieu du nombre de destinataires potentiels. Si la plate-forme ne permettait d&#8217;atteindre, par exemple, que 20% de la population, la valeur d&#8217;un envoi serait tr\u00e8s limit\u00e9e pour un exp\u00e9diteur actif sur le plan national. Vu sous cet angle, chaque destinataire potentiel suppl\u00e9mentaire augmente la valeur ajout\u00e9e pour les \u00e9metteurs. Dans ces conditions, on comprend aussi pourquoi les entreprises postales ne facturent leurs services qu&#8217;aux exp\u00e9diteurs et pas aux destinataires, bien que ces derniers en profitent \u00e9galement. Contrairement \u00e0 des plates-formes comme les bourses de titres, qui pr\u00e9l\u00e8vent des taxes des deux c\u00f4t\u00e9s du march\u00e9 (aupr\u00e8s des acheteurs et des vendeurs), les entreprises postales subventionnent ceux qui re\u00e7oivent les envois. Il est, en effet, \u00e9conomiquement int\u00e9ressant de raccorder le plus possible de destinataires au r\u00e9seau postal. Le service public ne fait donc pas qu&#8217;engendrer des co\u00fbts: l&#8217;acc\u00e8s \u00e0 chaque m\u00e9nage sur l&#8217;ensemble du territoire repr\u00e9sente \u00e9galement un pr\u00e9cieux avantage par rapport aux concurrents potentiels. S&#8217;ils ne disposent pas encore d&#8217;un r\u00e9seau similaire de points d&#8217;acc\u00e8s, ces derniers souffrent d&#8217;un d\u00e9savantage strat\u00e9gique certain.&#13;<br \/>\n&#13;<br \/>\nEncadr\u00e9 4: Bibliographie &#8211; Crew Michael A. et Kleindorfer Paul R., \u00abMulti-National Policies for the Universal Service Obligation in the Postal Sector under Entry\u00bb, Review of Network Economics, vol. 7, n\u00b0 2, 2008, pp. 188-206. &#8211; Dietl Helmut M., Gr\u00fctter Andreas et Lutzenberger Martin, \u00abComment calculer les co\u00fbts de la desserte de base? Avantages et inconv\u00e9nients des m\u00e9thodes possibles\u00bb, La Vie \u00e9conomique, 5-2007, pp. 17-21.- Dietl Helmut M., Gr\u00fctter Andreas et Lutzenberger Martin, \u00abGesch\u00e4ftsmodelle und Markteintrittsstrategien in ge\u00f6ffneten Brief- und Paketm\u00e4rkten\u00bb, dans: Die Unternehmung. Swiss Journal of Research and Practice, vol. 63, n\u00b0 2, 2009, pp. 193-211.- Finger Mathias, Alyanak Ismail et Rossel Pierre, The Universal Postal Service in the Communications Era: Adapting to Changing Markets and Customer Behaviour, 2005, College of Management of Technology, \u00c9cole polytechnique f\u00e9d\u00e9rale de Lausanne.<\/p>","protected":false},"excerpt":{"rendered":"<p>La lib\u00e9ralisation du march\u00e9 postal suscite fr\u00e9quemment la crainte que les normes minimales du service public ne soient plus garanties. C&#8217;est pourquoi le mandat qui oblige la Poste \u00e0 assurer la desserte de base constitue un \u00e9l\u00e9ment central de la nouvelle l\u00e9gislation postale pr\u00e9sent\u00e9e par le Conseil f\u00e9d\u00e9ral. Cependant, sa mise en oeuvre se heurte [&hellip;]<\/p>","protected":false},"author":2985,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"ep_exclude_from_search":false,"footnotes":""},"post__type":[83],"post_opinion":[],"post_serie":[],"post_content_category":[105],"post_content_subject":[],"acf":{"seco_author":2985,"seco_co_author":[3324,3104,0],"author_override":"","seco_author_post_ocupation_year":"","seco_author_post_occupation_de":"Professor f\u00fcr Services- und Operationsmanagement, Institut f\u00fcr Strategie und Unternehmens\u00f6konomik (ISU), Universit\u00e4t Z\u00fcrich","seco_author_post_occupation_fr":"Professeur en gestion des services et des op\u00e9rations, Institut f\u00fcr Strategie und Unternehmens\u00f6konomik (ISU), universit\u00e9 de Zurich","seco_co_authors_post_ocupation":[{"seco_co_author":3324,"seco_co_author_post_occupation_year":"","seco_co_author_post_occupation_de":"Professor f\u00fcr Unternehmensf\u00fchrung und -politik, Institut f\u00fcr Strategie und Unternehmens\u00f6konomik (ISU), Universit\u00e4t Z\u00fcrich","seco_co_author_post_occupation_fr":"Professeur en politique et direction d'entreprise, Institut f\u00fcr Strategie und Unternehmens\u00f6konomik (ISU), universit\u00e9 de Zurich"},{"seco_co_author":3104,"seco_co_author_post_occupation_year":"","seco_co_author_post_occupation_de":"Wissenschaftlicher Projektleiter, Avenir Suisse, Z\u00fcrich","seco_co_author_post_occupation_fr":"Chef de projet scientifique, Avenir Suisse, Zurich"}],"short_title":"","post_lead":"","post_hero_image_description":"","post_hero_image_description_copyright_de":"","post_hero_image_description_copyright_fr":"","post_references_literature":"","post_kasten":null,"post_notes_for_print":"","first_teaser_header_de":"","first_teaser_header_fr":"","first_teaser_text_de":"","first_teaser_text_fr":"","second_teaser_header_de":"","second_teaser_header_fr":"","second_teaser_text_de":"","second_teaser_text_fr":"","kseason_de":"","kseason_fr":"","post_in_pdf":152527,"main_focus":null,"serie_email":null,"frontpage_slider_bild":"","artikel_bild-slider":null,"legacy_id":"8072","post_abstract":"","magazine_issue":null,"seco_author_reccomended_post":null,"redaktoren":null,"korrektor":null,"planned_publication_date":null,"original_files":null,"external_release_for_author":"19700101","external_release_for_author_time":"00:00:00","link_for_external_authors":"https:\/\/dievolkswirtschaft.ch\/exedit\/55a74f0896671"},"_links":{"self":[{"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/posts\/152524"}],"collection":[{"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/users\/2985"}],"replies":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/comments?post=152524"}],"version-history":[{"count":1,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/posts\/152524\/revisions"}],"predecessor-version":[{"id":189667,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/posts\/152524\/revisions\/189667"}],"acf:user":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/users\/0"},{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/users\/3104"},{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/users\/3324"},{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/users\/2985"}],"wp:attachment":[{"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/media?parent=152524"}],"wp:term":[{"taxonomy":"post__type","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/post__type?post=152524"},{"taxonomy":"post_opinion","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/post_opinion?post=152524"},{"taxonomy":"post_serie","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/post_serie?post=152524"},{"taxonomy":"post_content_category","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/post_content_category?post=152524"},{"taxonomy":"post_content_subject","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/post_content_subject?post=152524"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}