{"id":176341,"date":"2022-11-11T08:30:00","date_gmt":"2022-11-11T07:30:00","guid":{"rendered":"https:\/\/dievolkswirtschaft.ch\/?p=176341"},"modified":"2023-08-24T01:34:09","modified_gmt":"2023-08-23T23:34:09","slug":"les-apprentis-sont-productifs-des-leur-formation","status":"publish","type":"post","link":"https:\/\/dievolkswirtschaft.ch\/fr\/2022\/11\/les-apprentis-sont-productifs-des-leur-formation\/","title":{"rendered":"\u00abLes apprentis sont productifs d\u00e8s leur formation\u00bb"},"content":{"rendered":"<div class=\"content-copy-questions\">Monsieur Marthaler, la formation professionnelle repr\u00e9sente-t-elle un enjeu tel que la direction g\u00e9n\u00e9rale de Swisscom en a fait une affaire personnelle?<\/div>\n<p>Le soutien doit venir d\u2019en haut. Notre directeur Christoph Aeschlimann a pris le temps d\u2019\u00eatre pr\u00e9sent \u00e0 la c\u00e9r\u00e9monie de fin d\u2019apprentissage, alors qu\u2019il venait tout juste d\u2019entrer en fonction. C\u2019est dire l\u2019estime qu\u2019il porte \u00e0 la formation professionnelle. La prochaine g\u00e9n\u00e9ration d\u2019apprentis est tr\u00e8s importante, surtout au vu de la p\u00e9nurie de main-d\u2019\u0153uvre qualifi\u00e9e.<\/p>\n<div class=\"content-copy-questions\">Dans quel domaine votre entreprise en ressent-elle le plus les effets?<\/div>\n<p>Incontestablement dans l\u2019informatique; nous n\u2019\u00e9chappons pas nous non plus \u00e0 la p\u00e9nurie qui frappe ce secteur. L\u2019\u00e9poque du post and pray o\u00f9 l\u2019entreprise n\u2019avait plus qu\u2019\u00e0 attendre les candidatures apr\u00e8s avoir publi\u00e9 une offre d\u2019emploi, est d\u00e9finitivement r\u00e9volue.<\/p>\n<div class=\"content-copy-questions\">Quel r\u00f4le joue la formation professionnelle dans ce contexte?<\/div>\n<p>Selon les pr\u00e9visions de l\u2019organisation nationale du monde du travail ICT-Formation professionnelle pour l\u2019ann\u00e9e 2030, 4500\u00a0sp\u00e9cialistes des technologies de l\u2019information et de la communication (TIC) arriveront sur le march\u00e9 suisse en 2021. Parmi ces sp\u00e9cialistes, 80\u00a0% environ seront issus de la formation professionnelle initiale et nombreux seront ceux qui viendront de la formation professionnelle sup\u00e9rieure ou des hautes \u00e9coles sp\u00e9cialis\u00e9es apr\u00e8s avoir accompli un apprentissage. Cela montre toute l\u2019importance pour une entreprise d\u2019investir dans ce domaine.<\/p>\n<div class=\"content-copy-questions\">Depuis l\u2019\u00e9t\u00e9 dernier, Swisscom exp\u00e9rimente en Suisse al\u00e9manique le recrutement d\u2019apprentis sans que ceux-ci aient \u00e0 fournir de bulletin scolaire ou de dossier. Pour quelles raisons?<\/div>\n<p>Nous voulons \u00eatre encore plus efficaces dans nos recherches afin de trouver les apprentis qui correspondent le mieux \u00e0 Swisscom et \u00e0 notre mod\u00e8le de formation.<\/p>\n<div class=\"content-copy-questions\">Dans votre mod\u00e8le de formation, les apprentis s\u00e9lectionnent eux-m\u00eames leurs projets sur le march\u00e9 num\u00e9rique de Swisscom. Qu\u2019y a-t-il de nouveau dans votre processus de recrutement?<\/div>\n<p>Les candidats commencent par r\u00e9pondre \u00e0 des questions par visioconf\u00e9rence, puis ils sont convi\u00e9s \u00e0 un NEX-Day, c\u2019est-\u00e0-dire \u00e0 une \u00e9valuation d\u2019une demi-journ\u00e9e. Nous apprenons donc d\u2019abord \u00e0 conna\u00eetre nos futurs apprentis en les d\u00e9couvrant dans des situations concr\u00e8tes avant d\u2019analyser leurs dossiers. L\u2019ann\u00e9e derni\u00e8re, nous avons re\u00e7u pr\u00e8s de 8000\u00a0candidatures pour 253 places d\u2019apprentissage, mais beaucoup ne satisfaisaient pas aux profils d\u2019exigences requis. Nous ne voulons pas de dossiers copier-coller envoy\u00e9s en m\u00eame temps \u00e0 un grand nombre d\u2019entreprises.<\/p>\n<div class=\"content-copy-questions\">Votre projet pilote est-il un signe de d\u00e9fiance envers les bulletins scolaires et les dossiers de candidature \u00e9crits?<\/div>\n<p>Non, pas du tout: le syst\u00e8me de formation suisse est bon et reconnu \u00e0 l\u2019\u00e9tranger, \u00e0 juste titre. Mais nous avons d\u00e9cid\u00e9 d\u2019inverser le processus de recrutement compte tenu de notre mod\u00e8le de formation particulier et du nombre \u00e9lev\u00e9 de candidatures non sp\u00e9cifiques. Ce n\u2019est qu\u2019apr\u00e8s avoir re\u00e7u une r\u00e9ponse positive de notre part que les apprentis doivent nous transmettent leur dossier.<\/p>\n<p>&nbsp;<\/p>\n<p><span class=\"content-quotes\">Nous voulons \u00eatre encore plus efficaces dans nos recherches afin de trouver les apprentis qui correspondent le mieux \u00e0 Swisscom et \u00e0 notre mod\u00e8le de formation.<\/span><\/p>\n<p>&nbsp;<\/p>\n<div class=\"content-copy-questions\">Les notes obtenues \u00e0 l\u2019\u00e9cole jouent donc bien un r\u00f4le?<\/div>\n<p>Nous abordons bien \u00e9videmment le th\u00e8me de l\u2019\u00e9cole et des notes obtenues durant les entretiens men\u00e9s pendant les NEX-Days. Nous avons de nombreux m\u00e9tiers pr\u00e9sentant des profils d\u2019exigences \u00e9lev\u00e9es qui n\u00e9cessitent certaines capacit\u00e9s cognitives. Durant la proc\u00e9dure d\u2019inscription, les candidats doivent confirmer qu\u2019ils remplissent les conditions requises pour le poste.<\/p>\n<div class=\"content-copy-questions\">Cette approche permet-elle de r\u00e9duire le temps consacr\u00e9 \u00e0 la recherche des apprentis?<\/div>\n<p>Les trois derniers mois ont montr\u00e9 que l\u2019\u00e9valuation par visioconf\u00e9rence est plus rapide que la proc\u00e9dure sur dossier. Mais si l\u2019on consid\u00e8re l\u2019int\u00e9gralit\u00e9 du processus, y compris les NEX-Days, nous devons encore nous am\u00e9liorer.<\/p>\n<div class=\"content-copy-questions\">Quels seront les crit\u00e8res d\u00e9terminants lors de l\u2019\u00e9valuation du nouveau syst\u00e8me de s\u00e9lection?<\/div>\n<p>L\u2019un des crit\u00e8res principaux sera de savoir si le nouveau syst\u00e8me nous aura permis de trouver les apprentis ad\u00e9quats et d\u2019acc\u00e9l\u00e9rer le recrutement. Les premi\u00e8res \u00e9valuations d\u00e9buteront au cours du premier trimestre de l\u2019ann\u00e9e prochaine et se feront en plusieurs phases.<\/p>\n<div class=\"content-copy-questions\">Le Gentlemen\u2019s Agreement en cours autrefois, qui voulait que l\u2019on ne publie pas les offres de places d\u2019apprentissage avant novembre, appartient depuis longtemps au pass\u00e9. Il y a un an, les organisations d\u2019employeurs et d\u2019employ\u00e9s sont convenues de ne pas publier d\u2019offres avant d\u00e9but ao\u00fbt. Cela a-t-il chang\u00e9 quelque chose pour Swisscom?<\/div>\n<p>Nous nous sommes toujours tenus \u00e0 cette r\u00e8gle, m\u00eame avant cet accord. Nous pensons que les \u00e9l\u00e8ves doivent rester des \u00e9l\u00e8ves. Sans cet accord, les offres seraient publi\u00e9es toujours plus t\u00f4t. Jusqu\u2019o\u00f9 cela irait-il\u00a0? Pour un jeune de 14 ou 15\u00a0ans, le choix de l\u2019apprentissage est d\u00e9j\u00e0 une t\u00e2che difficile. Devoir se d\u00e9cider encore plus t\u00f4t serait une erreur, \u00e0 mon avis.<\/p>\n<figure id=\"attachment_176857\" aria-describedby=\"caption-attachment-176857\" style=\"width: 2560px\" class=\"wp-caption alignnone\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-176857 size-full\" src=\"https:\/\/dievolkswirtschaft.ch\/content\/uploads\/2022\/11\/Marc-Marthaler-Inti-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1703\" srcset=\"https:\/\/dievolkswirtschaft.ch\/content\/uploads\/2022\/11\/Marc-Marthaler-Inti-scaled.jpg 2560w, https:\/\/dievolkswirtschaft.ch\/content\/uploads\/2022\/11\/Marc-Marthaler-Inti-300x200.jpg 300w, https:\/\/dievolkswirtschaft.ch\/content\/uploads\/2022\/11\/Marc-Marthaler-Inti-1024x681.jpg 1024w, https:\/\/dievolkswirtschaft.ch\/content\/uploads\/2022\/11\/Marc-Marthaler-Inti-768x511.jpg 768w, https:\/\/dievolkswirtschaft.ch\/content\/uploads\/2022\/11\/Marc-Marthaler-Inti-1536x1022.jpg 1536w, https:\/\/dievolkswirtschaft.ch\/content\/uploads\/2022\/11\/Marc-Marthaler-Inti-2048x1363.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><figcaption id=\"caption-attachment-176857\" class=\"wp-caption-text\">Image: Keystone \/ Remo N\u00e4geli<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<div class=\"content-copy-questions\">Les m\u00e9tiers \u00e9voluent. La r\u00e9forme des professions du commerce de d\u00e9tail d\u00e9ploie ses effets depuis cet \u00e9t\u00e9. En 2023, ce sera le tour des nouveaux plans de formation d\u2019employ\u00e9 de commerce. Ces r\u00e9formes mettent l\u2019accent sur les comp\u00e9tences commerciales, et non plus sur les mati\u00e8res scolaires et la culture g\u00e9n\u00e9rale. Qu\u2019est-ce que cela signifie pour les jeunes qui souhaitent accomplir une maturit\u00e9 professionnelle?<\/div>\n<p>Il faudra effectivement tenir compte de cette question \u00e0 l\u2019avenir. La maturit\u00e9 professionnelle permet d\u2019acqu\u00e9rir des connaissances g\u00e9n\u00e9rales suppl\u00e9mentaires en vue d\u2019int\u00e9grer une haute \u00e9cole. Lors de projets complexes comme celui de la r\u00e9forme d\u2019une profession, on ne peut pas penser \u00e0 tout. Il appartient aux personnes impliqu\u00e9es d\u2019\u00e9laborer une solution.<\/p>\n<div class=\"content-copy-questions\">Quels nouveaux m\u00e9tiers sont apparus chez Swisscom dans le sillage de la num\u00e9risation?<\/div>\n<p>Il y a 20\u00a0ans environ, ce fut le m\u00e9tier de m\u00e9diamaticien CFC. Le m\u00e9tier qui \u00e9merge en ce moment est celui de d\u00e9veloppeur business num\u00e9rique CFC. La num\u00e9risation ne fait pas seulement appara\u00eetre de nouveaux m\u00e9tiers, elle a aussi pour effet d\u2019en modifier d\u2019autres.<\/p>\n<div class=\"content-copy-questions\">Pourriez-vous nous d\u00e9crire le nouveau m\u00e9tier de d\u00e9veloppeur business num\u00e9rique?<\/div>\n<p>Un d\u00e9veloppeur business num\u00e9rique soutient la transformation num\u00e9rique dans l\u2019entreprise en servant d\u2019interm\u00e9diaire entre l\u2019humain, l\u2019\u00e9conomie et la technique. Dans les petites entreprises, sa t\u00e2che consiste \u00e0 num\u00e9riser les donn\u00e9es et \u00e0 harmoniser les outils, alors que, dans les grandes entreprises, il est charg\u00e9 d\u2019optimiser les processus et de mettre en relation les logiciels et les clients, o\u00f9 il tient lieu l\u00e0 aussi d\u2019interface.<\/p>\n<div class=\"content-copy-questions\">Quels m\u00e9tiers ont disparu?<\/div>\n<p>Nous n\u2019avons plus besoin d\u2019\u00e9lectroniciens car nous ne fabriquons ou ne r\u00e9parons plus d\u2019appareils depuis des ann\u00e9es. Concernant les t\u00e9l\u00e9maticiens, il s\u2019est av\u00e9r\u00e9 qu\u2019ils n\u2019apportent plus aucune valeur ajout\u00e9e \u00e0 l\u2019\u00e9conomie. La formation d\u2019agent relation client va \u00eatre \u00e9galement abandonn\u00e9e car les besoins chez Swisscom sont trop faibles.<\/p>\n<p>&nbsp;<\/p>\n<p><span class=\"content-quotes\">Nous faisons tout pour que les apprentis qui le souhaitent restent chez nous apr\u00e8s leur apprentissage.<\/span><\/p>\n<p>&nbsp;<\/p>\n<div class=\"content-copy-questions\">En quoi la formation professionnelle interne est-elle utile \u00e0 l\u2019entreprise?<\/div>\n<p>Nous pouvons former en interne nos propres sp\u00e9cialistes et contrer ainsi la p\u00e9nurie de main-d\u2019\u0153uvre qualifi\u00e9e. La collaboration entre plusieurs g\u00e9n\u00e9rations est \u00e9galement un avantage: les apprentis d\u00e9chargent leurs coll\u00e8gues, car ils sont productifs d\u00e8s leur formation. Vis-\u00e0-vis de l\u2019ext\u00e9rieur, nous accomplissons quelque chose de positif, car la formation professionnelle interne ne b\u00e9n\u00e9ficie pas seulement \u00e0 notre entreprise, mais \u00e0 toute l\u2019\u00e9conomie, puisque les apprentis ne restent pas tous chez nous.<\/p>\n<div class=\"content-copy-questions\">Selon une \u00e9tude de la Haute \u00e9cole f\u00e9d\u00e9rale pour la formation professionnelle, dans pr\u00e8s de deux tiers des cas, les apprentis apportent une valeur nette \u00e0 l\u2019entreprise d\u00e8s leur p\u00e9riode d\u2019apprentissage. Est-ce vrai aussi pour Swisscom?<\/div>\n<p>Oui, mais cela varie selon les m\u00e9tiers et les projets. Les co\u00fbts de la formation des apprentis du commerce de d\u00e9tail, des employ\u00e9s de commerce, des m\u00e9diamaticiens et des agents relation client sont rapidement amortis, dans bien plus de deux tiers des cas. Pour les informaticiens, en revanche, l\u2019amortissement prend plus de temps \u00e0 cause de la complexit\u00e9 du m\u00e9tier et des tr\u00e8s hautes exigences sp\u00e9cialis\u00e9es. Nous faisons tout pour que les apprentis qui le souhaitent restent chez nous apr\u00e8s leur apprentissage.<\/p>\n<div class=\"content-copy-questions\">En Suisse, le taux d\u2019\u00e9chec aux examens de fin d\u2019apprentissage est relativement \u00e9lev\u00e9 puisqu\u2019il est sup\u00e9rieur \u00e0 8\u00a0% en moyenne. Qu\u2019en est-il chez Swisscom?<\/div>\n<p>Chez nous, le taux d\u2019\u00e9chec est de 2,9\u00a0%. L\u2019ann\u00e9e derni\u00e8re, il a m\u00eame diminu\u00e9 pour atteindre seulement 2,2\u00a0%.<\/p>\n<div class=\"content-copy-questions\">Comment expliquer ces \u00e9checs?<\/div>\n<p>Chaque \u00e9chec aux examens de fin d\u2019apprentissage est un \u00e9chec de trop. Mais dire qu\u2019un apprenti qui \u00e9choue n\u2019a pas assez travaill\u00e9 ou qu\u2019il a jou\u00e9 de malchance serait trop simpliste. Une r\u00e9cente \u00e9tude a montr\u00e9 que la charge psychologique qui p\u00e8se sur les apprentis est de plus en plus grande. L\u2019\u00e9poque que nous vivons n\u2019est pas facile, m\u00eame apr\u00e8s la pand\u00e9mie de Covid-19.<\/p>\n<div class=\"content-copy-questions\">Les apprentis en situation d\u2019\u00e9chec peuvent-ils r\u00e9p\u00e9ter la derni\u00e8re ann\u00e9e?<\/div>\n<p>Ils le peuvent en g\u00e9n\u00e9ral, \u00e0 condition que leur comportement ne soit pas \u00e0 l\u2019origine de leur \u00e9chec. Nous faisons preuve de fermet\u00e9 lorsqu\u2019un apprenti suivi intens\u00e9ment ne prend pas au s\u00e9rieux les examens et qu\u2019il ne s\u2019investit pas. Dans ce cas, il n\u2019est pas autoris\u00e9 \u00e0 r\u00e9p\u00e9ter la derni\u00e8re ann\u00e9e.<\/p>\n<div class=\"content-copy-questions\">Qu\u2019attendez-vous du syst\u00e8me scolaire \u00e0 l\u2019avenir?<\/div>\n<p>Le plan d\u2019\u00e9tudes\u00a021 se focalise sur l\u2019acquisition de comp\u00e9tences, ce dont je me r\u00e9jouis. Il appartient aux \u00e9coles et aux enseignants de revoir leur compr\u00e9hension de l\u2019apprentissage et de l\u2019enseignement, et \u00e9ventuellement de les r\u00e9organiser. Je souhaite que les enseignants prennent ce d\u00e9fi \u00e0 bras-le-corps, qu\u2019ils fassent preuve d\u2019audace et qu\u2019ils d\u00e9veloppent en permanence le syst\u00e8me d\u2019enseignement.<\/p>","protected":false},"excerpt":{"rendered":"<p>Monsieur Marthaler, la formation professionnelle repr\u00e9sente-t-elle un enjeu tel que la direction g\u00e9n\u00e9rale de Swisscom en a fait une affaire personnelle? Le soutien doit venir d\u2019en haut. Notre directeur Christoph Aeschlimann a pris le temps d\u2019\u00eatre pr\u00e9sent \u00e0 la c\u00e9r\u00e9monie de fin d\u2019apprentissage, alors qu\u2019il venait tout juste d\u2019entrer en fonction. C\u2019est dire l\u2019estime qu\u2019il [&hellip;]<\/p>","protected":false},"author":4162,"featured_media":177492,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"ep_exclude_from_search":false,"footnotes":""},"post__type":[81,80],"post_opinion":[85],"post_serie":[],"post_content_category":[90],"post_content_subject":[123,217],"acf":{"seco_author":4162,"seco_co_author":[9862],"author_override":"","seco_author_post_ocupation_year":"","seco_author_post_occupation_de":"Chefredaktorin, Die Volkswirtschaft","seco_author_post_occupation_fr":"R\u00e9dactrice en chef de \u00ab La Vie \u00e9conomique \u00bb","seco_co_authors_post_ocupation":[{"seco_co_author":9862,"seco_co_author_post_occupation_year":"","seco_co_author_post_occupation_de":"Redaktorin, Die Volkswirtschaft","seco_co_author_post_occupation_fr":"R\u00e9dactrice \u00abLa Vie \u00e9conomique\u00bb"}],"short_title":"","post_lead":"La formation professionnelle interne est importante chez Swisscom, car elle contribue \u00e0 pallier la p\u00e9nurie de main-d\u2019\u0153uvre qualifi\u00e9e, comme l\u2019indique Marc Marthaler, responsable de la formation professionnelle chez Swisscom. Il explique en outre que les co\u00fbts de formation des gestionnaires du commerce de d\u00e9tail, des m\u00e9diamaticiens et des employ\u00e9s de commerce sont rapidement amortis.","post_hero_image_description":"Marc Marthaler dans le b\u00e2timent Swisscom situ\u00e9 \u00e0 la Genfergasse \u00e0 Berne. \u00abLa prochaine g\u00e9n\u00e9ration d\u2019apprentis est tr\u00e8s importante, surtout au vu de la p\u00e9nurie de main-d\u2019\u0153uvre qualifi\u00e9e.\u00bb","post_hero_image_description_copyright_de":"","post_hero_image_description_copyright_fr":"Keystone \/ Remo N\u00e4geli","post_references_literature":"","post_kasten":[{"kasten_title":"Marc Marthaler","kasten_box":"Marc Marthaler est responsable de la formation professionnelle chez Swisscom depuis plus de six ans. Auparavant, apr\u00e8s avoir obtenu un MAS en supervision et conseil en organisation, il a travaill\u00e9 pendant quatre ans comme enseignant, conseiller et chef de projets \u00e0 la Haute \u00e9cole p\u00e9dagogique de la FHNW. De 2003 \u00e0 2009, il a occup\u00e9 un poste de coach d\u2019apprentissage chez Swisscom, o\u00f9 il a particip\u00e9 d\u00e8s les premi\u00e8res heures \u00e0 la mise en place du concept de formation professionnelle. Initialement, il a obtenu un brevet d\u2019enseignement puis effectu\u00e9 des \u00e9tudes de sport et de gymnastique \u00e0 l\u2019Universit\u00e9 de Berne. Depuis cet \u00e9t\u00e9, il est titulaire d\u2019un MAS en gestion du capital humain. \u00c2g\u00e9 de 46 ans, Marc Marthaler vit \u00e0 Thoune."}],"post_notes_for_print":"","first_teaser_header_de":"","first_teaser_header_fr":"","first_teaser_text_de":"","first_teaser_text_fr":"","second_teaser_header_de":"","second_teaser_header_fr":"","second_teaser_text_de":"","second_teaser_text_fr":"","kseason_de":"","kseason_fr":"","post_in_pdf":"","main_focus":[177460,177462],"serie_email":null,"frontpage_slider_bild":"","artikel_bild-slider":null,"legacy_id":"","post_abstract":"","magazine_issue":null,"seco_author_reccomended_post":"","redaktoren":"","korrektor":"","planned_publication_date":"20221111","original_files":null,"external_release_for_author":null,"external_release_for_author_time":"","link_for_external_authors":"https:\/\/dievolkswirtschaft.ch\/fr\/exedit\/634ec1c936eed"},"_links":{"self":[{"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/posts\/176341"}],"collection":[{"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/users\/4162"}],"replies":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/comments?post=176341"}],"version-history":[{"count":45,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/posts\/176341\/revisions"}],"predecessor-version":[{"id":182655,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/posts\/176341\/revisions\/182655"}],"acf:post":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/main_focus_post\/177462"},{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/main_focus_post\/177460"}],"acf:user":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/users\/9862"},{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/users\/4162"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/media\/177492"}],"wp:attachment":[{"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/media?parent=176341"}],"wp:term":[{"taxonomy":"post__type","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/post__type?post=176341"},{"taxonomy":"post_opinion","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/post_opinion?post=176341"},{"taxonomy":"post_serie","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/post_serie?post=176341"},{"taxonomy":"post_content_category","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/post_content_category?post=176341"},{"taxonomy":"post_content_subject","embeddable":true,"href":"https:\/\/dievolkswirtschaft.ch\/fr\/wp-json\/wp\/v2\/post_content_subject?post=176341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}